{"id":114936,"date":"2025-04-05T20:28:00","date_gmt":"2025-04-06T00:28:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=114936"},"modified":"2025-04-07T20:58:06","modified_gmt":"2025-04-08T00:58:06","slug":"resultats-et-video-pour-le-aew-collision-du-5-avril-2025","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/04\/05\/resultats-et-video-pour-le-aew-collision-du-5-avril-2025\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AEW Collision du 5 Avril 2025 !"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/05\/reprise-video-pour-le-aew-collision-du-5-avril-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour voir Collision, cliquez ici.<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>AEW Collision Peoria, Illinois, 5 avril 2025<\/strong><br>Les commentateurs sont Tony Schiavone et Don Callis.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Kyle Fletcher et Konosuke Takeshita\u00a0<em>acc de Don Callis<\/em>\u00a0vs Powerhouse Hobbs et Tomohiro Ishii\u00a0acc de Rocky Romero<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Takeshita repousse Hobbs du ring avec un Blue Thunder Bomb. Fletcher fait une Clothesline \u00e0 Ishii, mais il se rel\u00e8ve directement. Fletcher lui fait un Superkick et enchaine avec un Tombstone. Fletcher le rel\u00e8ve et lui fait un Brain Buster pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Kyle Fletcher et Konosuke Takeshita<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur All In.<\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve Lio Rush et Action Andretti. Andretti dit qu&rsquo;ils font tous pour les \u00e9viter depuis des mois et maintenant ils veulent vraiment les affronter ce soir. Rush dit que ce soir ne sera pas diff\u00e9rent apr\u00e8s les avoir \u00e9cras\u00e9s semaine apr\u00e8s semaine. Rush et Andretti vont voit Nick Wayne plus loin. Rush demande si Wayne a r\u00e9fl\u00e9chi \u00e0 leur offre comme AR Fox est toujours l\u00e0 avec Top Flight. Wayne dit qu&rsquo;il a r\u00e9fl\u00e9chi et il croit avoir trop de valeur pour les aider, alors la r\u00e9ponse est non. Andretti rigole en disant qu&rsquo;il a besoin de la permission de son p\u00e8re. Rush dit que Cage l&rsquo;a enferm\u00e9 dans une cage. Wayne dit qu&rsquo;il fait tout quand il veut. Wayne dit que s&rsquo;il vient attaquer AR Fox, c&rsquo;est pour lui et non eux.<\/p>\n\n\n\n<p>&#8211; Max Caster est sur le ring pour un nouvel Open Challenge. Caster dit qu&rsquo;il est heureux d&rsquo;\u00eatre en vie ce soir car il a travers\u00e9 une tornade pour venir catcher ici ce soir. Au contraire de son ancien partenaire qui ne dira pas son nom. Caster invite les fans \u00e0 chanter son chant \u00a0\u00bbLet&rsquo;s Go Max, tu es le meilleur catcheur\u00a0\u00bb. Caster dit qu&rsquo;il \u00e9tait clair que les gens d&rsquo;ici ne sont pas capable de se souvenir de huit mots. Caster dit que dimanche \u00e0 AEW Dynasty il va lancer un autre Open Challenge. Alors qui peut survivre contre lui ? Mark Briscoe arrive.<\/p>\n\n\n\n<p><strong>Max Caster vs Mark Briscoe<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Briscoe fait son Jay Driller pour l&#8217;emporter en moins de cinq minutes sur Caster.<\/p>\n\n\n\n<p><em>Gagnant : Mark Briscoe<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Kevin Knight.<\/p>\n\n\n\n<p>&#8211; En coulisses,<strong>\u00a0Lexie <\/strong>demande \u00e0 <strong>Jay White<\/strong> ses commentaires sur sa blessure \u00e0 la main. White r\u00e9pond qu&rsquo;il a parl\u00e9 trop t\u00f4t en disant que cette ann\u00e9e n&rsquo;\u00e9tait pas pour Kevin Knight pour le tournoi Owen Hart. Mais gr\u00e2ce \u00e0 sa blessure Knight peut avoir cette place dans le tournoi. Will Ospreay et les autres auront la chance de continuer de pr\u00e9tendre qu&rsquo;ils sont les rois du ring. En raison des Death Riders il perd sa place dans le tournoi. Les Death Riders veulent rendre cette histoire personnelle. Il aura le temps de bien r\u00e9fl\u00e9chir \u00e0 son sc\u00e9nario de vengeance lors de son retour.<\/p>\n\n\n\n<p><strong>Lio Rush et Action Andretti vs Top Flight<em>&nbsp;(Dante et Darius Martin)<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Andretti fait un Falcon Arrow \u00e0 Darius, mais Dante le surprend avec un compte rapide pour le compte de trois !<\/p>\n\n\n\n<p><em>Gagnants : Top Flight<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Rush et Andretti commencent \u00e0 rouer de coups Top Flight comme ils sont s\u00e9rieux. AR Fox arrive pour repousser Rush et Andretti, mais Nick Wayne arrive et fait son Cutter \u00e0 Fox.<\/p>\n\n\n\n<p>&#8211; Les commentateurs annoncent que pour pour Pre-Show de Dynasty, Top Flight et AR Fox vont affronter Rush, Andretti et Wayne.<\/p>\n\n\n\n<p>&#8211; En coulisses, Jamie Hayter est avec Billie Starkz pour parler du tournoi Owen Hart. Hayter dit qu&rsquo;elle a \u00e9t\u00e9 impressionn\u00e9e par Starkz lors de leur premier match. Mais elle a un conseil d&rsquo;amie, Starkz doit faire attention \u00e0 Athena qui veut lui voler son moment. Starkz dit qu&rsquo;elle va montrer dans le tournoi pourquoi elle n&rsquo;est pas un \u00e9chec.<\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve Renee Paquette avec\u00a0<strong>Undisputed Kingdom <\/strong>face \u00e0 <strong>Daniel Garcia<\/strong>\u00a0et <strong>Matt Menard<\/strong>. Paquette demande \u00e0 Daniel Garcia ses commentaires sur sa premi\u00e8re d\u00e9fense de titre \u00e0 Dynasty, mais Adam Cole veut parler en premier.<\/p>\n\n\n\n<p> Cole dit que leur premier match \u00e9tait il y a deux ans. Il revenait d&rsquo;une importante blessure et Garcia \u00e9tait coinc\u00e9 avec Chris Jericho et confus. Mais deux ans apr\u00e8s Garcia est champion, mais il est toujours confus comme Garcia croit \u00eatre capable de le battre. S&rsquo;il avait eu 5 secondes de plus, il serait champion.<\/p>\n\n\n\n<p>Cole ajoute que dimanche il va c\u00e9l\u00e9brer ses 17 ans dans le catch, en plus dans la ville de Philadelphie o\u00f9 il a eu son premier match. Il a entendu longtemps pour \u00eatre champion \u00e0 la AEW, c&rsquo;est le moment dimanche.<\/p>\n\n\n\n<p> Garcia rajoute que Menard avait raison, il n&rsquo;\u00e9tait pas oblig\u00e9 de donner un rematch. Mais il l&rsquo;a fait en respect pour tout ce que Cole a fait pendant 17 ans. C&rsquo;est la derni\u00e8re chance que Cole pourra avoir apr\u00e8s Dynasty. Cole a eu 17 ann\u00e9es d&rsquo;opportunit\u00e9s et les 17 prochaines ann\u00e9es lui reviennent. Cole demande \u00e0 tout le monde de partir pour parler en priv\u00e9 avec Garcia. Cole dit qu&rsquo;il a du respect pour Garcia, mais parfois il doit dire la v\u00e9rit\u00e9. La v\u00e9rit\u00e9 est que Garcia n&rsquo;est pas pr\u00eat pour \u00eatre le leader d&rsquo;une compagnie et \u00eatre un vrai champion. Il a men\u00e9 toutes les compagnies o\u00f9 il a \u00e9t\u00e9. Il est LE gars depuis bien avant que Garcia n&rsquo;ait commenc\u00e9 sa carri\u00e8re. Si Garcia ne comprend pas, il devrait lui botter le cul dimanche.<\/p>\n\n\n\n<p><strong>Cash Wheeler vs Pac<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Pac \u00e9vite un Head Butt de Wheeler du coin. Pac monte sur le coin pour son Black Arrow, mais Wheeler se rel\u00e8ve et lui fait une Superplex ! Wheeler le couvre, mais il r\u00e9siste. Pac bloque la seconde prise et lui fait une German Suplex. Pac lui porte ensuite un coup de pied et se lance en Black Arrow, mais Wheeler l&rsquo;\u00e9vite et lui fait un Pile Driver ! Wheeler le couvre, mais Pac r\u00e9siste \u00e0 deux. Claudio Castagnoli arrive en ringside, mais Cope arrive pour le chasser. Wheeler Yuta arrive sur le ring de l&rsquo;autre c\u00f4t\u00e9, mais Wheeler le repousse. Pac en profite pour faire un compte rapide \u00e0 Wheeler pour la victoire.<\/p>\n\n\n\n<p><em>Gagnant : Pac<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat,\u00a0Rated FTR font la paix et se font une belle accolade de groupe ce qui nous fais douter de leur orientation comme Mattias et Antoine quand ils se taponne le petit paquet durant leur live. <\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur le match de Kenny Omega \u00e0 AEW Dynasty.<\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve Shane Taylor avec Carlie Bravo et Shawn Dean qui mentionnent vouloir s&rsquo;imposer.<\/p>\n\n\n\n<p>&#8211; Ricochet prend place avec les commentateurs pour le prochain match, et il n&rsquo;est pas meilleure que les pirouettes qu&rsquo;il fait dans le ring. <\/p>\n\n\n\n<p><strong>Speedball Mike Bailey vs Dralistico\u00a0<em>acc de Beast Mortos<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Bailey r\u00e9siste \u00e0 un compte rapide. Bailey porte un coup de pied et enchaine avec un Round Kick \u00e0 Dralistico pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Mike Bailey<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Bailey c\u00e9l\u00e8bre sa victoire, mais Ricochet lui porte un coup de pied sous la ceinture ! Ricochet le frappe avec son coup d&rsquo;avant-bras et quitte le ring.<\/p>\n\n\n\n<p>&#8211; En coulisses, Lexie demande \u00e0 Thunder Rosa et Kris Statlander leur commentaire sur le tournoi Owen Hart. Rosa dit qu&rsquo;elles auront leur premier match de l&rsquo;histoire. Elles ont h\u00e2te. <\/p>\n\n\n\n<p>Rosa dit que le futur de sa famille repose sur cette victoire. Il n&rsquo;y a rien de personnel, mais elle doit gagner. Statlander dit d&rsquo;aviser sa famille qu&rsquo;elle va perdre. Les deux commencent \u00e0 se bousculer.<\/p>\n\n\n\n<p>&#8211; Les commentateurs pr\u00e9sentent\u00a0la carte de AEW Dynasty qui aura lieu ce dimanche 6 avril.<\/p>\n\n\n\n<p>&#8211; En coulisses, Mercedes Mon\u00e9 et Cameron se pr\u00e9parent pour leur match. Mon\u00e9 est \u00e9nerv\u00e9e par le comportement de Cameron et lui explique comment se comporter.<\/p>\n\n\n\n<p><strong>Mercedes Mon\u00e9 et Harley Cameron vs Julia Hart et Athena<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Athena fait une Powerbomb \u00e0 Cameron. Hart prend la tag et se lance en Moonsault, mais Cameron l&rsquo;\u00e9vite ! Mon\u00e9 fait un Back Stabber \u00e0 Hart. Athena fait une Slam \u00e0 Mon\u00e9 pour la chasser. Cameron fait un Neck Breaker \u00e0 Athena. Hart et Cameron \u00e9changent les coups. Cameron enchaine avec une Slam et la prend pour son finisher, mais Hart bloque la prise et lui applique un Octopus. Mon\u00e9 d\u00e9cide de ne pas venir aider Cameron lorsque Athena lui bloque le chemin, Cameron abandonne.<\/p>\n\n\n\n<p><em>Gagnants : Julia Hart et Athena\u00a0<\/em><\/p>\n\n\n\n<p>Le show se termine avec une c\u00e9l\u00e9bration des gagnantes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/05\/reprise-video-pour-le-aew-collision-du-5-avril-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour voir Collision, cliquez ici.<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"s7LJQ8YTWG\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/05\/reprise-video-pour-le-aew-collision-du-5-avril-2025\/\">Reprise Vid\u00e9o pour le AEW Collision du 5 Avril 2025 !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le AEW Collision du 5 Avril 2025 !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/05\/reprise-video-pour-le-aew-collision-du-5-avril-2025\/embed\/#?secret=igLYrzudjS#?secret=s7LJQ8YTWG\" data-secret=\"s7LJQ8YTWG\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>AEW Collision Peoria, Illinois, 5 avril 2025Les commentateurs sont Tony Schiavone et Don Callis. Kyle Fletcher et Konosuke Takeshita\u00a0acc de Don Callis\u00a0vs Powerhouse Hobbs et Tomohiro Ishii\u00a0acc de Rocky Romero \u00c0 la fin du combat, Takeshita repousse Hobbs du ring avec un Blue Thunder Bomb. Fletcher fait une Clothesline \u00e0 Ishii, mais il se rel\u00e8ve&#8230;<\/p>\n","protected":false},"author":55,"featured_media":114937,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,89,102,21],"tags":[],"ppma_author":[288],"class_list":["post-114936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-collision","category-dynasty","category-resultats"],"authors":[{"term_id":288,"user_id":55,"is_guest":0,"slug":"mark-green","display_name":"Watch Wrestling","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48aa7229968e08b18e4ac74ae48666f742d5f4460d3a972818733f8de3e505c2?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/114936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=114936"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/114936\/revisions"}],"predecessor-version":[{"id":114938,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/114936\/revisions\/114938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/114937"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=114936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=114936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=114936"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=114936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}