{"id":114600,"date":"2025-04-01T01:11:00","date_gmt":"2025-04-01T05:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=114600"},"modified":"2025-04-01T15:24:44","modified_gmt":"2025-04-01T19:24:44","slug":"wade-barrett-na-pas-aime-la-replique-de-john-cena-lors-du-dernier-raw-et-lui-replique","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/04\/01\/wade-barrett-na-pas-aime-la-replique-de-john-cena-lors-du-dernier-raw-et-lui-replique\/","title":{"rendered":"Wade Barrett n\u2019a pas aim\u00e9 la r\u00e9plique de John Cena lors du dernier RAW, et lui r\u00e9plique !"},"content":{"rendered":"\n<p>Wade Barrett n\u2019a pas sembl\u00e9 se soucier de la r\u00e9plique de John Cena \u00ab&nbsp;Je n\u2019enterre pas le talent, j\u2019enterre la m\u00e9diocrit\u00e9&nbsp;\u00bb de l\u2019\u00e9pisode de WWE Raw de cette semaine.<\/p>\n\n\n\n<p>Barrett, qui a comment\u00e9 l\u2019\u00e9pisode de Raw du 31 mars aux c\u00f4t\u00e9s de Michael Cole et Pat McAfee en direct du O2 Arena de Londres, en Angleterre, a refait surface sur les r\u00e9seaux sociaux peu de temps apr\u00e8s la fin de l\u2019\u00e9mission pour partager une r\u00e9action \u00e0 la r\u00e9plique susmentionn\u00e9e utilis\u00e9e par Cena lorsque \u00ab\u00a0The Greatest of All-Time\u00a0\u00bb a r\u00e9agi au fait que Cody Rhodes a \u00e9voqu\u00e9 sa r\u00e9putation dans le pass\u00e9 d\u2019\u00eatre quelqu\u2019un qui enterrait et gardait le talent \u00e0 terre.<\/p>\n\n\n\n<p>Le post, que Barrett a partag\u00e9 via X, montrait une image de quelqu\u2019un de si en col\u00e8re que des veines sortaient de son front, indiquant qu\u2019il n\u2019\u00e9tait pas satisfait de la remarque de la future l\u00e9gende du WWE Hall of Fame.<\/p>\n\n\n\n<p>Comme indiqu\u00e9 dans une r\u00e9cente interview d\u2019Inside the Ropes publi\u00e9e cette semaine avec Heath Slater, un ancien membre de la faction Nexus qui comprenait Wade Barrett, a affirm\u00e9 que la finition avait \u00e9t\u00e9 modifi\u00e9e juste avant le tristement c\u00e9l\u00e8bre match Team Nexus vs Team WWE lors de WWE SummerSlam 2010, avec Team WWE gagnant \u00e0 la place du r\u00e9sultat initialement pr\u00e9vu. qui aurait vu la Team Nexus gagner, et plus pr\u00e9cis\u00e9ment gr\u00e2ce \u00e0 Barrett.<\/p>\n\n\n\n<p>\u00c0 la fin de l\u2019ann\u00e9e 2010, Cena avait litt\u00e9ralement enterr\u00e9 Barrett sous une \u00e9norme pile de chaises en acier.<\/p>\n\n\n\n<p>D\u00e9couvrez le post de Wade Barrett en r\u00e9ponse \u00e0 la phrase de John Cena \u00ab\u00a0Je n\u2019enterre pas le talent, j\u2019enterre la m\u00e9diocrit\u00e9\u00a0\u00bb ci-dessous:<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"zxx\" dir=\"ltr\"><a href=\"https:\/\/t.co\/WQ8m0MooiL\">https:\/\/t.co\/WQ8m0MooiL<\/a> <a href=\"https:\/\/t.co\/8tF4PrzDY0\">pic.twitter.com\/8tF4PrzDY0<\/a><\/p>&mdash; Stu Bennett (@StuBennett) <a href=\"https:\/\/twitter.com\/StuBennett\/status\/1906849685547135342?ref_src=twsrc%5Etfw\">March 31, 2025<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"y12AIylOnK\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/03\/31\/resultats-et-video-pour-le-wwe-monday-night-raw-du-31-mars-2025\/\">R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 31 Mars 2025 !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 31 Mars 2025 !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/03\/31\/resultats-et-video-pour-le-wwe-monday-night-raw-du-31-mars-2025\/embed\/#?secret=sMQt8jEyGG#?secret=y12AIylOnK\" data-secret=\"y12AIylOnK\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Wade Barrett n\u2019a pas sembl\u00e9 se soucier de la r\u00e9plique de John Cena \u00ab&nbsp;Je n\u2019enterre pas le talent, j\u2019enterre la m\u00e9diocrit\u00e9&nbsp;\u00bb de l\u2019\u00e9pisode de WWE Raw de cette semaine. Barrett, qui a comment\u00e9 l\u2019\u00e9pisode de Raw du 31 mars aux c\u00f4t\u00e9s de Michael Cole et Pat McAfee en direct du O2 Arena de Londres, en&#8230;<\/p>\n","protected":false},"author":665,"featured_media":114622,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,87,23],"tags":[],"ppma_author":[289],"class_list":["post-114600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-road-to-wrestlemania","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/114600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=114600"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/114600\/revisions"}],"predecessor-version":[{"id":114623,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/114600\/revisions\/114623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/114622"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=114600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=114600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=114600"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=114600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}