{"id":114148,"date":"2025-03-23T23:11:00","date_gmt":"2025-03-24T03:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=114148"},"modified":"2025-03-25T16:49:58","modified_gmt":"2025-03-25T20:49:58","slug":"le-lutteur-independant-artist-artest-seffondre-lors-dun-evenement-hier-soir-et-decede","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/03\/23\/le-lutteur-independant-artist-artest-seffondre-lors-dun-evenement-hier-soir-et-decede\/","title":{"rendered":"Le lutteur ind\u00e9pendant Artist Artest s\u2019effondre lors d\u2019un \u00e9v\u00e9nement hier soir et d\u00e9c\u00e8de !"},"content":{"rendered":"\n<p>Le lutteur ind\u00e9pendant Artist Artest s\u2019est effondr\u00e9 lors d\u2019un \u00e9v\u00e9nement XVW samedi soir, ce qui a entra\u00een\u00e9 l\u2019arr\u00eat du spectacle.<\/p>\n\n\n\n<p>La promotion s\u2019est ensuite rendue sur Facebook pour annoncer qu\u2019Artest \u00e9tait malheureusement d\u00e9c\u00e9d\u00e9.<\/p>\n\n\n\n<p>Artest, de son vrai nom Graham Michael, a \u00e9t\u00e9 transport\u00e9 d\u2019urgence \u00e0 l\u2019h\u00f4pital mais n\u2019a pas surv\u00e9cu.<\/p>\n\n\n\n<p>Vous pouvez consulter la d\u00e9claration officielle de XVW ci-dessous :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab\u00a0C\u2019est avec une grande tristesse que j\u2019ai le devoir d\u2019informer les fans de XVW qu\u2019apr\u00e8s s\u2019\u00eatre effondr\u00e9 ce soir \u00e0 XVW, et avoir \u00e9t\u00e9 transport\u00e9 d\u2019urgence \u00e0 l\u2019h\u00f4pital&#8230; L\u2019artiste Artest est d\u00e9c\u00e9d\u00e9. Nous souhaitons adresser nos condol\u00e9ances \u00e0 sa famille, ses amis et ses fans. Notre personnel a travaill\u00e9 sans rel\u00e2che pour le maintenir en vie jusqu\u2019\u00e0 l\u2019arriv\u00e9e des m\u00e9decins. Nous interromprons les activit\u00e9s en souvenir de la vie d\u2019Artest. Repose en paix champion.\u00a0\u00bb<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Nous adressons nos sinc\u00e8res condol\u00e9ances aux amis et \u00e0 la famille de l\u2019Artiste Artest.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le lutteur ind\u00e9pendant Artist Artest s\u2019est effondr\u00e9 lors d\u2019un \u00e9v\u00e9nement XVW samedi soir, ce qui a entra\u00een\u00e9 l\u2019arr\u00eat du spectacle. La promotion s\u2019est ensuite rendue sur Facebook pour annoncer qu\u2019Artest \u00e9tait malheureusement d\u00e9c\u00e9d\u00e9. Artest, de son vrai nom Graham Michael, a \u00e9t\u00e9 transport\u00e9 d\u2019urgence \u00e0 l\u2019h\u00f4pital mais n\u2019a pas surv\u00e9cu. Vous pouvez consulter la d\u00e9claration&#8230;<\/p>\n","protected":false},"author":665,"featured_media":114311,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,22,4],"tags":[],"ppma_author":[289],"class_list":["post-114148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-indy","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/114148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=114148"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/114148\/revisions"}],"predecessor-version":[{"id":114312,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/114148\/revisions\/114312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/114311"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=114148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=114148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=114148"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=114148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}