{"id":113673,"date":"2025-03-12T20:02:00","date_gmt":"2025-03-13T00:02:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=113673"},"modified":"2025-03-16T15:48:29","modified_gmt":"2025-03-16T19:48:29","slug":"resultats-et-video-pour-le-aew-dynamite-du-12-mars-2025","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/03\/12\/resultats-et-video-pour-le-aew-dynamite-du-12-mars-2025\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AEW Dynamite du 12 Mars 2025!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/03\/12\/reprise-video-pour-le-aew-dynamite-du-12-mars-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Dynamite, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>AEW Dynamite Fresno, Californie, 12 mars 2025<\/strong><br>Les commentateurs sont Tony Schiavone, Taz et Excalibur.<\/p>\n\n\n\n<p>&#8211; Le AEW Dynamite d\u00e9bute avec les commentateurs qui souhaitent la bienvenue <\/p>\n\n\n\n<p>&#8211; Le nouveau champion International\u00a0<strong>Kenny Omega<\/strong>\u00a0arrive sur le ring, et dit que c&rsquo;est toujours fou pour lui. Avant 2025 il \u00e9tait content d&rsquo;\u00eatre sur le ring et dire qu&rsquo;il a le feu vert et qu&rsquo;il peut encore catcher. Maintenant c&rsquo;est la nouvelle ann\u00e9e et il est de retour \u00e0 la AEW et en plus gr\u00e2ce au soutien des fans, des m\u00e9decins et de Will Ospreay il est de retour avec un titre solo. Il y a une liste de gens qui pourrait remercier, mais il y a une personne en particulier et c&rsquo;est Konosuke Takeshita. <\/p>\n\n\n\n<p>Il ajoute qu&rsquo;il doit remercier Takeshita pour l&rsquo;avoir pouss\u00e9 \u00e0 des limites qu&rsquo;il pensait impossible. Si ce n&rsquo;\u00e9tait pas de Takeshita, il n&rsquo;aurait pas \u00e9t\u00e9 en mesure d&rsquo;avoir ce titre et avoir ce micro ce soir. Il doit aussi remercier Takeshita pour avoir r\u00e9ellement rendu ce titre International. Alors son patron a eu l&rsquo;id\u00e9e de lancer un tournoi Eliminator pour d\u00e9terminer son prochain aspirant. C&rsquo;est une bonne id\u00e9e car il veut que personne ayant ce titre soit vraiment la meilleure au monde. Ce n&rsquo;est pas important d&rsquo;o\u00f9 on vient, il veut affronter le meilleur. Il va surveiller ce tournoi de pr\u00e8s.<\/p>\n\n\n\n<p><strong>The Opps&nbsp;<em>(Samoa Joe, Katsuyori Shibata et HOOK)<\/em>&nbsp;vs Trois catcheurs locaux<em>&nbsp;(Vinny Pacifico, Eli Theseus et Gabriel Aeros)<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Shibata applique un Sleeper et enchaine avec un Running Kick sur un catcheur pour le compte de trois en moins de deux minutes.<\/p>\n\n\n\n<p><em>Gagnants : The Opps<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve Ricochet. Ricochet dit que sa qu\u00eate vers le titre mondial AEW n&rsquo;est pas termin\u00e9 malgr\u00e9 qu&rsquo;il a \u00e9t\u00e9 arnaqu\u00e9 \u00e0 Revolution. Il a vu Kenny Omega avec le titre International, c&rsquo;est jolie, mais ce serait encore plus jolie sur lui. C&rsquo;est pour cette raison qu&rsquo;il entre dans le tournoi. Avant son match contre Shibata, il donne l&rsquo;option \u00e0 Shibata d&rsquo;abandonner et ne pas venir \u00e0 AEW Collision samedi pour s&rsquo;\u00e9viter une d\u00e9faite.<\/p>\n\n\n\n<p>&#8211; <a href=\"https:\/\/www.jdx.info\/lutte\/2025\/03\/09\/resultats-et-video-pour-le-aew-revolution-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">On pr\u00e9sente une vid\u00e9o des \u00e9v\u00e9nements \u00e0\u00a0AEW Revolution dimanche dernier<\/a>.<\/p>\n\n\n\n<p>&#8211; Les commentateurs annoncent que\u00a0Jon Moxley et Cope vont s&rsquo;affronter dans un rematch pour le titre mondial \u00e0 AEW Dynamite la semaine prochaine dans un Street Fight Match. Le gagnant ira affronter Swerve Strickland \u00e0 AEW Dynasty.<\/p>\n\n\n\n<p>&#8211; En vid\u00e9o de dimanche dernier, Swerve Strickland dit qu&rsquo;il y a un an il a marqu\u00e9 l&rsquo;histoire en devenant le premier champion noir. Strickland dit qu&rsquo;il le fera une seconde fois \u00e0 Dynasty. Cope arrive et dit qu&rsquo;il n&rsquo;a pas perdu ce soir. Alors il y a une chance que le match \u00e0 Dynasty soit contre lui et non Moxley.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, en coulisses,&nbsp;<strong>Jon Moxley<\/strong>&nbsp;dit que c&rsquo;\u00e9tait opportuniste \u00e0 Revolution, il avait sa chance d&rsquo;envoyer Adam Copeland sur la touche \u00e0 Revolution. Il sait qu&rsquo;il a fait mal \u00e0 Cope, mais Cope revenait encore et encore. Il peut admirer la d\u00e9termination de Cope. Mais on veut enlever les r\u00e8gles et le nommer en Street Fight. Sans les r\u00e8gles, il va enlever les excuses \u00e0 Cope. Il y a une raison de pourquoi il est le World Champion. Il ne r\u00e9p\u00e8te jamais la m\u00eame erreur deux fois et on le verra.<\/p>\n\n\n\n<p><strong>Hologram et Powerhouse Hobbs\u00a0<em>acc d&rsquo;HarleyGram<\/em>\u00a0vs Dralistico et Brian Cage\u00a0<em>acc de Beast Mortos<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Dralistico donne des Chops \u00e0 Hobbs. Dralistico se lance en Springboard, mais Hobbs le bloque en Spinebuster pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Hologram et Powerhouse Hobbs<\/em><\/p>\n\n\n\n<p>&#8211; En vid\u00e9o dimanche dernier, on retrouve l&rsquo;Hurt Syndicate. Shelton Benjamin dit qu&rsquo;il a h\u00e2te de savoir qui seront les prochains \u00e0 se faire battre. MVP dit que l&rsquo;Hurt Syndicate ne prend jamais de cong\u00e9 et ils vont regarder qui seront les prochains adversaires. MVP invite Benjamin et Lashley de passer un peu de temps \u00e0 la plage pour cette semaine et revenir en force pour le prochain match.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur toute l&rsquo;histoire entre Toni Storm et Mariah May.<\/p>\n\n\n\n<p>&#8211; La championne AEW\u00a0<strong>Toni Storm<\/strong>\u00a0arrive sur la sc\u00e8ne. Storm dit qu&rsquo;avec des agrafes sur sa t\u00eate, du verre dans son cul, elle se tient devant nous pour dire qu&rsquo;elle est toujours la championne. C&rsquo;\u00e9tait sa fin Hollywoodienne \u00e0 Revolution, une partie de son coeur est rest\u00e9e l\u00e0. C&rsquo;est le moment d&rsquo;un nouveau d\u00e9part. C&rsquo;est son honneur d&rsquo;\u00eatre notre championne AEW, car c&rsquo;est le vestiaire le plus talentueux de tout l&rsquo;univers du catch. Il y a beaucoup de titres, avec le titre mondial dans une mallettes ou bien des collectionneurs de titres, mais en l&rsquo;affrontant c&rsquo;est comme visiter le zoo. Car elle saigne comme un cochon, l\u00e8che comme une girafe et nous mangera comme un lion. Personne ne frappe comme Toni Storm, ce sera d\u00e9sordonn\u00e9 et en sueur, mais ce sera toujours \u00c9ternel ! Toni Storm pose sur la sc\u00e8ne, mais\u00a0Megan Bayne arrive pour la frapper dans le dos\u00a0!<\/p>\n\n\n\n<p>&#8211; De retour, les catcheurs arrivent, le Qu\u00e9b\u00e9cois Speedball Mike Bailey d\u00e9barque \u00e0 la AEW.<\/p>\n\n\n\n<p><strong>Tournoi Aspirant Titre International<\/strong><br><strong>Beast Mortos vs Speedball Mike Bailey<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Bailey monte sur le coin et se lance en Shooting Star Press, mais Mortos l&rsquo;\u00e9vite. Mortos attrape Bailey et lui fait un Samoan Drop pour le couvrir, mais il r\u00e9siste \u00e0 deux. Mortos monte sur le coin, mais Bailey se rel\u00e8ve et le frappe. Les deux s&rsquo;affrontent sur le coin, Mortos arrive \u00e0 faire une Press Slam de la troisi\u00e8me corde pour le couvrir, mais Bailey r\u00e9siste \u00e0 deux. Mortos se lance pour sa Clothesline, mais Bailey le bloque et lui fait une s\u00e9rie de Chops. Mortos le repousse et lui fait un Back Breaker. Mortos enchaine avec une Clothesline et le prend en Powerbomb, mais Bailey le renverse en compte rapide et il r\u00e9siste. Bailey lui porte un coup de pied et enchaine avec un Knee Drop. Bailey lui fait un Round Kick pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Mike Bailey<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, Renee Paquette est avec le clan de&nbsp;<strong>Christian Cage<\/strong>&nbsp;pour avoir leur r\u00e9action sur la d\u00e9faite \u00e0 Revolution. Cage dit que Paquette est reli\u00e9 \u00e0 Jon Moxley et il refuse de parler \u00e0 tout le monde qui est reli\u00e9 \u00e0 Jon Moxley. Cage demande \u00e0 Paquette de partir et elle quitte. Christian Cage dit qu&rsquo;il est toujours le prochain champion mondial AEW. Il demande que son contrat lui revient en raison de l&rsquo;incomp\u00e9tence de l&rsquo;arbitre. Il a remis son contrat en demandant un match simple, mais c&rsquo;\u00e9tait un Triple Threat. Il ne s&rsquo;attendait pas \u00e0 \u00e7a et il n&rsquo;a pas tap\u00e9 et encore moins abandonn\u00e9. Nick Wayne arr\u00eate Cage et dit que Cage ment \u00e0 tout le monde avec ses excuses. Si Cage avait suivi le plan original, il serait peut-\u00eatre le champion aujourd&rsquo;hui. Cage leur doit des explications et des excuses. Cage dit qu&rsquo;il est d\u00e9sol\u00e9 d&rsquo;en arriver l\u00e0. Cage pousse Nick Wayne ! La m\u00e8re s&rsquo;interpose. Cage dit que si elle veut dire quelque chose, elle va retourner bosser pour les quarts de nuit comme serveuse. La m\u00e8re recule. Cage demande combien de matchs de titre mondial Nick Wayne ou son p\u00e8re biologique ont gagn\u00e9 ? Il n&rsquo;est pas un l\u00e2che comme lui qui est mort devant sa m\u00e8re. Il sera le champion mondial AEW car c&rsquo;est ce qu&rsquo;il veut. Nick Wayne ferait mieux de garder le silence car la prochaine fois ce sera leur derni\u00e8re discussion.<\/p>\n\n\n\n<p>&#8211; En vid\u00e9o de dimanche dernier, Lexie veut interviewer MJF, mais MJF est furieux et casse un miroir.<\/p>\n\n\n\n<p>&#8211; La musique de&nbsp;<strong>MJF<\/strong>&nbsp;se lance et il arrive sur le ring. MJF dit qu&rsquo;il a un mal de t\u00eate, sa main lui fait mal, son corps lui fait mal. Mais ce qui lui fait encore plus mal est qu&rsquo;il le sait, tous les fans ignorants le savent aussi, il avait ce match de gagn\u00e9 dimanche dernier. Mais notre cowboy l\u00e2che a d\u00e9cid\u00e9 de prendre une victoire en coup de chance comme en 2019. Les fans peuvent chanter le nom de Page comme ils veulent, \u00e7a ne le d\u00e9range plus. MJF dit que le fait est qu&rsquo;il est 10 fois plus intelligent que Page et ses fans ignorants. MJF dit qu&rsquo;il aura sa revanche, cette histoire est loin d&rsquo;\u00eatre termin\u00e9e. La musique du Hurt Syndicate se lance et MVP arrive sur le ring.<\/p>\n\n\n\n<p>MVP et MJF font un face \u00e0 face, puis ils commencent \u00e0 se faire un c\u00e2lin en rigolant. MJF lui demande comment il va. MVP dit que tout va bien et il voulait lui parler. MVP dit qu&rsquo;il est fier de MJF, ce n&rsquo;est plus le m\u00eame petit gars de 18 ans qu&rsquo;il a rencontr\u00e9. Le jeune MJF de 18 ans a voulu \u00eatre son conducteur gratuitement en \u00e9change de pouvoir lui poser des questions sur le catch professionnel. Les questions de MJF l&rsquo;ont impressionn\u00e9, \u00e7a montrait l&rsquo;intelligence et que ce serait un gars qu&rsquo;il reverrait. Il \u00e9tait heureux de partager ses connaissances \u00e0 MJF. MJF lui a dit qu&rsquo;un jour il serait un champion mondial et MJF a tout fait ce qu&rsquo;il a fait. Et c&rsquo;est pour cela qu&rsquo;il est fier de MJF. Mais il n&rsquo;est pas fier de quelque chose, ce qui est arriv\u00e9 dimanche.<\/p>\n\n\n\n<p>MVP demande \u00e0 MJF ce qu&rsquo;il a fait \u00e0 Revolution. Pourquoi MJF commence \u00e0 se plaindre de son match dimanche ? Pourquoi MJF n&rsquo;est pas en col\u00e8re \u00e0 frapper des gens et blessant des gens ? Il connait la r\u00e9ponse. MJF a perdu son aura. Les gens n&rsquo;ont plus de respect pour MJF, les gens n&rsquo;ont plus peur de MJF. Les gens ont peur du Hurt Syndicate maintenant. Il a \u00e9t\u00e9 en mesure d&rsquo;aider MJF par le pass\u00e9 et il pourrait l&rsquo;aider encore une fois. Sa carte d&rsquo;affaire \u00e9tait pour se pr\u00e9senter aux gens, mais maintenant tout le monde sait qu&rsquo;il peut amener l&rsquo;or. Sa carte d&rsquo;affaire est un billet en or pour changer une carri\u00e8re. Alors c&rsquo;est peut-\u00eatre le temps de parler business.<\/p>\n\n\n\n<p>MJF refuse la carte d&rsquo;affaire de MVP. MJF dit qu&rsquo;il a du respect pour MVP, mais il n&rsquo;est plus le m\u00eame gar\u00e7on de l&rsquo;\u00e9poque. Avec respect, il n&rsquo;a pas besoin de l&rsquo;aide et des conseils de MVP. Il est MJF et il \u00e9tait le champion mondial pendant 406 jours. MVP dit qu&rsquo;il doit se concentrer sur le mot \u00e9tait. MVP lui donne sa carte et quitte le ring.<\/p>\n\n\n\n<p>&#8211; De retour, Max Caster est sur le ring pour un nouveau Open Challenge. Max Caster dit qu&rsquo;on regarde au meilleur catcheur en vit. Il a le tee-shirt le plus populaire de l&rsquo;AEW, ce qui prouve qu&rsquo;il \u00e9tait le plus populaire du Acclaimed. Il a aussi le meilleur chant avec \u00a0\u00bbLet&rsquo;s Go Max tu es le meilleur catcheur\u00a0\u00bb. La foule ne participe pas. Caster dit que les gens de Fresno sont visiblement stupides. Et la personne qui va accepter l&rsquo;Open Challenge sera aussi stupide.<\/p>\n\n\n\n<p> Konosuke Takeshita arrive sur le ring ! Caster reprend son micro et dit que c&rsquo;est impossible que Takeshita soit ici pour l&rsquo;affrontement. Il est meilleur catcheur en vit, il pourrait le tuer. Takeshita est surement l\u00e0 pour l&rsquo;inviter dans la Famille Don Callis. Qu&rsquo;est-ce que la Famille pourrait faire pour lui ? Il pourrait faire le main event au Tokyo Dome. Ou faire ce que Takeshita n&rsquo;est pas capable comme battre Omega&#8230; Takeshita le cogne !<\/p>\n\n\n\n<p><strong>Max Caster vs Konosuke Takeshita<\/strong><\/p>\n\n\n\n<p>Takeshita couvre Caster apr\u00e8s son coup de poing, mais il arr\u00eate le compte. Takeshita enchaine avec son Raging Fire pour le compte de trois sur Caster.<\/p>\n\n\n\n<p><em>Gagnant : Konosuke Takeshita<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, Chris Jericho a le masque de Gravity entre ses mains. Jericho dit que la situation entre lui et Bandido fait face \u00e0 la gravit\u00e9. Il a humili\u00e9 Bandido devant sa famille en volant le masque de son fr\u00e8re. Il a fait pleurer sa m\u00e8re devant lui. Comment en revenir ? Comment Bandido pourra regarder sa m\u00e8re apr\u00e8s l&rsquo;avoir d\u00e9\u00e7u ? Jericho dit que la vie de Bandido a chang\u00e9.<\/p>\n\n\n\n<p><strong>Willow Nightingale vs Penelope Ford<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Nightingale bloque une attaque avec son Pounce pour le compte de trois sur Ford.<\/p>\n\n\n\n<p><em>Gagnante : Willow Nightingale<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Nightingale c\u00e9l\u00e8bre sa victoire, mais Ford revient sur le ring pour l&rsquo;attaquer avec une chaise ! Kris Statlander arrive pour venir en aider et chasser Ford du ring. Megan Bayne d\u00e9barque sur le ring et fait une Double Clothesline \u00e0 Statlander et Nightingale. Bayne prend Statlander sur ses \u00e9paules pour lui faire un F5.<\/p>\n\n\n\n<p>&#8211; En coulisses, Renee Paquette est avec Mercedes Mon\u00e9. Mon\u00e9 n&rsquo;arrive pas \u00e0 parler car elle a trop mal \u00e0 la gorge. Paquette lui fait sa pr\u00e9sentation de CEO. Paquette dit que Mon\u00e9 est 15-0 pour ses matchs et Billie Starkz voulait lui parler. Paquette demande \u00e0 Billie Starkz ce qu&rsquo;elle a appris \u00e0 Revolution. Billie Starkz dit que c&rsquo;est de ne pas recevoir des coups \u00e0 la gorge. Oui Mon\u00e9 est couverte de titres. Mais de son c\u00f4t\u00e9 elle a \u00e9t\u00e9 la premi\u00e8re championne ROH TV \u00e0 19 ans. Le catch c&rsquo;est leur vie pour les deux. Mon\u00e9 disait toujours que l&rsquo;argent change tout et la semaine prochaine elle va changer en championne.\u00a0Mon\u00e9 dit que Starkz vise hors de son niveau. La semaine prochaine elle va montrer qu&rsquo;il y a un prix \u00e0 payer pour jouer avec elle.<\/p>\n\n\n\n<p>&#8211; Tony Schiavone est sur le ring et pr\u00e9sente<strong>\u00a0Will Ospreay<\/strong>. Ospreay dit qu&rsquo;il a eu 4 agrafes sur la t\u00eate. Il n&rsquo;a aucune id\u00e9e d&rsquo;o\u00f9 viennent les autres douleurs, mais il est heureux d&rsquo;\u00eatre en vie. Schiavone dit que c&rsquo;est impressionnant de le voir encore debout. Ospreay dit qu&rsquo;il a eu de la difficult\u00e9 \u00e0 rivaliser avec Kyle Fletcher, mais l&rsquo;\u00e9nergie des fans l&rsquo;a permis \u00e0 tenir. Un jour Kyle Fletcher sera un champion mondial. Mais sans mentir, il a quelques ennuis avec sa femme. Il a menti \u00e0 sa femme, samedi avant le match elle l&rsquo;a appel\u00e9 en disant qu&rsquo;elle avait peur et de rien faire de stupide du haut de la cage. Ospreay lui a promis qu&rsquo;il ne ferait rien de stupide comme il a 30 ans et des probl\u00e8mes de dos. Il a ensuite r\u00e9alis\u00e9 qu&rsquo;ils sont sur Prime Video. Apr\u00e8s le match il avait 15 appels rat\u00e9s de sa femme. Alors il l&rsquo;a rappel\u00e9 et elle l&rsquo;a insult\u00e9 pour le saut en haut de la cage. Il a \u00e9t\u00e9 en mesure de la charmer disant qu&rsquo;il sera de retour \u00e0 la maison vendredi pour lui cuisiner un bon repas. Schiavone lui demande c&rsquo;est quoi la suite pour Ospreay. Ospreay dit qu&rsquo;apr\u00e8s ce match en cage il veut \u00eatre LE gars. \u00c7a prend un titre pour \u00eatre le gars. Swerve Strickland a son match de titre \u00e0 Dynasty, alors quand lui il pourra r\u00e9clamer sa place ? Ospreay regarde le logo de All In Texas.\u00a0Ospreay dit que sa mission est d&rsquo;\u00eatre dans le main event de All In. Il a pour intention d&rsquo;avoir cette place en entrant dans le tournoi Owen Hart et le remporter. Un assassin arrive pour le tr\u00f4ne.\u00a0Il veut \u00eatre le champion mondial car les fans lui font confiance et car il est d&rsquo;un autre niveau.<\/p>\n\n\n\n<p>&#8211; En coulisses, Renee Paquette est avec\u00a0<strong>Jay White<\/strong>. White dit qu&rsquo;Ospreay est vraiment d&rsquo;un autre niveau, c&rsquo;est bien de l&rsquo;entendre. Peut-\u00eatre qu&rsquo;un jour ils vont se recroiser sur le ring, mais d&rsquo;ici l\u00e0 il veut le f\u00e9liciter pour Revolution et de le voir en demander plus. Jay White dit que si Ospreay veut aller \u00e0 All In, Ospreay devra rester loin de lui. Paquette demande \u00e0 White ce qui est arriv\u00e9 avec la mallette de Jon Moxley. White dit que tout le monde veut savoir s&rsquo;il a frapp\u00e9 Cope volontairement \u00e0 Revolution. Est-ce que Fresno le pense ? La foule r\u00e9pond non.\u00a0White dit que la r\u00e9ponse est non, il voulait aider Cope \u00e0 devenir champion et il a \u00e9chou\u00e9. Heureusement que Cope a une seconde chance la semaine prochaine.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisses, Renee Paquette demande \u00e0\u00a0<strong>Adam Page<\/strong>\u00a0ce qui lui r\u00e9serve la suite, mais MJF arrive et le bouscule. MJF demande s&rsquo;il veut se battre. Page demande s&rsquo;il veut se faire casser le cou. Page dit que MJF doit le penser vraiment lorsqu&rsquo;il menace. Dimanche il a vu que MJF se pr\u00e9occupe de ce que les gens pensent. <\/p>\n\n\n\n<p>MJF dit que c&rsquo;est bien de voir Page qui doute du fait de l&rsquo;incendier. MJF dit qu&rsquo;il ne pense pas que Page r\u00e9alise ce qui l&rsquo;attend. Page est dans sa bulle apr\u00e8s avoir battu MJF, un coup de chance. Mais pour la suite il est en route pour devenir un multiple champion mondial et devenir Hall of Famer. Pendant que Page va essayer de monter au sommet et au sommet il va chuter en bas. Il a r\u00e9alis\u00e9 que la plus grande ins\u00e9curit\u00e9 de Page est de m\u00e9riter l&rsquo;amour des fans. Un jour les fans ne pourront plus attendre de le voir gagner le grand match. Pendant ce temps il va gagner le titre mondial encore et encore et se moquer de Page.<\/p>\n\n\n\n<p><strong>Tournoi Aspirant Titre International <\/strong><br><strong>Hechicero vs Orange Cassidy<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Hechicero bloque le Stunner de Cassidy. Cassidy \u00e9vite un coup, Hechicero \u00e9vite l&rsquo;Orange Punch. Cassidy \u00e9vite un compte rapide. Cassidy revient \u00e0 la charge avec son compte rapide finisher pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Orange Cassidy<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, Cassidy c\u00e9l\u00e8bre sa victoire.<\/p>\n\n\n\n<p> Mike Bailey arrive sur la sc\u00e8ne pour faire un face \u00e0 face, le show se termine ainsi.<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/03\/12\/reprise-video-pour-le-aew-dynamite-du-12-mars-2025\/\">Pour voir Dynamite, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"RF9cVwKYDz\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/03\/12\/reprise-video-pour-le-aew-dynamite-du-12-mars-2025\/\">Reprise Vid\u00e9o pour le AEW Dynamite du 12 Mars 2025!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le AEW Dynamite du 12 Mars 2025!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/03\/12\/reprise-video-pour-le-aew-dynamite-du-12-mars-2025\/embed\/#?secret=RfftdNJErk#?secret=RF9cVwKYDz\" data-secret=\"RF9cVwKYDz\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>AEW Dynamite Fresno, Californie, 12 mars 2025Les commentateurs sont Tony Schiavone, Taz et Excalibur. &#8211; Le AEW Dynamite d\u00e9bute avec les commentateurs qui souhaitent la bienvenue &#8211; Le nouveau champion International\u00a0Kenny Omega\u00a0arrive sur le ring, et dit que c&rsquo;est toujours fou pour lui. Avant 2025 il \u00e9tait content d&rsquo;\u00eatre sur le ring et dire qu&rsquo;il&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":113680,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,50,30,21],"tags":[],"ppma_author":[297],"class_list":["post-113673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-dynamite","category-ex-wwe","category-resultats"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/113673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=113673"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/113673\/revisions"}],"predecessor-version":[{"id":113683,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/113673\/revisions\/113683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/113680"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=113673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=113673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=113673"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=113673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}