{"id":113651,"date":"2025-03-12T14:22:00","date_gmt":"2025-03-12T18:22:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=113651"},"modified":"2025-03-14T15:16:09","modified_gmt":"2025-03-14T19:16:09","slug":"une-legende-de-la-lutte-spoile-son-intronisation-et-de-son-partenaire-au-wwe-hall-of-fame","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/03\/12\/une-legende-de-la-lutte-spoile-son-intronisation-et-de-son-partenaire-au-wwe-hall-of-fame\/","title":{"rendered":"Une l\u00e9gende de la lutte spoile son intronisation, et de son partenaire, au WWE Hall Of Fame !"},"content":{"rendered":"\n<p>Jusqu\u2019\u00e0 pr\u00e9sent, la WWE n\u2019a officiellement annonc\u00e9 que Paul \u00ab&nbsp;Triple H&nbsp;\u00bb Levesque, Lex Luger et Michelle McCool comme intronis\u00e9s dans la classe 2025 du WWE Hall of Fame.<\/p>\n\n\n\n<p>Mercredi, une autre l\u00e9gende de la lutte a confirm\u00e9 qu\u2019il serait \u00e9galement de la partie.<\/p>\n\n\n\n<p>Typhoon, \u00e9galement connu sous le nom de Tugboat et tristement connu sous le nom de The Shockmaster, a confirm\u00e9 qu\u2019il entrerait au WWE Hall of Fame pendant le week-end de WrestleMania 41 dans le cadre d\u2019une intronisation par \u00e9quipe aux c\u00f4t\u00e9s de Earthquake.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab C\u2019est un honneur. C\u2019\u00e9tait fou quand j\u2019ai re\u00e7u cet appel t\u00e9l\u00e9phonique que M. Prichard [Bruce Prichard] m\u2019a appel\u00e9\u00a0\u00bb, a d\u00e9clar\u00e9 Fred Ottman, alias Typhoon, \u00e0 propos de sa prochaine intronisation au WWE Hall of Fame dans le cadre de The Natural Disasters avec Earthquake. \u00ab <em>C\u2019est un gars g\u00e9nial. Je n\u2019arrivais pas \u00e0 y croire.<\/em> >><\/p>\n\n\n\n<p> \u00ab Il y a tellement de gars qui sont si dignes d\u2019\u00eatre l\u00e0-dedans, qui ne le sont pas encore. C\u2019est incroyable que cela se produise.<\/p>\n<\/blockquote>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/8XhqIXCMDFM?si=MSqDmyUs3ulxlhWt\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Jusqu\u2019\u00e0 pr\u00e9sent, la WWE n\u2019a officiellement annonc\u00e9 que Paul \u00ab&nbsp;Triple H&nbsp;\u00bb Levesque, Lex Luger et Michelle McCool comme intronis\u00e9s dans la classe 2025 du WWE Hall of Fame. Mercredi, une autre l\u00e9gende de la lutte a confirm\u00e9 qu\u2019il serait \u00e9galement de la partie. Typhoon, \u00e9galement connu sous le nom de Tugboat et tristement connu sous&#8230;<\/p>\n","protected":false},"author":665,"featured_media":113728,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77,4,87,23],"tags":[],"ppma_author":[289],"class_list":["post-113651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hall-of-fame","category-news","category-road-to-wrestlemania","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/113651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=113651"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/113651\/revisions"}],"predecessor-version":[{"id":113729,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/113651\/revisions\/113729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/113728"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=113651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=113651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=113651"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=113651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}