{"id":112071,"date":"2025-02-13T00:33:00","date_gmt":"2025-02-13T05:33:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=112071"},"modified":"2025-02-13T22:20:16","modified_gmt":"2025-02-14T03:20:16","slug":"elias-alias-elijah-na-pas-signe-avec-la-aew-dustin-rhodes-a-un-match-de-retraite-en-tete","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/02\/13\/elias-alias-elijah-na-pas-signe-avec-la-aew-dustin-rhodes-a-un-match-de-retraite-en-tete\/","title":{"rendered":"Elias alias Elijah n&rsquo;a pas sign\u00e9 avec la AEW ! Dustin Rhodes a un match de retraite en t\u00eate !"},"content":{"rendered":"\n<p>&#8211; R\u00e9cemment, des rumeurs ont circul\u00e9 selon lesquelles Elias\/Elijah avait \u00e9t\u00e9 sign\u00e9 par AEW\/ROH. Ces rumeurs ont pris de l\u2019ampleur apr\u00e8s qu\u2019il soit apparu dans une vid\u00e9o avec The Righteous de la ROH. Cependant, des sources ont pr\u00e9cis\u00e9 qu\u2019Elijah n\u2019est pas sous contrat avec la AEW ou la ROH, du moins pour le moment car on ne sait jamais ce que le futur peut r\u00e9server.<\/p>\n\n\n\n<p>Bien qu\u2019il ait r\u00e9cemment affront\u00e9 Tommy Billington de la AEW lors de la croisi\u00e8re Jericho, nos sources rapportent qu\u2019Elijah est toujours un agent libre. Au cours des deux derni\u00e8res ann\u00e9es, depuis son d\u00e9part de la WWE, il a fait sa marque dans diverses promotions de lutte en Australie, au Royaume-Uni et sur le circuit ind\u00e9pendant.<\/p>\n\n\n\n<p>Il a \u00e9galement \u00e9t\u00e9 rapport\u00e9 que la TNA (Impact Wrestling) a montr\u00e9 de l\u2019int\u00e9r\u00eat pour le signer.<\/p>\n\n\n\n<p>&#8211; Dustin Rhodes a l\u2019intention de continuer \u00e0 lutter pendant encore environ trois ans.<\/p>\n\n\n\n<p>Alors qu\u2019il s\u2019adressait \u00e0 Tim &amp; Eli sur le podcast \u00ab&nbsp;Battleground&nbsp;\u00bb, on a demand\u00e9 \u00e0 Dustin Rhodes s\u2019il avait des plans pour un \u00e9ventuel match de retraite. Dire<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab Oui. Je le garde pr\u00e8s de la veste de mon adversaire. J\u2019ai planifi\u00e9 cela au cours des deux derni\u00e8res ann\u00e9es avec qui je veux finir. Cela va avoir lieu dans trois ans. Ce sera difficile de s\u2019\u00e9loigner. Je ne suis en aucun cas au niveau de Sting, mais je veux ce m\u00eame genre de sortie. Je pense que je l\u2019ai m\u00e9rit\u00e9. Finir sur un pay-per-view et faire une promo \u00e9motionnelle d\u00e9chirante apr\u00e8s, c\u2019est ce que les gens aiment. Ce n\u2019est pas comme au bon vieux temps. Je veux gagner. Je veux gagner ce dernier match. Je ne veux pas perdre. Cela signifie beaucoup pour moi, et j\u2019y ai beaucoup r\u00e9fl\u00e9chi. Je dirais probablement environ trois ans. Les choses changent. Nous verrons o\u00f9 ils nous m\u00e8neront. C\u2019est d\u00e9j\u00e0 assez difficile de dire : <\/em><\/p>\n\n\n\n<p><em>\u00ab&nbsp;<strong>Il est presque temps, Dustin<\/strong>&nbsp;\u00bb. <\/em><\/p>\n\n\n\n<p><em>C\u2019est difficile. Cela fait partie de ma vie depuis si longtemps. \u00c7a va \u00eatre tr\u00e8s \u00e9mouvant. Sortir de l\u2019entreprise est un grand pas parce que vous changez quelque chose que vous avez fait depuis longtemps. Que fais-tu? Vous devez trouver des choses \u00e0 faire dans l\u2019intervalle pour garder l\u2019esprit droit. Je serai entra\u00eeneur et je continuerai \u00e0 produire, ce que je fais en ce moment de toute fa\u00e7on. J\u2019adore \u00e7a. Transmettre toutes mes connaissances aux jeunes enfants, c\u2019est la r\u00e9compense. Quand je leur enseigne quelque chose et qu\u2019ils le font et que cela fonctionne. C\u2019est la r\u00e9compense, je transmets mes connaissances et mon exp\u00e9rience \u00e0 la jeune g\u00e9n\u00e9ration.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211; R\u00e9cemment, des rumeurs ont circul\u00e9 selon lesquelles Elias\/Elijah avait \u00e9t\u00e9 sign\u00e9 par AEW\/ROH. Ces rumeurs ont pris de l\u2019ampleur apr\u00e8s qu\u2019il soit apparu dans une vid\u00e9o avec The Righteous de la ROH. Cependant, des sources ont pr\u00e9cis\u00e9 qu\u2019Elijah n\u2019est pas sous contrat avec la AEW ou la ROH, du moins pour le moment car&#8230;<\/p>\n","protected":false},"author":665,"featured_media":112152,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,4,49,41],"tags":[],"ppma_author":[289],"class_list":["post-112071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-news","category-roh","category-tna-impact"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/112071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=112071"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/112071\/revisions"}],"predecessor-version":[{"id":112163,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/112071\/revisions\/112163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/112152"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=112071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=112071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=112071"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=112071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}