{"id":111982,"date":"2025-02-12T14:16:40","date_gmt":"2025-02-12T19:16:40","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=111982"},"modified":"2025-02-12T14:16:43","modified_gmt":"2025-02-12T19:16:43","slug":"aj-styles-fait-craquer-hardy-dans-les-coulisses-de-raw-le-clip-de-jey-uso-devient-viral-mise-a-jour-sur-le-jugement-day-et-un-nouveau-membre-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/02\/12\/aj-styles-fait-craquer-hardy-dans-les-coulisses-de-raw-le-clip-de-jey-uso-devient-viral-mise-a-jour-sur-le-jugement-day-et-un-nouveau-membre-et-plus\/","title":{"rendered":"AJ Styles fait craquer HARDY dans les coulisses de RAW, le clip de Jey Uso devient viral, mise \u00e0 jour sur le Jugement Day et un nouveau membre, et plus!"},"content":{"rendered":"\n<p>\u2013 La WWE a publi\u00e9 une paire de segments en coulisses exclusifs num\u00e9riques apr\u00e8s l\u2019\u00e9pisode de Raw de cette semaine sur Netflix \u00e0 la Bridgestone Arena de Nashville, TN. Dans le premier, la star de la musique country HARDY, qui \u00e9tait pr\u00e9sente et a fait une apparition dans l\u2019\u00e9mission, a rencontr\u00e9 AJ Styles dans les coulisses.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/GyFvCdrOAQs?si=DNWpcT31gB8QCQ7R\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n\n\n\n<p>\u2013 Dans le deuxi\u00e8me segment exclusif num\u00e9rique post-Raw, l\u2019ancienne championne f\u00e9minine WWE NXT, Roxanne Perez, est interview\u00e9e en coulisses \u00e0 propos de l\u2019\u00e9v\u00e9nement en direct premium WWE NXT Vengeance Day 2025 ce samedi soir, o\u00f9 elle affronte Bayley et Giulia dans une action \u00e0 triple menace avec le championnat f\u00e9minin WWE NXT en jeu. <\/p>\n\n\n\n<p>Alors qu\u2019elle parle du grand week-end \u00e0 venir, elle est confront\u00e9e \u00e0 Raquel Rodriguez, qui lui fait comprendre qu\u2019elle ne fera pas le poids face \u00e0 elle lorsqu\u2019elles s\u2019affronteront lors d\u2019un tournoi de qualification pour la Women\u2019s Elimination Chamber lors du WWE Raw de la semaine prochaine.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/To61CDVJJ4A?si=Tojw2cWHLL4w7c4h\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n\n\n\n<p>\u2013 La \u00ab\u00a0YEET-mania\u00a0\u00bb se poursuit alors que la WWE se dirige vers WrestleMania 41. Comme indiqu\u00e9, sur WWE Raw cette semaine, le \u00ab\u00a0Main Event\u00a0\u00bb Jey Uso a officiellement annonc\u00e9 qu\u2019il d\u00e9fiera GUNTHER pour le WWE World Heavyweight Championship dans l\u2019un des \u00e9v\u00e9nements principaux de l\u2019\u00e9v\u00e9nement premium en direct de deux nuits en avril \u00e0 l\u2019Allegiant Stadium de Las Vegas, Nevada. <\/p>\n\n\n\n<p>Au moment d\u2019\u00e9crire ces lignes, la vid\u00e9o du segment pr\u00e9sentant l\u2019annonce du 2\/10 Raw sur le compte officiel X de la WWE a attir\u00e9 plus de 2.2 million de vues. Plus de 600 000 vues suppl\u00e9mentaires ont \u00e9t\u00e9 enregistr\u00e9es pour le segment sur la cha\u00eene YouTube officielle de la WWE, marquant plus de deux millions de vues en moins de 12 heures sur ces deux seules plateformes.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"en\" dir=\"ltr\">BREAKING NEWS: 2025 Royal Rumble Winner Jey Uso just picked the World Heavyweight Champion, Gunther, as his <a href=\"https:\/\/twitter.com\/hashtag\/WrestleMania?src=hash&amp;ref_src=twsrc%5Etfw\">#WrestleMania<\/a> opponent! <a href=\"https:\/\/twitter.com\/hashtag\/WWERaw?src=hash&amp;ref_src=twsrc%5Etfw\">#WWERaw<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/RawOnNetflix?src=hash&amp;ref_src=twsrc%5Etfw\">#RawOnNetflix<\/a> <a href=\"https:\/\/t.co\/5dXfYsbILA\">pic.twitter.com\/5dXfYsbILA<\/a><\/p>&mdash; WWE (@WWE) <a href=\"https:\/\/twitter.com\/WWE\/status\/1889120797186294054?ref_src=twsrc%5Etfw\">February 11, 2025<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<p>\u2013 La WWE a commenc\u00e9 \u00e0 taquiner un nouveau membre potentiel pour The Judgment Day lors de l\u2019\u00e9pisode du 10 f\u00e9vrier de WWE Raw sur Netflix.<\/p>\n\n\n\n<p> Au cours de l\u2019\u00e9mission, Dominik Mysterio a fait remarquer \u00e0 Finn Balor qu\u2019ils \u00e9taient en inf\u00e9riorit\u00e9 num\u00e9rique depuis que JD McDonagh s\u2019est bless\u00e9. Balor a rapidement rejet\u00e9 l\u2019id\u00e9e, mais Liv Morgan s\u2019est immisc\u00e9e dans la conversation et a soutenu la suggestion de Dom. <\/p>\n\n\n\n<p>En fin de compte, Balor a rejet\u00e9 l\u2019id\u00e9e, mais il semble qu\u2019il y ait un nouvel ajout en route.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"en\" dir=\"ltr\"> NO NEW MEMBERS! <br><br>Should <a href=\"https:\/\/twitter.com\/hashtag\/TheJudgmentDay?src=hash&amp;ref_src=twsrc%5Etfw\">#TheJudgmentDay<\/a> listen to Finn? <a href=\"https:\/\/twitter.com\/hashtag\/WWERaw?src=hash&amp;ref_src=twsrc%5Etfw\">#WWERaw<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/RawOnNetflix?src=hash&amp;ref_src=twsrc%5Etfw\">#RawOnNetflix<\/a> <a href=\"https:\/\/t.co\/CvKxCRavJl\">pic.twitter.com\/CvKxCRavJl<\/a><\/p>&mdash; WWE (@WWE) <a href=\"https:\/\/twitter.com\/WWE\/status\/1889146117624897700?ref_src=twsrc%5Etfw\">February 11, 2025<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>\u2013 La WWE a publi\u00e9 une paire de segments en coulisses exclusifs num\u00e9riques apr\u00e8s l\u2019\u00e9pisode de Raw de cette semaine sur Netflix \u00e0 la Bridgestone Arena de Nashville, TN. Dans le premier, la star de la musique country HARDY, qui \u00e9tait pr\u00e9sente et a fait une apparition dans l\u2019\u00e9mission, a rencontr\u00e9 AJ Styles dans les&#8230;<\/p>\n","protected":false},"author":665,"featured_media":112076,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-111982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=111982"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111982\/revisions"}],"predecessor-version":[{"id":112067,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111982\/revisions\/112067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/112076"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=111982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=111982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=111982"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=111982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}