{"id":111934,"date":"2025-02-10T21:11:00","date_gmt":"2025-02-11T02:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=111934"},"modified":"2025-02-10T23:25:53","modified_gmt":"2025-02-11T04:25:53","slug":"deuxieme-heure-de-raw-145","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/02\/10\/deuxieme-heure-de-raw-145\/","title":{"rendered":"Deuxi\u00e8me Heure de RAW"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/02\/10\/resultats-pour-le-wwe-monday-night-raw\/\">Pour revenir \u00e0 la premi\u00e8re, cliquez ici<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>&#8211;\u00a0<strong>AJ Styles<\/strong>\u00a0arrive sur le ring et prend le micro. AJ Styles dit qu&rsquo;il a un sentiment de d\u00e9j\u00e0-vu. Il y a quatre mois il est venu dans cette salle avec un grand sourire car cet endroit lui appartient. Il voulait relancer sa carri\u00e8re en force, mais il s&rsquo;est bless\u00e9. C&rsquo;\u00e9tait une blessure qui devait terminer sa carri\u00e8re. Il croyait que c&rsquo;\u00e9tait termin\u00e9 ce jour-l\u00e0. Mais quand il s&rsquo;est relev\u00e9 le lendemain il a r\u00e9alis\u00e9 qu&rsquo;il pouvait encore donner et qu&rsquo;il avait encore quelque chose \u00e0 prouver. C&rsquo;\u00e9tait difficile pour revenir, mais c&rsquo;est toujours difficile quand on essaye de faire quelque chose de grand. Aujourd&rsquo;hui il est ici pour dire \u00e0 l&rsquo;Univers de la WWE qu&rsquo;il est de retour !\u00a0Et il a une liste longue de choses \u00e0 faire (AJ regarde le logo de WrestleMania). AJ dit qu&rsquo;avant il veut rappeler \u00e0 tout le monde qu&rsquo;il est toujours le Phenomenal AJ Styles !\u00a0<\/p>\n\n\n\n<p>La musique de Dominik Mysterio retenti et il arrive avec Carlito sous les hu\u00e9es, il essaye de dire qu&rsquo;il sait que \u00e7a fait longtemps. Dominik n&rsquo;arr\u00eate plus de se faire huer et ne peut pas parler. Carlito insulte la foule en espagnol. Dominik dit que \u00e7a fait longtemps qu&rsquo;AJ Styles n&rsquo;a pas mis le pied \u00e0 RAW, alors les choses ont chang\u00e9. Mais une chose qui ne changera jamais est que le Judgment Day dirige RAW.<\/p>\n\n\n\n<p> AJ r\u00e9plique qu&rsquo;il sait exactement qui est le Judgment Day. Mais Dominik a raison, les choses ont chang\u00e9&#8230; il ne voit pas Damian Priest, est-ce qu&rsquo;ils ont perdu Priest ? Est-ce que quelqu&rsquo;un voit Rhea Ripley ? O\u00f9 est Finn Balor ? Il fait autre chose ? Les choses changent et il ne s&rsquo;attendait pas \u00e0 le voir ainsi. Il voit juste un gars en jeans mauve trop serr\u00e9 et Dominik Mysterio que personne n&rsquo;aime. Mais il doit admettre, il est inspir\u00e9 par l&rsquo;\u00e9thique de travail de Dominik. Dominik est l\u00e0 chaque soir et bosse fort. Mais Dominik sera pour toujours le fils idiot de Rey Mysterio.<\/p>\n\n\n\n<p>Carlito veut attaquer AJ, mais AJ le repousse avec un Pele Kick. Dominik en profite pour frapper AJ. Dominik veut lui faire un 619, mais AJ se rel\u00e8ve, Dominik prend la fuite. AJ frappe Carlito et lui fait un Phenomenal Forearm !<\/p>\n\n\n\n<p>&#8211; La WWE officialise le match entre Gunther et Jey Uso pour WrestleMania 41.<\/p>\n\n\n\n<p>&#8211; En interview dans la foule, Jackie est avec<strong>\u00a0Seth Rollins<\/strong>. Jackie lui demande ses commentaires sur les qualifications d&rsquo;Elimination Chamber. Rollins dit que c&rsquo;est le moment de Monday Night Rollins. Il se sent extra bien car le chemin vers WrestleMania est bien clair avec Jey Uso qui a d\u00e9cid\u00e9 d&rsquo;affronter Gunther. Ce qui veut dire que les yeux pointent vers Cody Rhodes et le championnat WWE. Donc l&rsquo;homme qui va remporter l&rsquo;Elimination Chamber ira pour ce titre. Cet homme est un visionnaire, un r\u00e9volutionnaire, Seth Rollins ! Finn Balor arrive et dit que Rollins a raison, les gens regardent Rollins, mais ils ne voient que la chute de Rollins. On a tous vu les fissures de Rollins et sa d\u00e9faite contre CM Punk pour les d\u00e9buts de RAW sur Netflix. Heureusement pour lui la seule chose sur son chemin pour aller \u00e0 Elimination Chamber est un gars qui s&rsquo;effondre. <\/p>\n\n\n\n<p>Rollins termine en disant que les deux viennent de loin. Et tout le monde sait qu&rsquo;ils font un show lorsqu&rsquo;ils s&rsquo;affrontent. Mais il a une info pour Balor, il a des affaires \u00e0 r\u00e9gler avec CM Punk et ensuite avec Cody Rhodes. Alors c&rsquo;est Balor qui est sur son chemin jusqu&rsquo;\u00e0 la semaine prochaine.<\/p>\n\n\n\n<p>&#8211; Pendant la pause Netflix, Cathy est avec Austin Theory et Grayson Waller pour savoir quoi s&rsquo;attendre d&rsquo;eux pour 2025. Waller dit qu&rsquo;ils vont retourner \u00e0 NXT demain pour parler avec Oba Femi. Et samedi Adam Pearce sera bien content car il y aura un nouveau champion de NXT. Theory approuve. Theory dit qu&rsquo;il y a de bonnes \u00e9quipes ici comme Alpha Academy, mais ils n&rsquo;ont jamais eu de titres. Waller dit qu&rsquo;il ne sait pas si c&rsquo;est un vestiaire de catch ou bien une campagne \u00e0 cause de Sheamus. Theory dit que c&rsquo;est \u00e9chec, apr\u00e8s \u00e9chec, apr\u00e8s \u00e9chec et non banger.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisses, AJ Styles parle avec Adam Pearce disant qu&rsquo;il a besoin du match. Pearce confirme pour la semaine prochaine \u00e0 RAW AJ Styles contre Dominik Mysterio ! AJ le remercie. Bron Breakker arrive et fait un face \u00e0 face avec AJ Styles. Breakker dit qu&rsquo;ils vont se revoir.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Championnat par \u00c9quipe Mondial de la WWE<\/strong><\/p>\n\n\n\n<p><strong>American Made<em>\u00a0(Julius et Brutus Creed) acc d&rsquo;Ivy Nile<\/em>\u00a0vs War Raiders \u00a9\u00a0<em>(Erik et Ivar)<\/em><\/strong><\/p>\n\n\n\n<p>En fin de match, les War Raiders font leur PowerSlam \u00e0 deux sur Brutus pour le couvrir, mais il r\u00e9siste \u00e0 deux. Ivar prend la tag pour pr\u00e9parer leur finisher, mais Julius tire Erik en bas du ring. Brutus fait un Angle Slam \u00e0 Ivar pour le couvrir, mais il r\u00e9siste \u00e0 deux. Julius prend la tag, mais Ivar repousse les deux avec un Handspring Back Fist. Ivar monte sur le coin, mais Ivy Nile monte sur le tablier pour le distraire. Julius en profite pour faire une Superplex \u00e0 Ivar ! Brutus compl\u00e8te avec un Moonsault pour le couvrir, mais Erik arr\u00eate le compte ! Erik repousse Julius en bas du ring. Erik et Brutus \u00e9changent les coups, Erik cogne plus fort. Ivar prend la tag pour un War Machine, mais Julius frappe Ivar avec le titre ! L&rsquo;arbitre arr\u00eate le combat.<\/p>\n\n\n\n<p><em>Gagnants : War Raiders\u00a0par DQ<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Brutus frappe aussi Erik avec le titre par \u00e9quipe. American Made c\u00e9l\u00e8bre avec les ceintures.<\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve le Judgment Day. Finn Balor dit que la prochaine fois ils devraient peut-\u00eatre \u00e9couter Finn. Dominik dit que tout ira bien, Liv Morgan et Rodriguez iront dans l&rsquo;Elimination Chamber. Balor dit que c&rsquo;est beaucoup d&rsquo;excuses pour quelqu&rsquo;un qui s&rsquo;est fait humilier par AJ Styles. Dominik dit qu&rsquo;il va r\u00e9gler les choses avec AJ. Balor dit que Dominik a commenc\u00e9 l&rsquo;histoire avec AJ alors il devra la terminer seule.<\/p>\n\n\n\n<p>\u00a0Dominik dit termine en disant devraient peut-\u00eatre penser \u00e0 un nouveau membre pour remplacer JD McDonagh et avoir de l&rsquo;aide. Balor dit qu&rsquo;ils n&rsquo;ont pas besoin de \u00e7a. Il va battre Seth Rollins et devenir World Champion \u00e0 WrestleMania.<\/p>\n\n\n\n<p>&#8211; En coulisses, Rhea Ripley arr\u00eate Iyo Sky et Dakota Kai. Ripley dit qu&rsquo;elle ne doit rien \u00e0 Sky.\u00a0Alors elle ne va pas lui donner un match parce qu&rsquo;elle doit, mais bien parce qu&rsquo;elle le veut. Alors pour le RAW apr\u00e8s Elimination Chamber, nous aurons elle contre Iyo Sky pour le titre f\u00e9minin !\u00a0Iyo Sky dit qu&rsquo;elle a bien h\u00e2te.<\/p>\n\n\n\n<p>&#8211; CM Punk arrive sur le ring, et on retourne en pause mais heureusement ailleurs qu&rsquo;aux USA la WWE vous occupe durant les 3 minutes de pause. <\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=111938\">Pour la suite de RAW, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"mkAynYFAC6\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/02\/10\/troisieme-heure-de-raw-127\/\">Troisi\u00e8me Heure de RAW !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Troisi\u00e8me Heure de RAW !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/02\/10\/troisieme-heure-de-raw-127\/embed\/#?secret=RnXloRg3s4#?secret=mkAynYFAC6\" data-secret=\"mkAynYFAC6\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211;\u00a0AJ Styles\u00a0arrive sur le ring et prend le micro. AJ Styles dit qu&rsquo;il a un sentiment de d\u00e9j\u00e0-vu. Il y a quatre mois il est venu dans cette salle avec un grand sourire car cet endroit lui appartient. Il voulait relancer sa carri\u00e8re en force, mais il s&rsquo;est bless\u00e9. C&rsquo;\u00e9tait une blessure qui devait terminer&#8230;<\/p>\n","protected":false},"author":4,"featured_media":111959,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"ppma_author":[292],"class_list":["post-111934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=111934"}],"version-history":[{"count":9,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111934\/revisions"}],"predecessor-version":[{"id":111973,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111934\/revisions\/111973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/111959"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=111934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=111934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=111934"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=111934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}