{"id":111933,"date":"2025-02-10T22:49:08","date_gmt":"2025-02-11T03:49:08","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=111933"},"modified":"2025-02-12T16:21:03","modified_gmt":"2025-02-12T21:21:03","slug":"resultats-pour-le-wwe-monday-night-raw","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/02\/10\/resultats-pour-le-wwe-monday-night-raw\/","title":{"rendered":"R\u00e9sultats pour le WWE Monday Night RAW !"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/02\/10\/avant-gout-pour-le-wwe-monday-night-raw-du-10-fevrier-2025\/\">Pour voir RAW, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>WWE RAW Nashville, Tennessee, 10 f\u00e9vrier 2025<\/strong><br>Les commentateurs sont Michael Cole et Pat McAfee.<\/p>\n\n\n\n<p>&#8211; Le WWE Monday Night RAW d\u00e9bute avec les commentateurs qui souhaitent la bienvenue, puis voit les WWE Superstars arriver \u00e0 l&rsquo;ar\u00e9na Bravo ! <\/p>\n\n\n\n<p>&#8211; On retrouve Jey Uso. Il fait son entr\u00e9e par la foule sous une ovation. La foule n&rsquo;arr\u00eate plus de YEET et demande un rappel comme la semaine derni\u00e8re. Jey Uso va fair son YEET sur la table des commentateurs,&nbsp;pour continuer \u00e0 faire du YEET.<\/p>\n\n\n\n<p>Le tout se transf\u00e8re en bas du ring et Gunther lui fait un Slam sur la table des commentateurs. Gunther l&rsquo;am\u00e8ne sur le ring pour lui faire une Powerbomb. Gunther commence \u00e0 lui appliquer un Sleeper en criant \u00a0\u00bbJey, ne le fait pas !\u00a0\u00bb. Les officiels arrivent pour stopper Gunther, mais Gunther repousse les officiels et fait une seconde Powerbomb \u00e0 Jey. Gunther se fait sortir du ring.<\/p>\n\n\n\n<p>Jey Uso prend le micro alors qu&rsquo;il est toujours au sol, et dit qu&rsquo;il ne devrait pas dire \u00e7a, mais ce sera lui contre Gunther \u00e0 WrestleMania 41&nbsp;! <\/p>\n\n\n\n<p>Gunther est en col\u00e8re et retourne sur le ring, mais Jey Uso le repousse et se lance en saut suicide sur Gunther et les agents de s\u00e9curit\u00e9. Les deux se font s\u00e9parer.<\/p>\n\n\n\n<p>&#8211; Les commentateurs font le point sur les qualifications d&rsquo;Elimination Chamber chez les catcheuses.<\/p>\n\n\n\n<p>&#8211; En coulisses, Cathy demande \u00e0 Rhea Ripley si elle a des regrets sur la situation avec Liv Morgan. Ripley dit que si Liv Morgan atteint WrestleMania, elle sera pr\u00eate. Mais \u00e7a n&rsquo;a pas d&rsquo;importance tant que le choix de Charlotte n&rsquo;a pas \u00e9t\u00e9 fait. Iyo Sky arrive et dit qu&rsquo;elle arrive pour Rhea Ripley. Ripley dit qu&rsquo;elles vont se voir l\u00e0-bas.<\/p>\n\n\n\n<p>&#8211; Durant la pause Netflix, Liv Morgan nous souhaite la bienvenue \u00e0 un nouveau Monday Night Morgan. Comme on a vu, elle est la premi\u00e8re \u00e0 s&rsquo;\u00eatre qualifi\u00e9e pour l&rsquo;Elimination Chamber. <\/p>\n\n\n\n<p>Rachel en ajoute une couche en espagnole et Liv et en ajoute en disant  qu&rsquo;elle est aussi la Superstar avec le plus de participations dans la Chamber.  <\/p>\n\n\n\n<p>Morgan r\u00e9pond que Raquel Rodriguez va battre Roxanne Perez la semaine prochaine \u00e0 RAW pour s&rsquo;assurer de l&rsquo;aider \u00e0 gagner \u00e0 Elimination Chamber.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, on pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 des titres par \u00e9quipe.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Liv Morgan et Raquel Rodriguez vs Damage CTRL&nbsp;<em>(Iyo Sky et Dakota Kai)<\/em><\/strong><\/p>\n\n\n\n<p>En fin de match, Rodriguez utilise Morgan pour faire une Powerbomb sur Sky, mais Sky la bloque avec ses genoux et repousse Rodriguez en bas du ring. Kai prend la tag. Sky fait une German Suplex \u00e0 Morgan, Kai compl\u00e8te avec un Back Stabber pour la couvrir, mais Rodriguez bloque le compte. Rodriguez soul\u00e8ve Morgan et l&rsquo;utilise pour frapper Sky et Kai. Morgan fait un Oblivion \u00e0 Kai et la couvre, mais Sky brise le compte avec un Running Knee. Rodriguez veut faire une prise \u00e0 Kai, mais Kai la repousse contre le coin et lui fait un Running Kick. Morgan enchaine avec un Code Breaker \u00e0 Kai. Sky en profite pour faire un compte rapide \u00e0 Morgan, mais elle r\u00e9siste. Les deux s&rsquo;\u00e9changent des coups de pieds. Sky prend le contr\u00f4le et lui fait un Moonsault du coin pour la victoire.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnantes : Damage CTRL<\/em><\/p>\n\n\n\n<p>&#8211; Les commentateurs annoncent une absence pour Sami Zayn&nbsp;ce soir. Il doit r\u00e9cup\u00e9rer suite \u00e0 l&rsquo;attaque de Kevin Owens. Sami Zayn souffre d&rsquo;une \u00a0\u00bbcompression vert\u00e9brale\u00a0\u00bb et de \u00a0\u00bbprobl\u00e8mes aux tissus nerveux\u00a0\u00bb.<\/p>\n\n\n\n<p>&#8211; En vid\u00e9o, Kevin Owens d\u00e9clare que Sami Zayn n&rsquo;a rien fait pour lui au Royal Rumble. Zayn est un ami horrible et il devra le faire payer pour \u00e7a.<\/p>\n\n\n\n<p>&#8211; Pendant la pause Netflix, Jackie est avec Le New Day. Xavier Woods lui prend le micro. Xavier Woods dit qu&rsquo;ils voulaient parler d&rsquo;un sujet en particulier. Le New Day se fait huer trop fort. <\/p>\n\n\n\n<p>Kofi Kingston dit qu&rsquo;ils viennent ici pour demander pourquoi Rey Mysterio a un match de qualification pour Elimination Chamber et lui non. En 2019 il a ramen\u00e9 de l&rsquo;aura au Elimination Chamber.<\/p>\n\n\n\n<p><strong>Qualification Elimination Chamber<\/strong><br>Bayley vs Lyra Valkyria<\/p>\n\n\n\n<p>En fin de match, Valkyria veut faire son finisher, mais Bayley la bloque. Bayley veut faire son finisher, mais Valkyria la renverse en compte rapide et elle r\u00e9siste. Valkyria \u00e9vite le Rose Plant, mais Bayley surprend Valkyria avec un compte rapide pour la victoire.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Bayley<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Bayley f\u00e9licite Valkyria pour l&rsquo;affrontement et les deux c\u00e9l\u00e8brent ensemble.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Penta. Penta dit qu&rsquo;il n&rsquo;a aucune peur du challenge, aucune peur de l&rsquo;inconnu, aucune peur des l\u00e2ches qui attaquent dans le dos. Il a battu Pete Dunne et Ludwig Kaiser, mais ils veulent encore plus. Il va montrer la signification qu&rsquo;il donne au mot \u00ab\u00a0vengeance\u00a0\u00bb.<\/p>\n\n\n\n<p>&#8211; En coulisses, Jackie demande \u00e0 Ludwig Kaiser ses commentaires sur cette d\u00e9claration de Penta. Kaiser dit que lorsqu&rsquo;il cible quelqu&rsquo;un il n&rsquo;arr\u00eate jamais jusqu&rsquo;\u00e0 la fin. Pete Dunne arrive et dit qu&rsquo;il n&rsquo;avait pas besoin de son aide. Dunne ajoute qu&rsquo;il va casser Penta au point o\u00f9 il regrettera son arriv\u00e9e \u00e0 RAW. Kaiser dit qu&rsquo;il va lui laisser le chemin libre.<\/p>\n\n\n\n<p>&#8211; Pendant la pause Netflix, on retrouve Pat McAfee qui \u00e9change avec la foule. McAfee dit que Nashville n&rsquo;a aucune \u00e9quipe de sport digne de ce nom, mais ils ont la meilleure musique&nbsp;<em>country<\/em>. <\/p>\n\n\n\n<p>McAfee lance un chant \u00ab\u00a0joyeux anniversaire\u00a0\u00bb \u00e0 Michael Cole pour continuer son troll habituel.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisses, Alpha Academy f\u00e9licite Lyra Valkyria pour sa performance, mais les Creed Brothers arrivent. Ivy Nile dit que c&rsquo;est beau de voir la championne perde. Ce sera visiblement plus facile de la battre \u00e0 partir de maintenant. <\/p>\n\n\n\n<p>Valkyria lui r\u00e9pond de se taire et de rester dans sa salle de musculation. Nile dit que ce soir les Creed vont ramener les titres par \u00e9quipe \u00e0 American Made et elle va revoir Valkyria bient\u00f4t.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=111934\">Pour la suite de RAW, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"Ytcrqqe1mq\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/02\/10\/deuxieme-heure-de-raw-145\/\">Deuxi\u00e8me Heure de RAW<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Deuxi\u00e8me Heure de RAW\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/02\/10\/deuxieme-heure-de-raw-145\/embed\/#?secret=FTMpZB69KF#?secret=Ytcrqqe1mq\" data-secret=\"Ytcrqqe1mq\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE RAW Nashville, Tennessee, 10 f\u00e9vrier 2025Les commentateurs sont Michael Cole et Pat McAfee. &#8211; Le WWE Monday Night RAW d\u00e9bute avec les commentateurs qui souhaitent la bienvenue, puis voit les WWE Superstars arriver \u00e0 l&rsquo;ar\u00e9na Bravo ! &#8211; On retrouve Jey Uso. Il fait son entr\u00e9e par la foule sous une ovation. La foule&#8230;<\/p>\n","protected":false},"author":4,"featured_media":111943,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79,43,21,87,23],"tags":[],"ppma_author":[292],"class_list":["post-111933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elimination-chamber","category-raw-wwe","category-resultats","category-road-to-wrestlemania","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=111933"}],"version-history":[{"count":8,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111933\/revisions"}],"predecessor-version":[{"id":112085,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111933\/revisions\/112085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/111943"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=111933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=111933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=111933"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=111933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}