{"id":111871,"date":"2025-02-10T14:00:00","date_gmt":"2025-02-10T19:00:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=111871"},"modified":"2025-02-10T16:00:08","modified_gmt":"2025-02-10T21:00:08","slug":"la-tournee-40-years-of-foley-annoncee-nouveaux-contenus-wwe-sur-netflix-une-emission-speciale-broken-skull-sessions-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/02\/10\/la-tournee-40-years-of-foley-annoncee-nouveaux-contenus-wwe-sur-netflix-une-emission-speciale-broken-skull-sessions-et-plus\/","title":{"rendered":"La tourn\u00e9e \u00ab\u00a040 Years Of Foley\u00a0\u00bb annonc\u00e9e, Nouveaux contenus WWE sur Netflix, Une \u00e9mission sp\u00e9ciale Broken Skull Sessions, et plus!"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size\">* <em>Photo Cr\u00e9dit<\/em> : Google Image<\/p>\n\n\n\n<p>\u2013 Un certain nombre de pay-per-views classiques de la biblioth\u00e8que de la WWE ont \u00e9t\u00e9, et seront ajout\u00e9s \u00e0 l\u2019international \u00e0 Netflix \u00e0 partir de cette semaine.<\/p>\n\n\n\n<p>\u2013 La l\u00e9gende du WWE Hall of Fame, Mick Foley, c\u00e9l\u00e8bre son 40e anniversaire dans le monde de la lutte professionnelle avec une tourn\u00e9e sp\u00e9ciale \u00ab&nbsp;40 Years of Foley&nbsp;\u00bb annonc\u00e9e de f\u00e9vrier \u00e0 mai, qui comprendra des histoires, du stand-up et plus encore. Pour les dates de tourn\u00e9e et d\u2019autres informations, visitez le site officiel de Mick Foley..<\/p>\n\n\n\n<p>\u2013 La WWE continue de braquer les projecteurs sur sa cha\u00eene WWE Vault en pleine expansion sur YouTube. Lundi, la soci\u00e9t\u00e9 a publi\u00e9 un marathon sp\u00e9cial de diffusion en direct des \u00e9pisodes pass\u00e9s de \u00ab\u00a0Broken Skull Sessions\u00a0\u00bb avec la l\u00e9gende du WWE Hall of Fame \u00ab\u00a0Stone Cold\u00a0\u00bb Steve Austin.<\/p>\n\n\n\n<p> La description officielle de la vid\u00e9o, que vous pouvez regarder dans son int\u00e9gralit\u00e9 via le lecteur YouTube int\u00e9gr\u00e9 ci-dessous, se lit comme suit :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<h4 class=\"wp-block-heading\"><strong>Le meilleur des sessions de Broken Skull : Undertaker, Goldberg, Bret Hart<\/strong><\/h4>\n\n\n\n<p>\u00ab\u00a0Stone Cold\u00a0\u00bb Steve Austin accueille les l\u00e9gendes du \u00ab\u00a0Square Circle\u00a0\u00bb pour des conversations percutantes avec The Undertaker, Goldberg, Bret \u00ab\u00a0Hit Man\u00a0\u00bb Hart, Mick Foley, et bien d\u2019autres !<\/p>\n<\/blockquote>\n\n\n\n<ceter><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/o2KNuKmb-Lc?si=FTpeYMWsSEIixV5K\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n\n\n\n<p class=\"has-small-font-size\"><em>* Note: la photo date de plusieurs ann\u00e9es, elle a \u00e9t\u00e9 choisie pour illustrer plusieurs sujets<\/em><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>* Photo Cr\u00e9dit : Google Image \u2013 Un certain nombre de pay-per-views classiques de la biblioth\u00e8que de la WWE ont \u00e9t\u00e9, et seront ajout\u00e9s \u00e0 l\u2019international \u00e0 Netflix \u00e0 partir de cette semaine. \u2013 La l\u00e9gende du WWE Hall of Fame, Mick Foley, c\u00e9l\u00e8bre son 40e anniversaire dans le monde de la lutte professionnelle avec&#8230;<\/p>\n","protected":false},"author":665,"featured_media":111909,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,77,4,23],"tags":[123],"ppma_author":[289],"class_list":["post-111871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-hall-of-fame","category-news","category-wwe","tag-netflix"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=111871"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111871\/revisions"}],"predecessor-version":[{"id":111910,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111871\/revisions\/111910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/111909"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=111871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=111871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=111871"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=111871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}