{"id":111005,"date":"2025-01-24T23:11:00","date_gmt":"2025-01-25T04:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=111005"},"modified":"2025-01-25T16:30:31","modified_gmt":"2025-01-25T21:30:31","slug":"la-date-de-retour-de-charlotte-flair-a-la-wwe-revelee-2-autres-noms-echanges-a-raw-des-celebrites-a-smackdown-plus-de-participantes-au-rumble-qui-sajoutent-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/01\/24\/la-date-de-retour-de-charlotte-flair-a-la-wwe-revelee-2-autres-noms-echanges-a-raw-des-celebrites-a-smackdown-plus-de-participantes-au-rumble-qui-sajoutent-et-plus\/","title":{"rendered":"La date de retour de Charlotte Flair \u00e0 la WWE r\u00e9v\u00e9l\u00e9e, 2 autres noms \u00e9chang\u00e9s \u00e0 Raw, des c\u00e9l\u00e9brit\u00e9s \u00e0 SmackDown, plus de participantes au Rumble qui s&rsquo;ajoutent, et plus !"},"content":{"rendered":"\n<p>La date de retour de Charlotte Flair \u00e0 la WWE est fix\u00e9e.<\/p>\n\n\n\n<p>Dans l\u2019\u00e9pisode de cette semaine de WWE SmackDown, une autre vignette pour Charlotte a \u00e9t\u00e9 diffus\u00e9e. Dans celui-ci, l\u2019ancienne championne f\u00e9minine de la WWE a expliqu\u00e9 pourquoi elle a confiance en elle et n\u2019a aucune trace d\u2019arrogance. \u00c0 la fin de la vid\u00e9o, Charlotte s\u2019est d\u00e9clar\u00e9e pour le match f\u00e9minin du Royal Rumble 2025, comme nous vous l&rsquo;avions annonc\u00e9 en primeur ici m\u00eame juste avant les Survivor Series 2024.<\/p>\n\n\n\n<p>Charlotte Flair s\u2019est bless\u00e9e lors de l\u2019\u00e9pisode de WWE SmackDown du 8 d\u00e9cembre 2023. Elle a ensuite subi une intervention chirurgicale pour une d\u00e9chirure du LCA, du LCM et du m\u00e9nisque.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"en\" dir=\"ltr\">The Queen is BACK! <br><br>We can&#39;t wait for <a href=\"https:\/\/twitter.com\/hashtag\/RoyalRumble?src=hash&amp;ref_src=twsrc%5Etfw\">#RoyalRumble<\/a>! <a href=\"https:\/\/twitter.com\/MsCharlotteWWE?ref_src=twsrc%5Etfw\">@MsCharlotteWWE<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/SmackDown?src=hash&amp;ref_src=twsrc%5Etfw\">#SmackDown<\/a> <a href=\"https:\/\/t.co\/L2UihS8uea\">pic.twitter.com\/L2UihS8uea<\/a><\/p>&mdash; WWE (@WWE) <a href=\"https:\/\/twitter.com\/WWE\/status\/1882972618560540826?ref_src=twsrc%5Etfw\">January 25, 2025<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<p>Parlant du match f\u00e9minin du WWE Royal Rumble, Naomi, Bianca Belair et Liv Morgan se sont \u00e9galement d\u00e9clar\u00e9es pour le match lors de l\u2019\u00e9dition de cette semaine de SmackDown.<\/p>\n\n\n\n<p>Au moment d\u2019\u00e9crire ces lignes, la liste des participants est la suivante :<\/p>\n\n\n\n<p>* Nia Jax<br>* Bayley<br>* Charlotte Flair<br>* Naomi<br>* Bianca Belair<br>* Liv Morgan<\/p>\n\n\n\n<p>&#8211; Toujours dans l\u2019\u00e9pisode de cette semaine de WWE SmackDown, Nick Aldis a inform\u00e9 Austin Theory et Grayson Waller qu\u2019ils passeraient \u00e0 la marque WWE RAW. Cela s\u2019est produit apr\u00e8s que The Miz venait de former une alliance avec les deux hommes.<\/p>\n\n\n\n<p>&#8211; Et enfin, les com\u00e9diens Shane Gillis, Tony Hinchcliffe et Gabriel \u00ab\u00a0Fluffy\u00a0\u00bb Iglesias \u00e9taient pr\u00e9sents aux enregistrements t\u00e9l\u00e9vis\u00e9s de WWE SmackDown de cette semaine. Ils ont tous \u00e9t\u00e9 montr\u00e9s \u00e0 la cam\u00e9ra.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"BeDBfAzpIo\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/01\/24\/resultats-et-video-pour-le-wwe-friday-night-smackdown-du-24-janvier-2025\/\">R\u00e9sultats et Vid\u00e9o pour le WWE Friday Night Smackdown du 24 Janvier 2025 !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le WWE Friday Night Smackdown du 24 Janvier 2025 !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/01\/24\/resultats-et-video-pour-le-wwe-friday-night-smackdown-du-24-janvier-2025\/embed\/#?secret=d0KYbpJPkE#?secret=BeDBfAzpIo\" data-secret=\"BeDBfAzpIo\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La date de retour de Charlotte Flair \u00e0 la WWE est fix\u00e9e. Dans l\u2019\u00e9pisode de cette semaine de WWE SmackDown, une autre vignette pour Charlotte a \u00e9t\u00e9 diffus\u00e9e. Dans celui-ci, l\u2019ancienne championne f\u00e9minine de la WWE a expliqu\u00e9 pourquoi elle a confiance en elle et n\u2019a aucune trace d\u2019arrogance. \u00c0 la fin de la vid\u00e9o,&#8230;<\/p>\n","protected":false},"author":665,"featured_media":111033,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,71,36,23],"tags":[],"ppma_author":[289],"class_list":["post-111005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-royal-rumble","category-smackdown","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=111005"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111005\/revisions"}],"predecessor-version":[{"id":111034,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/111005\/revisions\/111034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/111033"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=111005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=111005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=111005"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=111005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}