{"id":110704,"date":"2025-01-19T15:16:00","date_gmt":"2025-01-19T20:16:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=110704"},"modified":"2025-01-20T16:02:59","modified_gmt":"2025-01-20T21:02:59","slug":"mise-a-jour-en-coulisses-sur-les-plans-de-la-wwe-pour-changer-la-duree-de-raw-et-smackdown","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/01\/19\/mise-a-jour-en-coulisses-sur-les-plans-de-la-wwe-pour-changer-la-duree-de-raw-et-smackdown\/","title":{"rendered":"Mise \u00e0 jour en coulisses sur les plans de la WWE pour changer la dur\u00e9e de Raw et SmackDown"},"content":{"rendered":"\n<p>Certaines mises \u00e0 jour concernant la dur\u00e9e de WWE Raw et WWE SmackDown ont fait surface.<\/p>\n\n\n\n<p>Le dernier num\u00e9ro du\u00a0<em>Wrestling Observer Newsletter<\/em>\u00a0rapporte que SmackDown devrait revenir \u00e0 un format de deux heures en mai ou juin. Ce changement devrait avoir lieu peu de temps apr\u00e8s WrestleMania 41 en avril, car la soci\u00e9t\u00e9 pense qu\u2019elle peut maintenir la dur\u00e9e actuelle de trois heures jusque-l\u00e0.<\/p>\n\n\n\n<p>Le rapport note \u00e9galement que la WWE vise g\u00e9n\u00e9ralement un \u00ab\u00a0sweet spot\u00a0\u00bb de deux heures et demie pour RAW sur Netflix. Cependant, cette dur\u00e9e est flexible et a chang\u00e9 dans le pass\u00e9, l\u2019objectif de deux heures et demie refl\u00e9tant la vision hebdomadaire de Triple H pour l\u2019\u00e9mission.<\/p>\n\n\n\n<p>Une autres source rapporte que cela pourrait \u00eatre seulement pour l&rsquo;\u00e9t\u00e9 et revenir \u00e0 3h d\u00e8s septembre ou octobre pour la prochaine saison.<\/p>\n\n\n\n<p>Lors de l\u2019\u00e9pisode de RAW de lundi dernier, la WWE a d\u00fb couper plusieurs segments pour respecter la dur\u00e9e souhait\u00e9e. Cet ajustement \u00e9tait n\u00e9cessaire car le segment de Penta a dur\u00e9 plus longtemps que pr\u00e9vu, ce qui a fait que l\u2019\u00e9mission a l\u00e9g\u00e8rement d\u00e9pass\u00e9 le temps pr\u00e9vu innitialement.<\/p>\n\n\n\n<p>Des segments ont \u00e9galement \u00e9t\u00e9 enregistr\u00e9s pendant les pauses publicitaires pour des \u00e9missions internationales non Netflix, ce qui a permis \u00e0 l\u2019\u00e9mission de durer trois heures avec des publicit\u00e9s. Les stations internationales ont \u00e9t\u00e9 inform\u00e9es de cette dur\u00e9e ajust\u00e9e. Au Canada c&rsquo;est comme \u00e7a depuis le premier RAW sur Netflix et pour Smackdown nous avons bien vu que les lutteuses n&rsquo;\u00e9taient pas au courant que cela continuait durant les pauses.<\/p>\n\n\n\n<p> On a plus voir Bayley arr\u00eater de vendre et Tiffany r\u00e9ajuster son bustre et ses shorts. M\u00eame les annimateurs commentaient peu ou pas contrairement \u00e0 RAW o\u00f9 cela continue normalement le temps que les Am\u00e9ricains son en plein 3 minutes et demie de publicit\u00e9 de fastfood.<\/p>\n\n\n\n<p>Nous vous tiendrons au courant au fur et \u00e0 mesure que des informations suppl\u00e9mentaires concernant les changements apport\u00e9s aux dur\u00e9es des \u00e9missions car le tout n&rsquo;est pas encore officiel ni coul\u00e9 dans le b\u00e9ton!<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Certaines mises \u00e0 jour concernant la dur\u00e9e de WWE Raw et WWE SmackDown ont fait surface. Le dernier num\u00e9ro du\u00a0Wrestling Observer Newsletter\u00a0rapporte que SmackDown devrait revenir \u00e0 un format de deux heures en mai ou juin. Ce changement devrait avoir lieu peu de temps apr\u00e8s WrestleMania 41 en avril, car la soci\u00e9t\u00e9 pense qu\u2019elle peut&#8230;<\/p>\n","protected":false},"author":665,"featured_media":110806,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,36,23],"tags":[123],"ppma_author":[289],"class_list":["post-110704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-smackdown","category-wwe","tag-netflix"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/110704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=110704"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/110704\/revisions"}],"predecessor-version":[{"id":110807,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/110704\/revisions\/110807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/110806"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=110704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=110704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=110704"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=110704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}