{"id":110508,"date":"2025-01-15T00:12:00","date_gmt":"2025-01-15T05:12:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=110508"},"modified":"2025-01-15T11:48:37","modified_gmt":"2025-01-15T16:48:37","slug":"mise-a-jour-detaillee-sur-les-debuts-de-penta-a-la-wwe-plans-originaux-pour-le-match-de-raw-rumeurs-de-chaleur-en-coulisses","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/01\/15\/mise-a-jour-detaillee-sur-les-debuts-de-penta-a-la-wwe-plans-originaux-pour-le-match-de-raw-rumeurs-de-chaleur-en-coulisses\/","title":{"rendered":"Mise \u00e0 jour d\u00e9taill\u00e9e sur les d\u00e9buts de Penta \u00e0 la WWE : plans originaux pour le match de Raw, rumeurs de chaleur en coulisses"},"content":{"rendered":"\n<p>Penta a fait ses d\u00e9buts tr\u00e8s attendus \u00e0 la WWE lors de l\u2019\u00e9pisode du WWE Monday Night RAW du 13 janvier.<\/p>\n\n\n\n<p>Selon une source, l\u2019accord avec la WWE avait \u00e9t\u00e9 finalis\u00e9 des semaines plus t\u00f4t, apr\u00e8s l\u2019expiration de son contrat avec la AEW le 1er d\u00e9cembre dernier.<\/p>\n\n\n\n<p>Initialement, Penta devait faire \u00e9quipe avec Rey Mysterio dans un match contre New Day, mais on ne sait pas trop pourquoi mais les plans ont chang\u00e9 durant la journ\u00e9e de lundi. Des sources internes ont d\u00e9crit la sortie de la marchandise de Penta le 13 janvier comme un \u00ab\u00a0heureux accident\u00a0\u00bb, bien qu\u2019il y ait du scepticisme \u00e0 propos de cette affirmation.<\/p>\n\n\n\n<p>Penta \u00e9tait pr\u00e9sent dans les coulisses tout au long de la journ\u00e9e, participant \u00e0 des s\u00e9ances photo et se m\u00ealant \u00e0 l&rsquo;alignement de RAW. Il n\u2019\u00e9tait pas cach\u00e9 et semblait pleinement int\u00e9gr\u00e9 aux activit\u00e9s de la journ\u00e9e. Du coup comme la nouvelle avait \u00e9t\u00e9 annonc\u00e9e par accident ou non, il n&rsquo;\u00e9tait plus n\u00e9cessaire de le tenir au placard. <\/p>\n\n\n\n<p>Des rapports sugg\u00e8rent que le segment de Penta a dur\u00e9 plus longtemps que pr\u00e9vu. Le match \u00e9tait initialement pr\u00e9vu pour un segment, utilis\u00e9 pour chronom\u00e9trer les pauses publicitaires plut\u00f4t que de d\u00e9terminer la dur\u00e9e sur le ring mais la promo a d\u00e9pass\u00e9 les attentes de la WWE. Il n\u2019est pas clair si ce d\u00e9passement a entra\u00een\u00e9 la suppression d\u2019autres segments.<\/p>\n\n\n\n<p>Certains rapports ont fait allusion \u00e0 une tension en coulisses en raison du d\u00e9passement, mais selon une source, ils ont dit qu\u2019ils n\u2019avaient pas entendu parler d\u2019une chaleur sp\u00e9cifique sur Penta. S\u2019il y avait de la frustration, elle \u00e9tait probablement dirig\u00e9e contre ceux qui \u00e9taient responsables de l\u2019application d\u2019une heure stricte de fin de spectacle. Surtout que Netflix contrairement \u00e0 une cha\u00eene normale, peut se permettre de d\u00e9passer le temps ou de le raccourcir.<\/p>\n\n\n\n<p>Malgr\u00e9 la flexibilit\u00e9 de la WWE avec les horaires de RAW, il y a eu un effort pour boucler le spectacle en environ deux heures et demie pour accommoder les talents ayant besoin de prendre des vols tardifs. Selon plusieurs talents en coulisses, aucun n\u2019a mentionn\u00e9 avoir entendu parler d\u2019une quelconque chaleur sur Penta. Au lieu de cela, ils ont reconnu l\u2019importance du moment pour lui et sa famille, beaucoup exprimant leur bonheur pour ses d\u00e9buts r\u00e9ussis.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/G-Xdh9mgRiM?si=L2lJdPLtaFgK4h1m\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"i9c7WcD7aH\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/01\/13\/resultats-et-video-pour-le-wwe-monday-night-raw-du-13-janvier-2025\/\">R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 13 Janvier 2025!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 13 Janvier 2025!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/01\/13\/resultats-et-video-pour-le-wwe-monday-night-raw-du-13-janvier-2025\/embed\/#?secret=VSJtaIqZtf#?secret=i9c7WcD7aH\" data-secret=\"i9c7WcD7aH\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Penta a fait ses d\u00e9buts tr\u00e8s attendus \u00e0 la WWE lors de l\u2019\u00e9pisode du WWE Monday Night RAW du 13 janvier. Selon une source, l\u2019accord avec la WWE avait \u00e9t\u00e9 finalis\u00e9 des semaines plus t\u00f4t, apr\u00e8s l\u2019expiration de son contrat avec la AEW le 1er d\u00e9cembre dernier. Initialement, Penta devait faire \u00e9quipe avec Rey Mysterio&#8230;<\/p>\n","protected":false},"author":665,"featured_media":110534,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,4,43,23],"tags":[],"ppma_author":[289],"class_list":["post-110508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/110508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=110508"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/110508\/revisions"}],"predecessor-version":[{"id":110535,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/110508\/revisions\/110535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/110534"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=110508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=110508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=110508"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=110508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}