{"id":109189,"date":"2024-12-22T00:26:00","date_gmt":"2024-12-22T05:26:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=109189"},"modified":"2024-12-22T12:27:28","modified_gmt":"2024-12-22T17:27:28","slug":"dirty-dominik-mysterio-se-souvient-de-son-travail-avec-cm-punk-je-connais-son-movesetset","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/12\/22\/dirty-dominik-mysterio-se-souvient-de-son-travail-avec-cm-punk-je-connais-son-movesetset\/","title":{"rendered":"Dirty Dominik Mysterio se souvient de son travail avec CM Punk : \u00ab Je connais son movesetset&#8230; \u00bb"},"content":{"rendered":"\n<p>Le \u00ab Dirty \u00bb Dominik Mysterio sait comment se mettre dans la peau des gens.<\/p>\n\n\n\n<p>Il est devenu l\u2019un des meilleurs heels de la WWE ces derniers temps gr\u00e2ce \u00e0 cette capacit\u00e9, et lors d\u2019une r\u00e9cente apparition sur le podcast\u00a0No-Contest Wrestling, il a tent\u00e9 de se mettre dans la peau de CM Punk avec ce talent.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab\u00a0J\u2019ai eu le grand d\u00e9shonneur d\u2019accueillir Punk de retour apr\u00e8s dix longues ann\u00e9es\u00a0\u00bb<\/em>, a d\u00e9clar\u00e9 Dom-Dom en se souvenant d\u2019avoir particip\u00e9 au premier match de la WWE avec Punk apr\u00e8s son retour aux Survivor Series 2023.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em> \u00ab\u00a0C\u2019\u00e9tait tout ce \u00e0 quoi je m\u2019attendais, juste un vieil homme essayant de faire son truc. Il pense qu\u2019il l\u2019a toujours. Il est all\u00e9 l\u00e0-bas en sous-v\u00eatements noirs. Il n\u2019avait m\u00eame pas son \u00e9quipement. C\u2019\u00e9tait vraiment un spectacle \u00e0 voir. Dans l\u2019ensemble, je suis content que la soci\u00e9t\u00e9 ait pu me faire confiance pour entrer l\u00e0-bas avec CM Punk et lui donner ses premiers coups de poing en retour comme un beau cadeau de bienvenue \u00e0 la maison. Cette \u00e9nergie que nous avions l\u00e0-bas \u00e9tait vraiment quelque chose de sp\u00e9cial. J\u2019ai l\u2019impression qu\u2019il me doit aussi quelque chose.<\/em><\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Je suis s\u00fbr qu\u2019il s\u2019en souvient, il a chant\u00e9 Joyeux anniversaire \u00e0 ma s\u0153ur. J\u2019avais probablement 12 ans et il lui a chant\u00e9 Joyeux anniversaire. Il a coinc\u00e9 toute ma famille quand il avait ses longs cheveux noirs. Quel \u00e9tait son groupe ? La soci\u00e9t\u00e9 ? [Soci\u00e9t\u00e9 du straight edge]. Je ne m\u2019en souvenais pas parce que \u00e7a n\u2019avait pas d\u2019importance. Maintenant que je suis mon propre homme et qu\u2019il n\u2019a pas \u00e0 me coincer dans un coin, j\u2019adorerais remettre la main sur lui. Maintenant que je suis pr\u00eat et pr\u00eat. J\u2019ai vu un peu ce qu\u2019il peut faire. Il n\u2019y a rien de sp\u00e9cial. Il fait les m\u00eames choses. Je suis presque s\u00fbr que je peux lire son livre de jeu. En fait, en voici un bon, je connais ses mouvements.<\/p>\n<\/blockquote>\n\n\n\n<p>Comme indiqu\u00e9, CM Punk a r\u00e9cemment clairement indiqu\u00e9 qu\u2019il pensait que\u00a0quiconque dit \u00ab\u00a0moveset\u00a0\u00bb est un idiot. ( <em><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/12\/16\/ne-dites-pas-moveset-si-tu-dis-ca-tu-es-un-idiot\/\" target=\"_blank\" rel=\"noreferrer noopener\">cliquez ici<\/a><\/em> )<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/pf_G2BTXPHU?si=e3UXbMYQeqmrVyCN\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le \u00ab Dirty \u00bb Dominik Mysterio sait comment se mettre dans la peau des gens. Il est devenu l\u2019un des meilleurs heels de la WWE ces derniers temps gr\u00e2ce \u00e0 cette capacit\u00e9, et lors d\u2019une r\u00e9cente apparition sur le podcast\u00a0No-Contest Wrestling, il a tent\u00e9 de se mettre dans la peau de CM Punk avec ce&#8230;<\/p>\n","protected":false},"author":665,"featured_media":109336,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-109189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/109189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=109189"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/109189\/revisions"}],"predecessor-version":[{"id":109334,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/109189\/revisions\/109334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/109336"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=109189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=109189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=109189"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=109189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}