{"id":109112,"date":"2024-12-17T15:17:00","date_gmt":"2024-12-17T20:17:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=109112"},"modified":"2024-12-18T14:53:11","modified_gmt":"2024-12-18T19:53:11","slug":"lun-des-top-de-la-nxt-blesse-au-wwe-main-event-jbl-se-souvient-dune-vraie-bagarre-a-laeroport-avec-une-autre-superstar","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/12\/17\/lun-des-top-de-la-nxt-blesse-au-wwe-main-event-jbl-se-souvient-dune-vraie-bagarre-a-laeroport-avec-une-autre-superstar\/","title":{"rendered":"L&rsquo;un des Top de la NXT, bless\u00e9 au WWE Main Event \/ JBL se souvient d&rsquo;une vraie bagarre \u00e0 l\u2019a\u00e9roport avec une autre SuperStar!"},"content":{"rendered":"\n<p>&#8211; Selon un rapport, Wes Lee a \u00e9t\u00e9\u00a0<em>\u00ab\u00a0d\u00e9fonc\u00e9\u00a0\u00bb<\/em>\u00a0lors des enregistrements t\u00e9l\u00e9vis\u00e9s du Main Event de la WWE hier soir \u00e0 Boston, MA.<\/p>\n\n\n\n<p>Le rapport indique que Lee souffrait d\u2019une blessure au pied ou \u00e0 la cheville et qu\u2019il sera examin\u00e9 sous peu.<\/p>\n\n\n\n<p>Deux \u00e9pisodes de WWE NXT seront enregistr\u00e9s ce soir \u00e0 Lowell, MA. Au moment d\u2019\u00e9crire ces lignes, on ne sait pas si Lee est dans les coulisses du spectacle.<\/p>\n\n\n\n<p>&#8211; JBL, Hall of Famer de la WWE, s\u2019est battu dans la vraie vie avec Steve Blackman pendant l&rsquo;Attitude Era.<\/p>\n\n\n\n<p>Lors d\u2019une r\u00e9cente \u00e9dition du podcast \u00ab&nbsp;Something to Wrestle&nbsp;\u00bb de Bruce Prichard, Conrad Thompson a demand\u00e9 \u00e0 JBL s\u2019il avait des&nbsp;<strong><em>\u00ab&nbsp;histoires amusantes&nbsp;\u00bb<\/em><\/strong>&nbsp;sur Blackman. Dire<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab\u00a0Je ne sais pas si vous diriez que c\u2019est amusant. Nous nous sommes disput\u00e9s vers neuf heures du matin \u00e0 la r\u00e9cup\u00e9ration des bagages de l\u2019a\u00e9roport de Kansas City. Bien s\u00fbr. Ce qui s\u2019est pass\u00e9, c\u2019est que Steve avait des migraines. Je pense que c\u2019est ce qui a conduit \u00e0 \u00e7a parce qu\u2019il y avait quelques gars qui \u00e9taient d\u2019\u00e9normes membres du Temple de la renomm\u00e9e qui avaient jou\u00e9 avec Steve pendant le vol, et Steve essayait de dormir. Ils ne m\u2019ont pas dit que Steve \u00e9tait d\u2019une humeur horrible. Ils ont dit : \u00ab\u00a0H\u00e9, va <\/em>t\u2019emb\u00eater avec Steve.<em>\u00a0\u00bb Alors j\u2019ai juste pens\u00e9 qu\u2019il avait un mauvais gars ou quelque chose comme \u00e7a. Je n\u2019avais pas r\u00e9alis\u00e9 \u00e0 quel point c\u2019\u00e9tait grave. Alors ils l\u2019avaient gard\u00e9 \u00e9veill\u00e9 ou quelque chose comme \u00e7a, ils l\u2019avaient gard\u00e9 \u00e9veill\u00e9 pendant le vol. Il avait des migraines et il \u00e9tait de mauvaise humeur. Je ne le savais pas, ils \u00e9taient en train de me pi\u00e9ger. Ce que j\u2019aurais fait \u00e0 quelqu\u2019un d\u2019autre. <\/em><\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>[Rires] Steve \u00e9tait assis l\u00e0 en short ou quelque chose comme \u00e7a. Je me suis approch\u00e9 et je l\u2019ai pinc\u00e9 sur les fesses. Je lui ai dit : &lsquo;Tu es bien dans ce short, mon gar\u00e7on&rsquo;, en faisant le vieux truc de &lsquo;D\u00e9livrance&rsquo;. Les gars vont sortir \u00e7a de son contexte et inventer toutes sortes de choses. Les gars faisaient des b\u00eatises comme \u00e7a \u00e0 l\u2019\u00e9poque. Nous n\u2019avions pas Internet, nous nous ennuyions. Steve me donne un coup de poing et me frappe environ six ou sept fois avant que je puisse bouger. Je veux dire [rires], je suis comme un putain de mannequin de coup de poing. Je me suis dit, oh mon dieu. Il est environ neuf heures du matin. Tout d\u2019un coup, je me rends compte que je suis dans un putain de combat. Dieu merci, au milieu de tout cela, il recule pour me donner un coup de pied, et il a mis son pied dans un sac \u00e0 la r\u00e9cup\u00e9ration des bagages. Dieu merci, il aurait cass\u00e9 tout ce qu\u2019il avait donn\u00e9. Alors nous nous sommes lanc\u00e9s dans une assez bonne bagarre sur le toit du carrousel en mouvement, sur ce gars de 60 ou 70 ans. [Ken] \u00e9tait au t\u00e9l\u00e9phone, c\u2019est lui qui est venu et qui a rompu [rires]. Alors oui, nous avons eu un bon brouhaha. Dieu merci, il est entr\u00e9 dans ce sac. Je ne sais pas ce qu\u2019il aurait fait, mais \u00e7a ne se serait pas bien pass\u00e9 pour moi. Je me sentais mal \u00e0 ce sujet. C\u2019\u00e9tait de ma faute, je le m\u00e9ritais pleinement. Je n\u2019aurais pas d\u00fb jouer avec lui. Je ne savais pas qu\u2019il passait une si mauvaise journ\u00e9e. Steve et moi, nous \u00e9tions amis, j\u2019avais fait des trucs comme \u00e7a une centaine de fois. Quoi qu\u2019il en soit, c\u2019\u00e9tait mal ce jour-l\u00e0, et \u00e7a arrive.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>JBL a ajout\u00e9 qu\u2019ils avaient tous deux \u00e9t\u00e9 condamn\u00e9s \u00e0 une amende pour l\u2019incident. Les deux hommes ont depuis fait amende honorable.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211; Selon un rapport, Wes Lee a \u00e9t\u00e9\u00a0\u00ab\u00a0d\u00e9fonc\u00e9\u00a0\u00bb\u00a0lors des enregistrements t\u00e9l\u00e9vis\u00e9s du Main Event de la WWE hier soir \u00e0 Boston, MA. Le rapport indique que Lee souffrait d\u2019une blessure au pied ou \u00e0 la cheville et qu\u2019il sera examin\u00e9 sous peu. Deux \u00e9pisodes de WWE NXT seront enregistr\u00e9s ce soir \u00e0 Lowell, MA. Au&#8230;<\/p>\n","protected":false},"author":665,"featured_media":109134,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,77,4,85,23],"tags":[143],"ppma_author":[289],"class_list":["post-109112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-hall-of-fame","category-news","category-nxt","category-wwe","tag-wwe-main-event"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/109112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=109112"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/109112\/revisions"}],"predecessor-version":[{"id":109135,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/109112\/revisions\/109135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/109134"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=109112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=109112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=109112"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=109112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}