{"id":109075,"date":"2024-12-17T00:05:00","date_gmt":"2024-12-17T05:05:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=109075"},"modified":"2024-12-17T13:49:17","modified_gmt":"2024-12-17T18:49:17","slug":"spoilers-pour-lepisode-du-wwe-monday-night-raw-pour-le-24-decembre","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/12\/17\/spoilers-pour-lepisode-du-wwe-monday-night-raw-pour-le-24-decembre\/","title":{"rendered":"Spoilers pour l\u2019\u00e9pisode du WWE Monday Night RAW pour le 24 D\u00e9cembre !"},"content":{"rendered":"\n<p>Apr\u00e8s l\u2019\u00e9pisode de WWE RAW de cette semaine au TD Garden Arena de Boston, MA, les matchs et segments suivants ont \u00e9t\u00e9 enregistr\u00e9s pour l\u2019\u00e9pisode de RAW du 23 d\u00e9cembre :<\/p>\n\n\n\n<p>Drew McIntyre ouvre le show avec une promo pour dire qu\u2019il va prendre ce qu\u2019il m\u00e9rite. Il cible Roman Reigns et CM Punk, et il critique les fans qui les acclament. Sami Zayn l\u2019interrompt, et ils font des allers-retours. Ils se battent, et quand McIntyre prend le dessus, Jey Uso fait l\u2019arr\u00eat. Uso et Zayn se battent contre McIntyre.<\/p>\n\n\n\n<p>*\u00a0<strong>Tournoi du Championnat Intercontinental F\u00e9minin de la WWE :<\/strong>\u00a0<br>IYO SKY (en remplacement de Kairi Sane) bat Natalya et Alba Fyre dans un triple menace.<\/p>\n\n\n\n<p>* Alpha Academy (Otis, Akira Tozawa et Maxxine Dupri) et R-Truth apparaissent dans les coulisses, tout comme Pete Dunne et American Made (Chad Gable, Ivy Nile, Brutus Creed et Julius Creed). <\/p>\n\n\n\n<p>Le Judgment Day appara\u00eet \u00e9galement au cours du segment.<\/p>\n\n\n\n<p>* Chad Gable bat Akira Tozawa par soumission. Il refuse de rel\u00e2cher la prise, mais Otis vient l\u2019arr\u00eatter.<\/p>\n\n\n\n<p>* Damian Priest bat Dominik Mysterio. Priest bat JD McDonagh, qui \u00e9tait d\u00e9guis\u00e9 en P\u00e8re No\u00ebl, pendant le match. Apr\u00e8s le match, The Judgment Day attaque Damian Priest.<\/p>\n\n\n\n<p>* Dexter Lumis bat The Miz via DQ quand The Final Testament s\u2019en m\u00eale. Apr\u00e8s le match, les Wyatt Sicks viennent s&rsquo;en m\u00ealer.<\/p>\n\n\n\n<p>* Kofi Kingston et Xavier Woods sont venu faire une promo pour dire qu\u2019ils ont des probl\u00e8mes avec Joe Tessitore et Wade Barrett. Kingston et Woods interpellent Barrett en disant que, tout comme Big E, il ne luttera plus jamais. Kingston d\u00e9signe sa m\u00e8re dans la foule, et elle le d\u00e9savoue.<\/p>\n\n\n\n<p>* Drew McIntyre bat Sami Zayn. La New Bloodline (Jacob Fatu, Tama Tonga et Solo Sikoa) sort apr\u00e8s le match et attaque Jey Uso et Sami Zayn. Uso et Zayn sont examin\u00e9s par le personnel m\u00e9dical \u00e0 la fin de la s\u00e9rie.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s l\u2019\u00e9pisode de WWE RAW de cette semaine au TD Garden Arena de Boston, MA, les matchs et segments suivants ont \u00e9t\u00e9 enregistr\u00e9s pour l\u2019\u00e9pisode de RAW du 23 d\u00e9cembre : Drew McIntyre ouvre le show avec une promo pour dire qu\u2019il va prendre ce qu\u2019il m\u00e9rite. Il cible Roman Reigns et CM Punk, et&#8230;<\/p>\n","protected":false},"author":665,"featured_media":109089,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,21,23],"tags":[],"ppma_author":[289],"class_list":["post-109075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-resultats","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/109075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=109075"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/109075\/revisions"}],"predecessor-version":[{"id":109090,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/109075\/revisions\/109090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/109089"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=109075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=109075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=109075"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=109075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}