{"id":109031,"date":"2024-12-16T20:02:00","date_gmt":"2024-12-17T01:02:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=109031"},"modified":"2024-12-18T17:37:42","modified_gmt":"2024-12-18T22:37:42","slug":"resultats-et-video-pour-le-wwe-monday-night-raw-du-16-decembre-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/12\/16\/resultats-et-video-pour-le-wwe-monday-night-raw-du-16-decembre-2024\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 16 D\u00e9cembre 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/12\/16\/avant-gout-pour-le-wwe-monday-night-raw-du-16-decembre-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir RAW, cliquez ici.<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>WWE RAW Boston, Massachusetts, 16 d\u00e9cembre 2024<\/strong><br>Les commentateurs sont Joe Tessitore et Wade Barrett.<\/p>\n\n\n\n<p>-Le WWE Monday Night RAW d\u00e9bute avec les commentateurs qui nous souhaitent la bienvenue puis on voit les Superstars qui sont arriv\u00e9s dans un putain d&rsquo;ar\u00e9na plus t\u00f4t en journ\u00e9e. <\/p>\n\n\n\n<p>&#8211; La musique de&nbsp;<strong>CM Punk<\/strong>&nbsp;se fait entendre et il arrive sur le ring. La foule chante son nom, et il dit de faire attention, des gens pourraient se f\u00e2cher en attendant ce nom. Punk dit qu&rsquo;il est un peu de mauvaise humeur ce soir. Il a avis\u00e9 Seth Rollins il y a deux semaines qu&rsquo;il ne pensait pas du tout \u00e0 Rollins. Maintenant il a commenc\u00e9 \u00e0 penser \u00e0 Rollins et \u00e7a le rend de mauvaise humeur. Car Seth Rollins, avec leur pass\u00e9 c&rsquo;est une question de temps avant qu&rsquo;ils s&rsquo;affrontent sur ce ring.&nbsp;Punk dit qu&rsquo;il sait aussi qu&rsquo;\u00e0 chaque fois qu&rsquo;il va parler sur ce ring cette musique stupide va se lancer s&rsquo;il ne fait rien.<\/p>\n\n\n\n<p>Punk dit que le point est que m\u00eame si Rollins porte des lunettes d&rsquo;Elton John, \u00e7a ne fait pas lui Elton John. Et ce n&rsquo;est pas parce qu&rsquo;on grandi en admirant CM Punk qu&rsquo;on est CM Punk. Punk dit que Rollins a d\u00e9clar\u00e9 qu&rsquo;il a ignor\u00e9 ses messages, c&rsquo;est vrai. Mais il n&rsquo;est pas ici pour parler du pass\u00e9, mais bien du futur. Rollins montrer l&rsquo;image qu&rsquo;il est mauvais. Oui il \u00e9tait la mauvaise personne dans cette histoire. \u00c0 la fin, il est la raison de l&rsquo;\u00e9chec de Rollins. Si Rollins veut venir ce soir, il est pr\u00eat \u00e0 lui donner sa le\u00e7on de catch qu&rsquo;il a demand\u00e9 gratuitement il y a plusieurs ann\u00e9es.<\/p>\n\n\n\n<p>Punk dit que le dernier gars qui a essay\u00e9 de l&rsquo;\u00e9craser \u00e9tait Drew McIntyre, Rollins ne doit pas l&rsquo;oublier. Est-ce que Rollins est plus solide que McIntyre ? Il n&rsquo;y aura pas suffisamment d&rsquo;agrafes pour Rollins lorsqu&rsquo;il aura termin\u00e9 avec lui. Punk dit qu&rsquo;il va dire autre chose pour le provoquer. Punk dit que pendant son absence, les fans chantaient toujours son nom pendant les segments de Rollins. On entend la voix de Rollins crier \u00a0\u00bbCM Punk\u00a0\u00bb. Rollins arrive par la foule.<\/p>\n\n\n\n<p>Rollins dit que la vie est une question de perspective. Il pensait qu&rsquo;en venant par ici il verrait CM Punk de la fa\u00e7on que les fans le voient. Il pensait voir une nouvelle perspective de CM Punk. Rollins regarde Punk et dit que m\u00eame de loin CM Punk reste un trou de cul. Punk dit que pour la premi\u00e8re fois de sa vie Rollins arrive du bon c\u00f4t\u00e9 car la place de Rollins est dans la foule avec les fans de CM Punk. Rollins dit qu&rsquo;il n&rsquo;a pas honte d&rsquo;\u00eatre avec ces gens. Il est un fan et sera toujours un fan.&nbsp;Pendant que Punk est parti et voulait voir cette place coul\u00e9e, il a pris la compagnie sur ses \u00e9paules pour l&rsquo;\u00e9lever. C&rsquo;est Punk qui devrait avoir honte car ce \u00a0\u00bbfan\u00a0\u00bb aura toujours plus de main events de WrestleMania que Punk.<\/p>\n\n\n\n<p>Rollins et Punk se retrouvent dans la foule et commencent \u00e0 \u00e9changer les coups. Les officiels arrivent pour essayer de s\u00e9parer tout le monde. Apr\u00e8s plusieurs tentatives, ils arrivent enfin \u00e0 s\u00e9parer tout le monde.<\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve le Judgment Day. Liv Morgan se demande pourquoi elle a gagn\u00e9 et Finn Balor non. Balor se demande o\u00f9 \u00e9tait ses partenaires pendant qu&rsquo;il \u00e9tait attaqu\u00e9 deux contre un. Morgan dit que c&rsquo;est Balor qui a demand\u00e9 d&rsquo;\u00eatre seul. Ce soir il sera aussi seul car le Judgment Day est banni du ringside. Mais Balor g\u00e8re tout bien, alors tout ira bien. Balor remercie Morgan sarcastiquement.<\/p>\n\n\n\n<p>&#8211; Ludwig Kaiser arrive sur le ring pour son match.<\/p>\n\n\n\n<p>&#8211; La WWE pr\u00e9sente le&nbsp;nouveau logo de RAW sur Netflix.<\/p>\n\n\n\n<p>&#8211; En coulisses, Adam Pearce arr\u00eate Seth Rollins et lui demande de l&rsquo;\u00e9couter.&nbsp;Rollins dit que c&rsquo;est \u00e0 Adam Pearce de l&rsquo;\u00e9couter. Il veut avoir ce match et Pearce doit l&rsquo;organiser. Pearce dit que si les deux peuvent arr\u00eater de se battre pendant une minute peut-\u00eatre qu&rsquo;il pourrait organiser quelque chose.&nbsp;Pearce quitte en disant qu&rsquo;il va faire son boulot. <\/p>\n\n\n\n<p>Drew McIntyre arrive et dit que ce n&rsquo;est pas facile d&rsquo;oublier la Bloodline. Roman Reigns l&rsquo;a dit vendredi dernier, il veut encore \u00eatre reconnu par tout le monde. Reigns reste la m\u00eame personne depuis le d\u00e9but. Rollins dit que McIntyre croit qu&rsquo;ils sont des amis \u00e0 cause de leur point en commun. Mais il a d\u00e9j\u00e0 r\u00e9gl\u00e9 cette histoire de Reigns avec Sami Zayn et Jey Uso.&nbsp;Il s&rsquo;agit de deux amis et il a du respect pour ses amis, mais pour McIntyre c&rsquo;est diff\u00e9rent. Rollins dit qu&rsquo;il doit le quitter pour aller faire quelque chose que McIntyre n&rsquo;a pas \u00e9t\u00e9 capable de faire, soit mettre un terme \u00e0 CM Punk.<\/p>\n\n\n\n<p><strong>Championnat Intercontinental<\/strong><br>Ludwig Kaiser vs Bron Breakker<\/p>\n\n\n\n<p>En fin de match, Kaiser veut faire son Running Kick en ringside, Kaiser ne le trouve pas. Breakker arrive \u00e0 faire le tour du ring plus rapidement et le tacle. Breakker ram\u00e8ne Kaiser sur le ring et lui fait un Gut Buster. Breakker enchaine avec son Spear pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Bron Breakker<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses,&nbsp;Kofi Kingston et Xavier Woods veulent entrer dans le vestiaire, mais Rey Mysterio bloque la porte, et dit que personne ne veut les voir ici. Kofi Kingston dit que d\u00e9j\u00e0 les fans osent les traiter ainsi, mais c&rsquo;est autre chose apr\u00e8s 10 ans de voir Rey Mysterio agir ainsi. <\/p>\n\n\n\n<p>Mysterio ajoute qu&rsquo;il ne sait pas quoi dire, ils ont d\u00e9pass\u00e9 les limites apr\u00e8s 10 ans. Pour le bien de tous, Woods et Kingston devraient se trouver une nouvelle place pour se changer. Woods dit que \u00e7a ira, ils ne voulaient pas se changer avec eux non plus.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la&nbsp;victoire de Cody Rhodes \u00e0 Saturday Night&rsquo;s Main Event&nbsp;et l&rsquo;attaque de Kevin Owens apr\u00e8s le show, et Triple H qui est sorti pour l&rsquo;arr\u00eater.<\/p>\n\n\n\n<p>&#8211; Les commentateurs annoncent que Cody Rhodes a eu son cong\u00e9 d&rsquo;h\u00f4pital suite aux examens&nbsp;sa blessure \u00e0 la colonne vert\u00e9brale.<\/p>\n\n\n\n<p>&#8211; En vid\u00e9o, on retrouve les War Raiders. Erik dit que ce soir ils vont \u00e0 la guerre contre le Judgment Day. Ivar et Erik disent qu&rsquo;ils ont pass\u00e9 une p\u00e9riode difficile sur le banc des bless\u00e9s. Ivar dit qu&rsquo;ils voient chaque match comme le dernier. Leur moment doit arriver maintenant. Erik dit qu&rsquo;ils doivent ramener les titres par \u00e9quipe \u00e0 la maison pour montrer que le risque en vaut la peine.<\/p>\n\n\n\n<p>&#8211; En coulisses, Cathy demande \u00e0 Adam Pearce s&rsquo;il a un nouveau match pour la premi\u00e8re de RAW sur Netflix. Pearce dit qu&rsquo;apr\u00e8s avoir n\u00e9goci\u00e9 avec les deux hommes,&nbsp;il peut annoncer que CM Punk va affronter Seth Rollins pour la premi\u00e8re de RAW sur Netflix&nbsp;!<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/12\/16\/deuxieme-heure-de-raw-139\/\">Pour la suite de RAW, cliquez ici<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"hRIZ7SEIAg\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/12\/16\/deuxieme-heure-de-raw-139\/\">Deuxi\u00e8me Heure de RAW!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Deuxi\u00e8me Heure de RAW!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/12\/16\/deuxieme-heure-de-raw-139\/embed\/#?secret=ufWzRvkA9E#?secret=hRIZ7SEIAg\" data-secret=\"hRIZ7SEIAg\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE RAW Boston, Massachusetts, 16 d\u00e9cembre 2024Les commentateurs sont Joe Tessitore et Wade Barrett. -Le WWE Monday Night RAW d\u00e9bute avec les commentateurs qui nous souhaitent la bienvenue puis on voit les Superstars qui sont arriv\u00e9s dans un putain d&rsquo;ar\u00e9na plus t\u00f4t en journ\u00e9e. &#8211; La musique de&nbsp;CM Punk&nbsp;se fait entendre et il arrive sur&#8230;<\/p>\n","protected":false},"author":4,"featured_media":109047,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,21,23],"tags":[],"ppma_author":[292],"class_list":["post-109031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe","category-resultats","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/109031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=109031"}],"version-history":[{"count":7,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/109031\/revisions"}],"predecessor-version":[{"id":109054,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/109031\/revisions\/109054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/109047"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=109031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=109031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=109031"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=109031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}