{"id":108995,"date":"2024-12-16T13:11:00","date_gmt":"2024-12-16T18:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=108995"},"modified":"2024-12-16T23:26:50","modified_gmt":"2024-12-17T04:26:50","slug":"ne-dites-pas-moveset-si-tu-dis-ca-tu-es-un-idiot","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/12\/16\/ne-dites-pas-moveset-si-tu-dis-ca-tu-es-un-idiot\/","title":{"rendered":"Ne dites pas \u00ab Moveset \u00bb Si tu dis \u00e7a, tu es un idiot !"},"content":{"rendered":"\n<p>CM Punk ne supporte pas le terme \u00ab moveset \u00bb.<\/p>\n\n\n\n<p>Dans un nouveau \u00ab&nbsp;Digital Exclusive&nbsp;\u00bb avec Jackie Redmond et Peter Rosenberg lors du Main Event de samedi soir, Punk a donn\u00e9 son avis sur le terme \u00ab&nbsp;moveset&nbsp;\u00bb.<\/p>\n\n\n\n<p>Tout a commenc\u00e9 lorsque Peter Rosenberg a fait pression pour que Koko B. Ware soit intronis\u00e9 au WWE Hall of Fame, ne r\u00e9alisant clairement pas que Koko avait \u00e9t\u00e9 intronis\u00e9 en 2009.<\/p>\n\n\n\n<p>Rosenberg a commenc\u00e9 la convention en faisant l\u2019\u00e9loge de Koko B. Ware, disant que son \u00ab&nbsp;moveset&nbsp;\u00bb \u00e9tait incroyable.<\/p>\n\n\n\n<p>Punk a r\u00e9pondu :\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab Ne dites pas moveset. \u00bb<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Quand Jackie Redmond a demand\u00e9 pourquoi Punk ne voulait pas entendre le mot \u00ab&nbsp;moveset&nbsp;\u00bb, il a r\u00e9pondu ce qui suit,<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab C\u2019est de la. Si tu dis \u00e7a, tu es un idiot ! Surtout si vous \u00eates un lutteur et que vous dites &lsquo;moveset&rsquo;, \u00e7a me dit \u00e0 100% que vous ne savez pas ce que vous faites.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Punk a poursuivi en faisant l\u2019\u00e9loge de Koko en disant :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00a0<em>\u00ab Tous les grands savent que ce n\u2019est pas une question de mouvements. \u00bb<\/em><\/p>\n<\/blockquote>\n\n\n\n<center><blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"en\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/askpunk?src=hash&amp;ref_src=twsrc%5Etfw\">#askpunk<\/a> if you had to steal the moveset of anyone in the wrestling world, who would it be?<\/p>&mdash; Bry am a wrestling fan (@Bl3222) <a href=\"https:\/\/twitter.com\/Bl3222\/status\/1387833476276228096?ref_src=twsrc%5Etfw\">April 29, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>CM Punk ne supporte pas le terme \u00ab moveset \u00bb. Dans un nouveau \u00ab&nbsp;Digital Exclusive&nbsp;\u00bb avec Jackie Redmond et Peter Rosenberg lors du Main Event de samedi soir, Punk a donn\u00e9 son avis sur le terme \u00ab&nbsp;moveset&nbsp;\u00bb. Tout a commenc\u00e9 lorsque Peter Rosenberg a fait pression pour que Koko B. Ware soit intronis\u00e9 au WWE&#8230;<\/p>\n","protected":false},"author":665,"featured_media":109057,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-108995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/108995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=108995"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/108995\/revisions"}],"predecessor-version":[{"id":109058,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/108995\/revisions\/109058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/109057"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=108995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=108995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=108995"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=108995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}