{"id":108917,"date":"2024-12-14T15:16:00","date_gmt":"2024-12-14T20:16:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=108917"},"modified":"2024-12-18T14:59:36","modified_gmt":"2024-12-18T19:59:36","slug":"trois-nouveaux-segments-annonces-pour-le-wwe-monday-night-raw-du-16-decembre","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/12\/14\/trois-nouveaux-segments-annonces-pour-le-wwe-monday-night-raw-du-16-decembre\/","title":{"rendered":"Trois nouveaux segments annonc\u00e9s pour le WWE Monday Night Raw du 16 d\u00e9cembre"},"content":{"rendered":"\n<p>La programmation de l\u2019\u00e9pisode de WWE Raw de la semaine prochaine continue de prendre forme.<\/p>\n\n\n\n<p>Samedi matin, la WWE a annonc\u00e9 l\u2019ajout de trois nouveaux segments pour l\u2019\u00e9pisode du 16 d\u00e9cembre de WWE Raw, qui comprend des apparitions de CM Punk, Seth \u00ab&nbsp;Freakin&rsquo;&nbsp;\u00bb Rollins et le retour de Kofi Kingston dans la ville natale de Boston, Massachusetts.<\/p>\n\n\n\n<p>De\u00a0WWE.com\u00a0:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<h4 class=\"wp-block-heading\"><strong>CM Punk<\/strong><\/h4>\n\n\n\n<p>CM Punk aspire \u00e0 entrer dans l\u2019image du championnat, mais il semble avoir des affaires inachev\u00e9es avec Seth \u00ab&nbsp;Freakin&nbsp;\u00bb Rollins.<\/p>\n\n\n\n<p>Rollins a souvent appel\u00e9 The Voice of the Voiceless, bien que Punk ait qualifi\u00e9 Rollins de \u00ab&nbsp;second rang&nbsp;\u00bb lors d\u2019une interview avec Jackie Redmond.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Seth \u00ab&nbsp;Freakin&rsquo;&nbsp;\u00bb Rollins<\/strong><\/h4>\n\n\n\n<p>Ce lundi, Seth \u00ab&nbsp;Freakin&nbsp;\u00bb Rollins sera en direct \u00e0 Raw, potentiellement sur une trajectoire de collision avec CM Punk.<\/p>\n\n\n\n<p>Rollins a r\u00e9primand\u00e9 Punk la semaine derni\u00e8re et se concentre sur un match avec son ennemi jur\u00e9.<\/p>\n\n\n\n<p>Que dira The Visionary \u00e0 propos de The Best in the World cette semaine ?<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Kofi Kingston<\/strong><\/h4>\n\n\n\n<p>The New Day a ouvert une nouvelle voie apr\u00e8s avoir r\u00e9primand\u00e9 Big E et l\u2019avoir expuls\u00e9 du groupe lors de la c\u00e9l\u00e9bration de leur 10e anniversaire.<\/p>\n\n\n\n<p>Ce moment \u00e9mouvant a envoy\u00e9 des ondes de choc dans l\u2019univers de la WWE, laissant Kofi Kingston et Xavier Woods avec tr\u00e8s peu de soutien.<\/p>\n\n\n\n<p>Ce lundi, Kingston retournera dans sa ville natale de Boston dans l\u2019espoir d\u2019obtenir un bien meilleur accueil que celui que lui et Woods ont re\u00e7u la semaine derni\u00e8re.<\/p>\n\n\n\n<p>Kingston recevra-t-elle un accueil chaleureux ou sera-t-elle accueillie avec plus d\u2019hostilit\u00e9 ?<\/p>\n<\/blockquote>\n\n\n\n<p>\u00c9galement programm\u00e9 pour l\u2019\u00e9pisode du 16\/12 de WWE Raw, le duo The Judgment Day de Finn Balor et JD McDonagh d\u00e9fendra leurs championnats par \u00e9quipe de la WWE contre l\u2019\u00e9quipe des War Raiders compos\u00e9e d\u2019Erik et Ivar, ainsi que Bron Breakker contre Ludwig Kaiser pour le WWE Intercontinental Championship.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La programmation de l\u2019\u00e9pisode de WWE Raw de la semaine prochaine continue de prendre forme. Samedi matin, la WWE a annonc\u00e9 l\u2019ajout de trois nouveaux segments pour l\u2019\u00e9pisode du 16 d\u00e9cembre de WWE Raw, qui comprend des apparitions de CM Punk, Seth \u00ab&nbsp;Freakin&rsquo;&nbsp;\u00bb Rollins et le retour de Kofi Kingston dans la ville natale de&#8230;<\/p>\n","protected":false},"author":665,"featured_media":109138,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,23],"tags":[],"ppma_author":[289],"class_list":["post-108917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/108917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=108917"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/108917\/revisions"}],"predecessor-version":[{"id":109139,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/108917\/revisions\/109139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/109138"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=108917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=108917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=108917"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=108917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}