{"id":108740,"date":"2024-12-10T20:11:00","date_gmt":"2024-12-11T01:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=108740"},"modified":"2024-12-12T14:05:55","modified_gmt":"2024-12-12T19:05:55","slug":"resultats-et-video-pour-le-wwe-nxt-du-10-decembre-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/12\/10\/resultats-et-video-pour-le-wwe-nxt-du-10-decembre-2024\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE NXT du 10 D\u00e9cembre 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/12\/10\/avant-gout-pour-le-wwe-nxt-du-10-decembre-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir NXT, Cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>WWE NXT, Orlando, Floride, 25 d\u00e9cembre 2024<\/strong><br>Les commentateurs sont Vic Joseph et Booker T.<\/p>\n\n\n\n<p>&#8211; Le WWE NXT de cette semaine d\u00e9bute avec les commentateurs qui souhaitent la bienvenue et on voit une vid\u00e9o r\u00e9capitulative du&nbsp;NXT Deadline de samedi dernier.<\/p>\n\n\n\n<p>&#8211; La gagnante de l&rsquo;Iron Survivor Challenge<strong>&nbsp;Giulia<\/strong>&nbsp;arrive ensuite sur le ring. Giulia dit qu&rsquo;elle est l&rsquo;Iron Survivor. Alors elle pourra faire ce qu&rsquo;elle voulait faire en venant ici. \u00c0 New Year&rsquo;s Evil, elle pourra devenir la nouvelle championne. Roxanne Perez arrive sur le ring et dit que Giulia est la plus chanceuse.<\/p>\n\n\n\n<p>Perez dit que Giulia a gagn\u00e9 le match, mais Sol Ruca \u00e9tait visiblement la meilleure du match. M\u00eame Wren Sinclair a eu une grande chance de gagner en restant dans la box des p\u00e9nalit\u00e9s. C&rsquo;est une question de chance au final. Giulia a gagn\u00e9, mais Giulia n&rsquo;est pas de son niveau. Malgr\u00e9 tout, NXT a encore prouv\u00e9 qu&rsquo;elles ont la meilleure division f\u00e9minine. \u00c0 New Year&rsquo;s Evil le r\u00e9sultat sera le m\u00eame, elle va c\u00e9l\u00e9brer avec son titre f\u00e9minin. Giulia dit qu&rsquo;elles peuvent se battre maintenant. Cora Jade arrive et lui dit de se calmer un peu. Elle ne pense m\u00eame pas que Giulia pourra se rendre \u00e0 New Year&rsquo;s Evil. Sans oublier que Giulia n&rsquo;a plus son amie.<\/p>\n\n\n\n<p>On voit sur le TitanTron que Stephanie Vaquer a \u00e9t\u00e9 attaqu\u00e9 dans les coulisses.&nbsp;Jade et Perez commencent \u00e0 rouer de coups Giulia. Kelani Jordan arrive sur le ring pour venir en aide \u00e0 Giulia, Jade et Perez prennent la fuite.<\/p>\n\n\n\n<p>&#8211; En coulisses, les catcheurs regardent la vid\u00e9o de Ethan Page \u00e0 NXT Deadline qui a perdu toute sa confiance. Tony D&rsquo;Angelo dit \u00e0 Ethan Page de passer \u00e0 autre chose, il a perdu c&rsquo;est tout. Page dit qu&rsquo;il ne sait plus comment retrouver sa place pour une chance au titre. D&rsquo;Angelo dit qu&rsquo;il peut lui donner un match pour le titre Nord-Am\u00e9ricain. <\/p>\n\n\n\n<p>Page dit qu&rsquo;il est un ancien champion de NXT, il a transform\u00e9 NXT. Le titre Nord-Am\u00e9ricain est un pas de recul pour lui. D&rsquo;Angelo dit qu&rsquo;il va offrir sa chance \u00e0 une autre personne alors.&nbsp;Page dit qu&rsquo;il va prendre le match finalement. S&rsquo;il ne peut pas battre le champion Nord-Am\u00e9ricain, sa carri\u00e8re sera surement termin\u00e9e. Il a besoin du match. D&rsquo;Angelo accepte.<\/p>\n\n\n\n<p>&#8211; En coulisses, Charlie Dempsey discute avec Lexis King. King dit qu&rsquo;il a d\u00e9couvert qu&rsquo;il est un homme d&rsquo;int\u00e9grit\u00e9. Il veut une autre chance pour l&rsquo;Heritage Cup. Dempsey dit qu&rsquo;il lui a d\u00e9j\u00e0 donn\u00e9 une chance, mais il va r\u00e9fl\u00e9chir. Le reste du No Quarter Catch Crew arrive. Dempsey dit qu&rsquo;il est tellement fier de son \u00e9quipe. Heights et Borne \u00e9taient si pr\u00e8s de devenir champions par \u00e9quipe. Et Sinclair a presque gagn\u00e9 l&rsquo;Iron Survivor. OTM arrive et disent qu&rsquo;ils auraient pu ramener les titres \u00e0 la maison. Jaida Parker dit que sans son Back Fist sur Lola Vice, Sinclair n&rsquo;aurait jamais eu cette derni\u00e8re place. OTM et NQCC commencent \u00e0 argumenter.<\/p>\n\n\n\n<p><strong>Je&rsquo;Von Evans vs Wes Lee<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Evans bloque une charge avec un Superkick. Lee se rel\u00e8ve, Evans lui fait un autre Superkick. Evans enchaine avec son Twisting Splash pour le compte de trois sur Lee.<\/p>\n\n\n\n<p><em>Gagnant : Je&rsquo;Von Evans<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve Nathan Frazer et Axiom. Axiom dit que Frazer \u00e9tait si pr\u00e8s de remporter l&rsquo;Iron Survivor. Frazer dit qu&rsquo;ils sont toujours champions par \u00e9quipe au moins. Axiom dit qu&rsquo;il \u00e9tait inquiet pour le double match de Frazer, mais Frazer a bien perform\u00e9. Frazer dit que sans la performance d&rsquo;Axiom, ils ne seraient plus des champions. Axiom dit qu&rsquo;il voulait voir Frazer r\u00e9ussir, Frazer est son partenaire, il ferait tout pour lui. Frazer dit qu&rsquo;il va corriger la situation.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de l&rsquo;allilance entre Josh Briggs et Yoshiki Inamura de la NOAH.<\/p>\n\n\n\n<p>&#8211; En coulisses, Sarah est devant le bureau du m\u00e9decin pour avoir une update sur Stephanie Vaquer. Giulia parle en japonais. Kelani Jordan dit que Vaquer est mal en point, mais elle ira bien. Jordan dit qu&rsquo;elle ne peut plus endurer Perez et Jade qui agissent comme si elles dirigent NXT. La nouvelle Kelani Jordan peut manger les deux sans probl\u00e8me.<\/p>\n\n\n\n<p>&#8211; En coulisses, Zaria et Sol Ruca discutent ensemble. Ruca dit qu&rsquo;elle n&rsquo;a jamais eu autant de plaisir que dans l&rsquo;Iron Survivor Challenge. Zaria dit qu&rsquo;elle s&rsquo;est sentie bien vivante avec la chaleur du combat. Lash Legend et Jakara Jackson. Legend dit que c&rsquo;\u00e9tait \u00e9vident que les deux n&rsquo;allaient pas gagner. Jackson dit que les Meta Girls auraient pu remporter le match. Legend dit que Zaria joue la forte, mais elle n&rsquo;aurait aucune chance contre elle. Ruca dit que si Legend aurait \u00e9t\u00e9 dans le match elle ne dirait pas \u00e7a. Jackson dit qu&rsquo;elle ne devrait pas d\u00e9fendre quelqu&rsquo;un qui l&rsquo;a battu \u00e0 Deadline.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Tank Ledger et Hank Walker vs Tyson Dupont et Tyriek Igwe<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Hank bloque une charge de Dupont avec une Bossman Slam. Tank prend la tag et ils font leur combinaison de PowerSlam et charge sur Dupont pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Tank Ledger et Hank Walker<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Tank et Hank f\u00e9licitent Dupont pour le match, mais Igwe refuse.<\/p>\n\n\n\n<p>&#8211;&nbsp;<strong>Oba Femi<\/strong>&nbsp;arrive sur le ring et prend le micro. Femi dit qu&rsquo;il est de retour. Femi dit qu&rsquo;il a d\u00e9truit tout le monde et il est l&rsquo;Iron Survivor. Dans quatre semaines, \u00e0 New Year&rsquo;s Evil, il va reprendre sa position sur le tr\u00f4ne comme le dirigeant de NXT. Ce qui l&rsquo;am\u00e8ne sur le sujet de Trick Williams. Ils n&rsquo;ont jamais crois\u00e9 le m\u00eame chemin, mais les deux ont \u00e9t\u00e9 dominant. C&rsquo;est le moment de savoir qui est le meilleur. La musique de Trick Williams se lance et il arrive sur le ring. Les deux font un face \u00e0 face, mais la musique d&rsquo;Eddy Thorpe se lance.<\/p>\n\n\n\n<p>Thorpe dit que \u00e7a ne se passera pas ainsi. Il ne va pas ignorer ce que Femi lui a fait. Femi l&rsquo;a attaqu\u00e9 la semaine derni\u00e8re, il lui a pris sa plus grande en carri\u00e8re. Alors o\u00f9 est la justice dans cette histoire ? Femi lui demande de se taire. Femi dit que c&rsquo;est de grandes accusations. Est-ce que Thorpe l&rsquo;a vu l&rsquo;attaquer ? Thorpe dit qu&rsquo;il a \u00e9t\u00e9 frapp\u00e9 dans le dos et il n&rsquo;a jamais \u00e9t\u00e9 frapp\u00e9 par autant de force. Femi le remercie pour le compliment, mais c&rsquo;est termin\u00e9 de perdre son temps. Williams dit que tout le monde a h\u00e2te de voir leur match. \u00c0 Los Angeles, dans la ville des \u00e9toiles, les deux plus grandes stars vont s&rsquo;affronter. Le r\u00e8gne d&rsquo;un champion est d\u00e9fini par qui le champion bat et non par les jours de r\u00e8gne.<\/p>\n\n\n\n<p>Femi dit que Williams \u00e9tait le gars num\u00e9ro un car il l&rsquo;a laiss\u00e9 faire. C&rsquo;est lui qui a donn\u00e9 cette chance d&rsquo;avoir l&rsquo;\u00e8re du Whoop That Trick. Il savait toujours que lorsqu&rsquo;il serait pr\u00eat il pourrait prendre facilement cette \u00e8re. \u00c0 New Year&rsquo;s Evil, ils ont un rendez-vous avec la destin\u00e9. Il promet que le d\u00e9but 2025 sera la fin de l&rsquo;\u00e8re de Williams. Femi quitte le ring. Thorpe dit que Williams est un champion, Williams devrait \u00eatre un leader. Mais Williams ne fait rien pour l&rsquo;attaque dans les coulisses. Il pensait que Williams lui aurait donn\u00e9 un match de titre pour l&rsquo;injustice qu&rsquo;il a v\u00e9cu. Il pensait que Williams se battait pour les gens, mais il n&rsquo;a rien \u00e0 offrir.<\/p>\n\n\n\n<p>Thorpe dit que Williams ne pourra m\u00eame pas survivre dans le Dojo du Japon d&rsquo;o\u00f9 il vient. Williams est venu de la NFL apr\u00e8s un tryout. Williams dit que Carmelo Hayes et d&rsquo;autres ont dout\u00e9 comme Thorpe.&nbsp;Si Thorpe pense pouvoir lui prendre son titre, il n&rsquo;a aucun probl\u00e8me de lui prouver pourquoi il est le champion. Williams dit qu&rsquo;il veut affronter Thorpe la semaine prochaine. Williams le frappe et quitte le ring.<\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve Fatal Influence. Jacy Jayne et Fallon Henley argumentent sur le retour de Gigi Dolin. Jazmyn Nyx dit que \u00e7a ne change rien, elles doivent r\u00e9gler ce probl\u00e8me.<\/p>\n\n\n\n<p>&#8211; En coulisses, Gigi Dolin et Tatum Paxley discutent du fait qu&rsquo;elles sont deux contre trois. Izzi Dame arrive et leur dit qu&rsquo;elle n&rsquo;a pas termin\u00e9 avec les deux. Shawn Spears, Niko et Brooks Jensen arrivent. Spears dit que Dame semble perdue. Dame dit qu&rsquo;elle n&rsquo;a pas besoin de son approbation, elle sait \u00e0 quel point elle est impressionnante.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Jacy Jayne et Jazmyn Nyx<em>&nbsp;acc de Fallon Henley<\/em>&nbsp;vs Gigi Dolin et Tatum Paxley<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Paxley prend Jayne sur ses \u00e9paules et lui fait un Air Plane Spin. Paxley monte sur le coin, mais Henley la repousse au sol pendant que Nyx distrait l&rsquo;arbitre. Jayne enchaine avec une Clothesline sur Paxley pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnantes : Jacy Jayne et Jazmyn Nyx<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, le clan de Jayne commence \u00e0 rouer de coups Paxley. Gigi Dolin veut venir en aide, mais elle se fait aussi attaquer.<strong>&nbsp;La musique de Shotzi<\/strong>&nbsp;se lance et elle fait son retour ! Shotzi arrive \u00e0 repousser Fatal Influence du ring.<\/p>\n\n\n\n<p>&#8211; En coulisses, Axiom est avec Nathan Frazer.&nbsp;Axiom dit qu&rsquo;il a \u00e9t\u00e9 voir Ava pour demander un match simple contre Oba Femi.&nbsp;Frazer demande c&rsquo;est quand. Axiom dit que c&rsquo;est la semaine prochaine, il veut prouver ce qu&rsquo;il peut faire. Frazer dit qu&rsquo;il a \u00e9t\u00e9 voir Ava pour organiser un match par \u00e9quipe la semaine prochaine pour offrir une meilleure performance que Deadline. Frazer dit que si quelqu&rsquo;un est capable de faire deux matchs est bien Axiom. Axiom dit qu&rsquo;on voit dans quelle condition il est.<\/p>\n\n\n\n<p><strong>NXT North American Championship<\/strong><br>Ethan Page vs Tony D&rsquo;Angelo <em>\u00a9 accompagn\u00e9 de La Famille<\/em><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Page porte un coup de pied \u00e0 D&rsquo;Angelo. Page enchaine avec un Cutter et le couvre, mais D&rsquo;Angelo r\u00e9siste \u00e0 deux. Page le rel\u00e8ve pour son finisher, mais D&rsquo;Angelo le bloque et lui fait son Spinebuster pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Tony D&rsquo;Angelo<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, Lexis King est avec l&rsquo;ancien joueur de NFL Ryan Leaf. King dit que Leaf est une inspiration pour tout ce qu&rsquo;il a fait. Leaf dit que c&rsquo;est toujours le bon moment pour changer son histoire. Il a h\u00e2te de voir ce que King fera. Charlie Dempsey arrive et dit que King devient vraiment meilleur.&nbsp;Il aura son match Heritage Cup dans deux semaines, mais avant il devra faire un entrainement avec lui. King approuve.<\/p>\n\n\n\n<p>&#8211; Sur le parking, Ethan Page quitte avec sa valise. Ethan Page dit qu&rsquo;il sait qu&rsquo;il est meilleur que \u00e7a.&nbsp;Il a d\u00e9j\u00e0 \u00e9t\u00e9 meilleur, mais il a perdu sa voie. Il dit \u00eatre All Ego, mais il ne pense pas l&rsquo;\u00eatre. Il est perdu et il a honte.<\/p>\n\n\n\n<p>&#8211; Les commentateurs annoncent pour la semaine prochaine : Trick Williams vs Eddy Thorpe pour le titre de NXT, Oba Femi vs Axiom, Axiom et Nathan Frazer vs Gallus pour les titres par \u00e9quipe, et Ruca et Zaria vont affronter les Meta Girls.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Roxanne Perez et Cora Jade vs Giulia et Kelani Jordan<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Perez fait son Pop Rox sur Jordan en ringside. Giulia se lance en Running Knee du tablier sur Perez. Perez et Giulia commencent \u00e0 \u00e9changer les coups en ringside. Jade en profite pour faire son DDT \u00e0 Jordan pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnantes : Roxanne Perez et Cora Jade<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, la musique de Stephanie Vaquer se lance. Jade l&rsquo;attend, mais Vaquer arrive de l&rsquo;autre c\u00f4t\u00e9 pour l&rsquo;attaquer. Jade arrive \u00e0 s&rsquo;\u00e9chapper du ring et prendre la fuite.<\/p>\n\n\n\n<p>&#8211; En coulisses, Eddy Thorpe signe son contrat pour son match contre Trick Williams. Ava dit que c&rsquo;est officiel.&nbsp;Ava dit qu&rsquo;ils enqu\u00eatent toujours pour son agresseur. Eddy Thorpe dit qu&rsquo;elle le regarde, il a jou\u00e9 la sc\u00e8ne pour avoir ce match. Le show se termine ainsi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2024\/12\/10\/avant-gout-pour-le-wwe-nxt-du-10-decembre-2024\/\" target=\"_blank\">Pour voir NXT, Cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"ERZO4JJG4z\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/12\/10\/avant-gout-pour-le-wwe-nxt-du-10-decembre-2024\/\">Reprise Vid\u00e9o et Programme pour le WWE NXT du 10 D\u00e9cembre 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le WWE NXT du 10 D\u00e9cembre 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/12\/10\/avant-gout-pour-le-wwe-nxt-du-10-decembre-2024\/embed\/#?secret=Nq047ugnB3#?secret=ERZO4JJG4z\" data-secret=\"ERZO4JJG4z\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE NXT, Orlando, Floride, 25 d\u00e9cembre 2024Les commentateurs sont Vic Joseph et Booker T. &#8211; Le WWE NXT de cette semaine d\u00e9bute avec les commentateurs qui souhaitent la bienvenue et on voit une vid\u00e9o r\u00e9capitulative du&nbsp;NXT Deadline de samedi dernier. &#8211; La gagnante de l&rsquo;Iron Survivor Challenge&nbsp;Giulia&nbsp;arrive ensuite sur le ring. Giulia dit qu&rsquo;elle est&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":108741,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,21,23],"tags":[],"ppma_author":[297],"class_list":["post-108740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nxt","category-resultats","category-wwe"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/108740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=108740"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/108740\/revisions"}],"predecessor-version":[{"id":108821,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/108740\/revisions\/108821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/108741"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=108740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=108740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=108740"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=108740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}