{"id":108244,"date":"2024-12-02T15:16:00","date_gmt":"2024-12-02T20:16:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=108244"},"modified":"2024-12-02T15:38:00","modified_gmt":"2024-12-02T20:38:00","slug":"a-quoi-pourrait-ressembler-lavenir-de-big-e-si-sa-carriere-sur-le-ring-serait-termine-kofi","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/12\/02\/a-quoi-pourrait-ressembler-lavenir-de-big-e-si-sa-carriere-sur-le-ring-serait-termine-kofi\/","title":{"rendered":"\u00c0 quoi pourrait ressembler l&rsquo;avenir de Big E si sa carri\u00e8re sur le ring serait termin\u00e9 ! Kofi Kingston parle des 10 ans du New Day, et plus !"},"content":{"rendered":"\n<p>Big E. a connu un parcours formidable dans le cadre de The New Day \u00e0 la WWE.<\/p>\n\n\n\n<p>Avant la c\u00e9l\u00e9bration du 10e anniversaire du New Day ce soir \u00e0 Raw en provenance de la ville d&rsquo;Everett, dans l\u2019\u00c9tat de Washington, l\u2019ancien champion de la WWE a r\u00e9fl\u00e9chi dans un article de\u00a0<strong>Players Tribune<\/strong>\u00a0sur un segment m\u00e9morable de leur pass\u00e9, ainsi que sur ce \u00e0 quoi pourrait ressembler son avenir si sa carri\u00e8re sur le ring est termin\u00e9e.<\/p>\n\n\n\n<p>Vous trouverez ci-dessous quelques-uns des points forts.<\/p>\n\n\n\n<p><strong>Sur l\u2019excitation d\u2019explorer les opportunit\u00e9s si sa carri\u00e8re sur le ring de la WWE est termin\u00e9e :<\/strong>\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Vous savez ce que j\u2019ai dit plus t\u00f4t \u2013 comment je suis quelqu\u2019un qui a pass\u00e9 son pass\u00e9 \u00e0 ne pas \u00eatre capable d\u2019imaginer un avenir ? Je peux en imaginer un maintenant. Ce qui est ironique, je suppose, puisque je me suis cass\u00e9 le cou et que je ne peux pas lutter. Mais je suis en paix. Et si c\u2019est vraiment la fin de ma carri\u00e8re sur le ring &#8230;&#8230;. <\/p>\n\n\n\n<p>J\u2019ai h\u00e2te d\u2019explorer les chemins qui s\u2019ouvrent \u00e0 moi dans son sillage. Qu\u2019il s\u2019agisse de travailler pour la WWE en dehors du ring, ou d\u2019animer, ou d\u2019agir, ou de faire du doublage, ou de faire des films, ou tant d\u2019autres choses. J\u2019ai l\u2019impression qu\u2019il y a encore tellement de parties de moi-m\u00eame \u00e0 d\u00e9couvrir. J\u2019ai l\u2019impression d\u2019avoir pass\u00e9 les 10 derni\u00e8res ann\u00e9es avec Woods et Kofi sur ce projet incroyable qui change la vie : essayer de jouer une version de la lutte qui est \u00e0 l\u2019image de toutes les choses que nous aimons. Et maintenant, je veux savoir jusqu\u2019o\u00f9 je peux \u00e9tendre ce projet au-del\u00e0 de la lutte. Je veux voir si je peux vraiment cr\u00e9er certaines de ces choses que nous aimons.<\/p>\n<\/blockquote>\n\n\n\n<p><strong>Sur la raison pour laquelle il a dout\u00e9 \u00e0 l\u2019origine de la m\u00e9morable bataille de rap entre The Usos et New Day en 2017 :<\/strong>\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Ce n\u2019est que maintenant que nous avons pu le faire d\u2019une mani\u00e8re qui nous ressemblait. Par exemple, notre entr\u00e9e \u00e0 WrestleMania 32 \u2013 c\u2019est juste Woods qui est Woods. Il a eu une id\u00e9e bas\u00e9e sur Dragon Ball Z (lui et Kofi sont tous les deux fans), et ce designer talentueux nomm\u00e9 Mikal Mosley nous a aid\u00e9s \u00e0 lui donner vie : o\u00f9 non seulement notre \u00e9quipement serait inspir\u00e9 des personnages de Dragon Ball Z&#8230; Notre entr\u00e9e ressemblerait \u00e0 des jouets vers\u00e9s dans une bo\u00eete de c\u00e9r\u00e9ales. (Je n\u2019arrive toujours pas \u00e0 croire qu\u2019ils ont r\u00e9ussi.) <\/p>\n\n\n\n<p>Ou comme \u2014 Kofi, c\u2019est une \u00e9norme t\u00eate de baskets. Et un jour, sur Twitter, il y a eu cette \u00ab controverse \u00bb autour de la nouvelle \u00ab chaussure de papa \u00bb de Steph Curry. Imm\u00e9diatement, nous avons pens\u00e9, oui. C\u2019est un segment. Nous avons donc trouv\u00e9 le Foot Locker le plus proche, pris une paire de Curry 2 Low blanc h\u00f4pital et coup\u00e9 une promo \u00e0 la t\u00e9l\u00e9vision qui n\u2019est litt\u00e9ralement que Woods et moi r\u00f4tissant Kofi pour avoir port\u00e9 ces chaussures. <\/p>\n\n\n\n<p>Mec&#8230; ou m\u00eame le segment de la bataille de rap. Nous sommes tous de grands fans de hip-hop. Mais l\u2019une des rares fois o\u00f9 j\u2019ai dout\u00e9 de Woods, c\u2019\u00e9tait lors de notre querelle avec les Usos, quand il a dit que nous devrions faire une bataille de rap avec eux. Je connais assez bien le rap pour savoir que je ne devrais pas rapper. Je me dis, \u00e7a a une chance d\u2019\u00eatre une poubelle chaude. Mais ce n\u2019\u00e9tait pas le cas\u00a0!! Et je pense que la raison en est la quantit\u00e9 d\u2019AMOUR qu\u2019il y a mise &#8211; et \u00e0 quel point il \u00e9tait clair que nous nous amusions \u00e0 le faire.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"en\" dir=\"ltr\">I don\u2019t know if The New Day saved my career, or my life.<br><br>But I know it turned them both into things where anything feels possible.<br><br>I hope you\u2019ll read this. <a href=\"https:\/\/twitter.com\/PlayersTribune?ref_src=twsrc%5Etfw\">@PlayersTribune<\/a><a href=\"https:\/\/t.co\/fnfUyAyeq8\">https:\/\/t.co\/fnfUyAyeq8<\/a><\/p>&mdash; Ettore \u201cBig E\u201d Ewen (@WWEBigE) <a href=\"https:\/\/twitter.com\/WWEBigE\/status\/1863597019060990427?ref_src=twsrc%5Etfw\">December 2, 2024<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p><\/p>\n\n\n\n<p>Kofi Kingston s\u2019est entretenu avec le\u00a0<em>New York Post<\/em>\u00a0avant l\u2019\u00e9pisode sp\u00e9cial de RAW dans la ville d&rsquo;Everett, dans l\u2019\u00c9tat de Washington.<\/p>\n\n\n\n<p>Au cours de la discussion, l\u2019ancien champion de la WWE a parl\u00e9 de la long\u00e9vit\u00e9 du groupe de trois hommes, qui comprend lui-m\u00eame, Big E. et Xavier Woods:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Quand vous pensez \u00e0 toutes les \u00e9quipes qui sont pass\u00e9es par la WWE, beaucoup d\u2019entre elles, nous pensons qu\u2019elles ont dur\u00e9 beaucoup plus longtemps qu\u2019elles ne l\u2019ont fait en r\u00e9alit\u00e9\u00a0\u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0Pour nous, aller 10 ans est vraiment un exploit incroyable et quelque chose dont nous sommes vraiment tr\u00e8s fiers, quelque chose que nous nous sommes efforc\u00e9s d\u2019atteindre. C\u2019est toujours l\u2019objectif d\u2019arriver \u00e0 ce point et au-del\u00e0.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Alors oui, mec, nous sommes tr\u00e8s fiers, et surtout avec le fait que nous avons apport\u00e9 une grande partie de l\u2019industrie, nous avons pu faire tellement de choses incroyables, en animant WrestleMania, en allant au coude \u00e0 coude avec The Rock au micro, en apportant de vraies c\u00e9r\u00e9ales (Booty-Os) \u00e0 la WWE &#8211; le premier produit alimentaire depuis plus d\u2019une d\u00e9cennie. Il y a tellement de choses diff\u00e9rentes que nous avons pu accomplir et dont nous sommes tr\u00e8s fiers. Dix ans, c\u2019est vraiment, vraiment long, et vous ne vous en rendez m\u00eame pas vraiment compte jusqu\u2019\u00e0 ce que vous vous asseyiez et que vous vous disiez : \u00ab\u00a0Oh mon Dieu, 10 ans. Waouh.<\/p>\n<\/blockquote>\n\n\n\n<p>Assurez-vous de nous rejoindre ici ce soir pour voir le Monday Night RAW, ou encore la couverture des r\u00e9sultats  y compris la c\u00e9l\u00e9bration du 10e anniversaire de The New Day.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/Q8HUAmaJBYw?si=qB-1JaFu8uw817t9\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"hTRScMGGJK\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/12\/02\/avant-gout-pour-le-wwe-monday-night-raw-du-2-decembre-2024\/\">Reprise Vid\u00e9o pour le WWE Monday Night RAW du 2 D\u00e9cembre 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le WWE Monday Night RAW du 2 D\u00e9cembre 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/12\/02\/avant-gout-pour-le-wwe-monday-night-raw-du-2-decembre-2024\/embed\/#?secret=IXKIxuIKsz#?secret=hTRScMGGJK\" data-secret=\"hTRScMGGJK\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Big E. a connu un parcours formidable dans le cadre de The New Day \u00e0 la WWE. Avant la c\u00e9l\u00e9bration du 10e anniversaire du New Day ce soir \u00e0 Raw en provenance de la ville d&rsquo;Everett, dans l\u2019\u00c9tat de Washington, l\u2019ancien champion de la WWE a r\u00e9fl\u00e9chi dans un article de\u00a0Players Tribune\u00a0sur un segment m\u00e9morable&#8230;<\/p>\n","protected":false},"author":665,"featured_media":108271,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,23],"tags":[],"ppma_author":[289],"class_list":["post-108244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/108244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=108244"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/108244\/revisions"}],"predecessor-version":[{"id":108274,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/108244\/revisions\/108274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/108271"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=108244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=108244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=108244"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=108244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}