{"id":107687,"date":"2024-11-25T02:29:00","date_gmt":"2024-11-25T07:29:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=107687"},"modified":"2024-11-26T14:50:10","modified_gmt":"2024-11-26T19:50:10","slug":"qt-marshall-remet-les-pendules-a-lheure-a-propos-de-la-rumeur-punk-cm-la-wwe-depose-une-demande-de-marque-pour-le-nom-de-ring-edge","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/11\/25\/qt-marshall-remet-les-pendules-a-lheure-a-propos-de-la-rumeur-punk-cm-la-wwe-depose-une-demande-de-marque-pour-le-nom-de-ring-edge\/","title":{"rendered":"QT Marshall remet les pendules \u00e0 l\u2019heure \u00e0 propos de la rumeur punk CM, la WWE d\u00e9pose une demande de marque pour le nom de ring \u00ab\u00a0Edge\u00a0\u00bb"},"content":{"rendered":"\n<p>\u2013 Malgr\u00e9 ce que les autres disent, CM Punk a en fait demand\u00e9 un match avec QT Marshall alors qu\u2019il \u00e9tait \u00e0 la AEW. Le v\u00e9t\u00e9ran de la lutte professionnelle, qui affronte Big Boom AJ lors du pr\u00e9-show \u00ab\u00a0Zero Hour\u00a0\u00bb au AEW Full Gear 2024 ce week-end, s\u2019est rendu \u00e0 X mercredi pour r\u00e9pondre \u00e0 un fan qui a affirm\u00e9 le contraire. \u00ab\u00a0Il l\u2019a litt\u00e9ralement demand\u00e9 \u00e0 mon patron\u00a0\u00bb, a \u00e9crit Marshall. \u00ab\u00a0J\u2019aimerais lutter contre un m\u00e9chant dans ma ville natale qui ne veut pas se lancer en affaires par lui-m\u00eame et essayer de s\u2019en sortir avec le public.\u00a0\u00bb<\/p>\n\n\n\n<p>\u2013 Ne vous attendez pas \u00e0 voir \u00ab\u00a0The Rated-R Superstar\u00a0\u00bb utiliser son ancien nom Edge de sit\u00f4t. La WWE a d\u00e9pos\u00e9 cette semaine aupr\u00e8s de l\u2019Office des brevets et des marques des \u00c9tats-Unis (USPTO) la marque d\u00e9pos\u00e9e \u00ab\u00a0Edge\u00a0\u00bb, qui a \u00e9t\u00e9 utilis\u00e9 pendant des ann\u00e9es par la star actuelle de la AEW, Adam Copeland, au cours de sa carri\u00e8re au WWE Hall of Fame. Vous trouverez ci-dessous la description officielle du d\u00e9p\u00f4t de l\u2019USPTO :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab D\u00e9monstrations et performances de lutte d\u2019un lutteur professionnel et d\u2019un artiste diffus\u00e9es par le biais de m\u00e9dias audiovisuels, y compris la t\u00e9l\u00e9vision et via Internet ou un service commercial en ligne ; fournir des nouvelles et des informations sur la lutte via un r\u00e9seau informatique mondial&nbsp;; fournir des informations dans les domaines du sport via un portail communautaire en ligne.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>\u2013 Malgr\u00e9 ce que les autres disent, CM Punk a en fait demand\u00e9 un match avec QT Marshall alors qu\u2019il \u00e9tait \u00e0 la AEW. Le v\u00e9t\u00e9ran de la lutte professionnelle, qui affronte Big Boom AJ lors du pr\u00e9-show \u00ab\u00a0Zero Hour\u00a0\u00bb au AEW Full Gear 2024 ce week-end, s\u2019est rendu \u00e0 X mercredi pour r\u00e9pondre \u00e0&#8230;<\/p>\n","protected":false},"author":665,"featured_media":107976,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,77,4],"tags":[],"ppma_author":[289],"class_list":["post-107687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-hall-of-fame","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/107687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=107687"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/107687\/revisions"}],"predecessor-version":[{"id":107978,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/107687\/revisions\/107978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/107976"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=107687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=107687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=107687"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=107687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}