{"id":107571,"date":"2024-11-18T20:11:00","date_gmt":"2024-11-19T01:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=107571"},"modified":"2024-11-20T16:21:34","modified_gmt":"2024-11-20T21:21:34","slug":"resultats-et-video-pour-le-wwe-monday-night-raw-du-18-novembre-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/11\/18\/resultats-et-video-pour-le-wwe-monday-night-raw-du-18-novembre-2024\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 18 Novembre 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2024\/11\/18\/avant-gout-pour-le-wwe-monday-night-raw-du-18-novembre-2024\/\" target=\"_blank\">Pour voir RAW, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>WWE RAW Grand Rapids, Michigan, 18 novembre<\/strong><br>Les commentateurs sont Joe Tessitore et Wade Barrett.<\/p>\n\n\n\n<p>&#8211; Le WWE Monday Night RAW, le show rouge d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue et on voit les WWE Superstars arriver \u00e0 l&rsquo;ar\u00e9na de la ville et non \u00e0 la salle paroissiale o\u00f9 Mattias et Atoinne vont se marier. <\/p>\n\n\n\n<p>&#8211; Liv Morgan et Raquel Rodriguez arrivent sur le ring. Morgan nous souhaite la bienvenue \u00e0 Monday Night Morgan. Elle sait que Jade Cargill et Bianca Belair veulent le revanche suite \u00e0 SmackDown, alors elles ne sont pas ici seules. La musique de Nia Jax se lance et elle arrive sur le ring avec Tiffany Stratton et Candice LeRae.<\/p>\n\n\n\n<p>Nia Jax dit qu&rsquo;elle veut r\u00e9gler quelques \u00e9l\u00e9ments. Elle n&rsquo;aime pas Rodriguez et elle ne se pr\u00e9occupe pas d&rsquo;elle. Jax dit qu&rsquo;elle a eu ses conflits avec Liv Morgan, elle ne l&rsquo;aime pas, m\u00eame chose. Bianca Belair, Jade Cargill et Naomi arrivent sur le ring. Belair dit que si Nia Jax veut faire quelque chose c&rsquo;est le moment de le faire. Mais elles avaient raison sur un point, elles ne sont pas seules. Iyo Sky arrive.<\/p>\n\n\n\n<p>Les quatre catcheuses montent sur le ring devant le clan de Liv Morgan. Morgan dit que c&rsquo;est bien cool d&rsquo;avoir Iyo Sky mais il leur manque toujours quelqu&rsquo;un. Elles sont cinq contre quatre et elle sait que surement personne en coulisses ne voudra faire \u00e9quipe avec elles. Morgan demande qui veut s&rsquo;essayer la premi\u00e8re ?<strong>&nbsp;<\/strong><\/p>\n\n\n\n<p>Ripley fait son entr\u00e9e en courant vers avec un masque protecteur au visage.&nbsp;Ripley arrive face \u00e0 face avec Morgan et sa bande et hurle \u00a0\u00bb<strong>WarGames<\/strong>\u00a0\u00bb et porte un coup de t\u00eate \u00e0 Morgan. L&rsquo;affrontement \u00e9clate entre les deux clans sur le ring.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de SmackDown vendredi dernier avec la Bloodline et Bronson Reed.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, on pr\u00e9sente une vid\u00e9o sur l&rsquo;annonce de Travis Scott qui&nbsp;fera la chanson th\u00eame du WWE Monday Night RAW pour Netflix.<\/p>\n\n\n\n<p><strong>Mixed Tag Team Match<\/strong><br>Zelina Vega et Rey Mysterio vs Ivy Nile et Chad Gable<\/p>\n\n\n\n<p>En fin de match, Mysterio lance Vega sur Gable pour qu&rsquo;elle fasse un Rana du coin \u00e0 Gable. Vega repousse Nile en bas du ring. Mysterio enchaine avec un Springboard Moonsault et couvre Gable, mais il r\u00e9siste. Mysterio repousse Gable sur la deuxi\u00e8me corde et lui fait un 619 pour compl\u00e9ter avec un Splash pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Zelina Vega et&nbsp;Rey Mysterio<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, les Creed Brothers viennent sur le ring pour soutenir Gable, mais Gable repousse les Creed. Gable dit qu&rsquo;il n&rsquo;est pas un perdant comme eux, est-ce le cas ? Les Creed commencent \u00e0 se bousculer pour se motiver et se donner de l&rsquo;\u00e9nergie. Gable dit que c&rsquo;est ce qu&rsquo;il cherche comme \u00e9nergie. American Made c\u00e9l\u00e8bre ensemble sur le ring.<\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve le Judgment Day. Finn Balor dit \u00e0 Morgan que tout ira bien avec Ripley, Belair, Cargill et Sky. Il peut prendre la direction de l&rsquo;\u00e9quipe pour ce soir si \u00e7a peut aider. Morgan approuve. Balor dit que Dominik Mysterio a battu Damian Priest en main event de RAW, maintenant Carlito et Dominik vont montrer aux WarRaiders ce que le Judgment Day est capable de faire. Il connait les WarRaiders depuis longtemps, leur faiblesse est le cou. Ils devraient cibler le cou, ou bien \u00e7a va frustrer les WarRaiders et ils seront encore plus dangereux. JD McDonagh quitte avec Balor car il veut discuter avec lui.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisses, on retrouve le&nbsp;<strong>Miz<\/strong> qui dit que les derni\u00e8res semaines \u00e9taient pleines d&rsquo;\u00e9motions. Apr\u00e8s avoir r\u00e9fl\u00e9chi, il a pris son choix. Il m\u00e9rite un troph\u00e9e pour avoir jou\u00e9 ce r\u00f4le de trahison sur les Wyatt Sicks. C&rsquo;est impossible de le changer comme les Wyatt Sicks croyaient. <\/p>\n\n\n\n<p>Karrion Kross ajoute que les Wyatt Sicks ne sont pas invincibles et on l&rsquo;a vu. Kross dit qu&rsquo;il n&rsquo;a pas peur et on va continuer de jouer le jeu qu&rsquo;il contr\u00f4le.<\/p>\n\n\n\n<p>&#8211; En coulisses, Ludwig Kaiser demande \u00e0 Gunther pourquoi il a fait \u00e7a lundi dernier.&nbsp;Gunther dit que c&rsquo;est le moment pour Kaiser de se faire un nom et de parler pour lui-m\u00eame.&nbsp;\u00c0 partir de maintenant, Kaiser doit se tenir comme un homme unique. <\/p>\n\n\n\n<p>Kaiser r\u00e9plique qu&rsquo;il comprend. Gunther l&rsquo;arr\u00eate et demande s&rsquo;il voit toujours l&rsquo;ancien Ring General. Kaiser dit que rien n&rsquo;a chang\u00e9, ile le voit encore \u00e0 100%. Gunther dit que c&rsquo;est impossible de l&rsquo;affecter, le dossier Damian Priest est r\u00e9gl\u00e9. Kaiser lui serre la main et quitte.<\/p>\n\n\n\n<p>Gunther marche plus loin et applique un Sleeper sur Damian Priest qui \u00e9tait de dos. Priest arrive \u00e0 le repousser et le frappe dans le ventre. Priest dit que sur le ring Gunther est peut-\u00eatre le Ring General, mais dans la rue c&rsquo;est lui le roi. Adam Pearce lui demande ce qui se passe. Priest dit que son champion a besoin d&rsquo;un peu de glace.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/11\/18\/deuxieme-heure-de-raw-135\/\">Pour la suite de RAW, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"1hfuotXCEA\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/11\/18\/deuxieme-heure-de-raw-135\/\">Deuxi\u00e8me heure de RAW!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Deuxi\u00e8me heure de RAW!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/11\/18\/deuxieme-heure-de-raw-135\/embed\/#?secret=uSspk3vM95#?secret=1hfuotXCEA\" data-secret=\"1hfuotXCEA\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE RAW Grand Rapids, Michigan, 18 novembreLes commentateurs sont Joe Tessitore et Wade Barrett. &#8211; Le WWE Monday Night RAW, le show rouge d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue et on voit les WWE Superstars arriver \u00e0 l&rsquo;ar\u00e9na de la ville et non \u00e0 la salle paroissiale o\u00f9 Mattias et Atoinne vont&#8230;<\/p>\n","protected":false},"author":4,"featured_media":107593,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,21,23],"tags":[],"ppma_author":[292],"class_list":["post-107571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe","category-resultats","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/107571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=107571"}],"version-history":[{"count":6,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/107571\/revisions"}],"predecessor-version":[{"id":107631,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/107571\/revisions\/107631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/107593"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=107571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=107571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=107571"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=107571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}