{"id":107465,"date":"2024-11-15T13:55:56","date_gmt":"2024-11-15T18:55:56","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=107465"},"modified":"2024-11-15T13:58:24","modified_gmt":"2024-11-15T18:58:24","slug":"du-nouveau-concernant-une-premiere-apparition-pour-beckly-lynch-et-la-possible-date-de-son-retour-sky-blue-en-rhabilitation-kouki-amarei-premiere-championne-ghc-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/11\/15\/du-nouveau-concernant-une-premiere-apparition-pour-beckly-lynch-et-la-possible-date-de-son-retour-sky-blue-en-rhabilitation-kouki-amarei-premiere-championne-ghc-et-plus\/","title":{"rendered":"Du nouveau concernant une premi\u00e8re apparition pour Beckly Lynch et la possible date de son retour! Sky Blue en rhabilitation \/ Kouki Amarei premi\u00e8re championne GHC, Nouvelles Four Horsewomen, et plus !"},"content":{"rendered":"\n<p><strong>La Pro Wrestling NOAH a sacr\u00e9 sa premi\u00e8re championne GHC ce lundi lors du show Magic Monday.<\/strong><\/p>\n\n\n\n<p>La promotion japonaise avait r\u00e9cemment annonc\u00e9\u00a0l\u2019introduction d\u2019un championnat f\u00e9minin GHC. Pour d\u00e9signer la premi\u00e8re championne, c\u2019est une simple bataille royale qui a eu lieu ce lundi \u00e0 Magic Monday.<\/p>\n\n\n\n<p>Une bataille royale dans laquelle on pouvait retrouver Chigusa Nagayo, Utami Hayashishita, Takumi Iroha, Bozilla, Yuu, Miyuki Takase, Miku Aono, Great Sakuya, Nightshade et Sadie Gibbs, et remport\u00e9e par la catcheuse de la\u00a0Marigold\u00a0Kouki Amarei apr\u00e8s avoir \u00e9limin\u00e9 en dernier Sadie Gibbs.<\/p>\n\n\n\n<p>Kouki Amarei est une ancienne danseuse classique de 27 ans ; elle a d\u00e9but\u00e9 le catch en 2022 et a rejoint la promotion de Rossy Ogawa \u00e0 sa fondation en d\u00e9but d\u2019ann\u00e9e.<\/p>\n\n\n\n<p>Voici ce qu&rsquo;d\u00e9clar\u00e9 Amarei apr\u00e8s le show:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab\u00a0J\u2019ai gagn\u00e9 cette ceinture en solo. Le Royal Rumble \u00e9tait un format un peu inhabituel, mais c\u2019est moi qui suis rest\u00e9 \u00e0 la fin et qui porte cette ceinture. Avec cette ceinture, je vais continuer \u00e0 progresser\u00a0\u00bb<\/em><\/p>\n<\/blockquote>\n\n\n\n<center><blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"en\" dir=\"ltr\"> <a href=\"https:\/\/twitter.com\/xX_0Kouki0_Xx?ref_src=twsrc%5Etfw\">@xX_0Kouki0_Xx<\/a> MAKES HISTORY AS THE 1ST GHC WOMEN\u2019S CHAMPION!<br><br>Congratulations Kouki Amarei!<a href=\"https:\/\/twitter.com\/hashtag\/noah_ghc?src=hash&amp;ref_src=twsrc%5Etfw\">#noah_ghc<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/MONDAYMAGIC?src=hash&amp;ref_src=twsrc%5Etfw\">#MONDAYMAGIC<\/a> <a href=\"https:\/\/twitter.com\/Marigold_Joshi?ref_src=twsrc%5Etfw\">@Marigold_Joshi<\/a> <a href=\"https:\/\/twitter.com\/DSF_Marigold?ref_src=twsrc%5Etfw\">@DSF_Marigold<\/a> <a href=\"https:\/\/t.co\/ARVzoXWrkl\">pic.twitter.com\/ARVzoXWrkl<\/a><\/p>&mdash; PRO WRESTLING NOAH GLOBAL (@noahglobal) <a href=\"https:\/\/twitter.com\/noahglobal\/status\/1855941277432639646?ref_src=twsrc%5Etfw\">November 11, 2024<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<p>Vous le savez, Becky Lynch est absente de la WWE depuis sa fin de contrat, le premier juin 2024. La catcheuse a simplement voulu prendre une pause et\u00a0reste en bons termes avec la WWE. Malgr\u00e9 qu&rsquo;il n&rsquo;y a pas d&rsquo;entente officielle, The Man est toujours rest\u00e9 sur la page du <a href=\"https:\/\/www.wwe.com\/superstars\/becky-lynch\" target=\"_blank\" rel=\"noreferrer noopener\">Roster de la WWE<\/a>.<\/p>\n\n\n\n<p>Plusieurs mois plus tard, le retour de Becky Lynch se pr\u00e9cise ! D&rsquo;apr\u00e8s PWinsider, des sources au sein de la WWE et Netflix s&rsquo;attendent \u00e0\u00a0revoir Becky Lynch aux alentours du premier WWE Monday Night RAW sur Netflix, pr\u00e9vu pour le 6 janvier 2025. Cela voudrait donc dire que Becky Lynch auraient ou seraient sur le point de signer un nouveau contrat car comme mentionn\u00e9, il n&rsquo;a jamais \u00e9t\u00e9 claire si elle prenait un simple cong\u00e9 avec une entente d\u00e9j\u00e0 pr\u00eate pour un retour \u00e9ventuelle. Rollins a d&rsquo;ailleurs eut des vacances plus longue que pr\u00e9vu cette \u00e9t\u00e9 pour passer du temps en famille, ensemble avec leur enfant. <\/p>\n\n\n\n<p>Ce week-end,\u00a0Becky Lynch\u00a0fera sa premi\u00e8re apparition publique depuis son d\u00e9part de la WWE afin de parler de son livre. Certaines personnes s&rsquo;attendent \u00e0 voir une annonce li\u00e9e \u00e0 la WWE dans le week-end.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Bless\u00e9e \u00e0 la cheville lors d&rsquo;un match \u00e0 AEW Collision le 20 juillet 2024, Skye Blue est toujours absente des shows aujourd&rsquo;hui.<\/p>\n\n\n\n<p>Apr\u00e8s avoir subi une op\u00e9ration cet \u00e9t\u00e9, son retour ne semble pas imminent. En effet, Fightful a fait le point sur l&rsquo;absence de Skye Blue et affirme qu&rsquo;elle restera encore sur la touche quelque temps avant son retour.<\/p>\n\n\n\n<p>N\u00e9anmoins, la catcheuse de la AEW a r\u00e9cemment particip\u00e9 \u00e0 des s\u00e9ances de d\u00e9dicaces de la compagnie.<\/p>\n\n\n\n<p>Le dernier match en date de Skye Blye :<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/qSFSHRb6HZo?si=y5cSD_yOlT7wWd7U\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n\n\n\n<p>Il y a de nouvelles Four Horsewomen sur la sc\u00e8ne de WWE NXT.<\/p>\n\n\n\n<p>Les Four Horsewomen originales du MMA, Ronda Rousey, Shayna Baszler, Marina Shafir et Jessamyn Duke, ont donn\u00e9 naissance \u00e0 une version de lutte professionnelle dans les premiers jours de WWE NXT, compos\u00e9e de Charlotte Flair, Sasha Banks, Becky Lynch et Bayley.<\/p>\n\n\n\n<p>Lors d\u2019une r\u00e9cente apparition sur le podcast In The Kliq, l\u2019actuelle championne f\u00e9minine de WWE NXT, Roxanne Perez, s\u2019est nomm\u00e9e elle-m\u00eame, Cora Jade, Giulia et Stephanie Vaquer, comme la nouvelle version moderne des Four Horsewomen dans WWE NXT.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab&nbsp;J\u2019ai donc vu un post \u00e0 ce sujet l\u2019autre jour, et je suis tout \u00e0 fait d\u2019accord avec \u00e7a&nbsp;\u00bb, a d\u00e9clar\u00e9 Perez. \u00ab Ce serait moi, Cora Jade, Stephanie Vaquer et Giulia. \u00bb<\/p>\n\n\n\n<p>\u00ab\u00a0J\u2019ai l\u2019impression que nous nous ressemblons un peu de diff\u00e9rentes mani\u00e8res, de la m\u00eame mani\u00e8re que nous avons toujours voulu faire partie de la WWE depuis que nous sommes jeunes, nous avons mis ces ann\u00e9es, ces 1 000 heures pour devenir grands, et maintenant nous sommes capables de faire partie de la plus grande division f\u00e9minine du monde. et je pense que cela a beaucoup \u00e0 voir avec nous quatre femmes.<\/p>\n<\/blockquote>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/1DehPMVY1DU?si=DVpyxH4_sA8aCg0j\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La Pro Wrestling NOAH a sacr\u00e9 sa premi\u00e8re championne GHC ce lundi lors du show Magic Monday. La promotion japonaise avait r\u00e9cemment annonc\u00e9\u00a0l\u2019introduction d\u2019un championnat f\u00e9minin GHC. Pour d\u00e9signer la premi\u00e8re championne, c\u2019est une simple bataille royale qui a eu lieu ce lundi \u00e0 Magic Monday. Une bataille royale dans laquelle on pouvait retrouver Chigusa&#8230;<\/p>\n","protected":false},"author":609,"featured_media":107467,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,22,4,23],"tags":[],"ppma_author":[295],"class_list":["post-107465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-indy","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/107465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=107465"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/107465\/revisions"}],"predecessor-version":[{"id":107471,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/107465\/revisions\/107471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/107467"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=107465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=107465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=107465"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=107465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}