{"id":107386,"date":"2024-11-13T00:45:00","date_gmt":"2024-11-13T05:45:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=107386"},"modified":"2024-11-13T12:45:44","modified_gmt":"2024-11-13T17:45:44","slug":"francine-a-refuser-detre-arbitre-lors-du-nxt-a-la-2300-arena-elle-explique-pourquoi-elle-ne-la-pas-fait","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/11\/13\/francine-a-refuser-detre-arbitre-lors-du-nxt-a-la-2300-arena-elle-explique-pourquoi-elle-ne-la-pas-fait\/","title":{"rendered":"Francine a refuser d&rsquo;\u00eatre arbitre lors du NXT \u00e0 la 2300 Arena. Elle explique pourquoi elle ne l\u2019a pas fait!"},"content":{"rendered":"\n<p>Francine a fait une apparition dans l\u2019\u00e9pisode de WWE NXT du 6 novembre depuis la 2300 Arena (ECW Arena) \u00e0 Philadelphie, Pennsylvanie. Elle a rejoint Bubba Ray Dudley, D-Von Dudley, Rob Van Dam, Dawn Marie, Rhyno, Little Guido et d\u2019autres en tant qu\u2019ECW Originals qui sont apparus dans l\u2019\u00e9mission.<\/p>\n\n\n\n<p>Bien que Francine n\u2019apparaisse que dans la foule, d\u2019autres id\u00e9es lui sont propos\u00e9es.<\/p>\n\n\n\n<p>Au cours de la derni\u00e8re \u00e9dition de son podcast \u00ab&nbsp;Eyes Up Here&nbsp;\u00bb, Francine a d\u00e9clar\u00e9 qu\u2019elle avait re\u00e7u un appel de John Cone le 17 octobre concernant une \u00e9ventuelle apparition dans l\u2019\u00e9mission. Elle a dit :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Salut Francine, c\u2019est John Cone de WWE Talent Relations. Nous nous sommes crois\u00e9s en 2006 quand j\u2019\u00e9tais arbitre pour la relance de la ECW. J\u2019ai quelque chose que je veux faire passer par vous si vous avez une minute. NXT pr\u00e9sentera un show au ECW Arena. Nous aimerions savoir si vous seriez disponible pour \u00eatre l\u2019arbitre invit\u00e9 sp\u00e9cial pour l\u2019un des matchs ? Ce serait avec les talents de NXT Jaida Parker et Lola Vice.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Francine dit qu\u2019elle a dit \u00e0 Cone qu\u2019elle voulait d\u2019abord parler de choses \u00e0 son mari. Elle a d\u00e9clar\u00e9 :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab J\u2019ai ensuite parl\u00e9 \u00e0 mon mari et il m\u2019a dit : \u00ab\u00a0<em>N&rsquo;as tu pas oubli\u00e9 les cinq op\u00e9rations que vous avez subies sur votre abdomen ?<\/em>\u00a0\u00bb \u00ab <em>Eh bien, oui<\/em>. \u00bb \u00ab\u00a0<em>Penses-tu vraiment que tu peux \u00eatre assez rapide avec la fa\u00e7on dont ces filles travaillent.\u00a0<\/em>\u00bb <\/p>\n\n\n\n<p>Ces filles sont bonnes et elles peuvent travailler. \u00ab <em>Penses-tu que tu peux te mettre \u00e0 terre, obtenir les fausses finitions et courir partout ?<\/em> \u00bb J\u2019\u00e9tais comme, pour moi, parce que mon c\u0153ur est si faible, juste me lever pour monter sur le ring est lent. Je me suis dit : \u00ab\u00a0<em>Je suppose que je ne vais pas pouvoir le faire.\u00a0<\/em>\u00bb <\/p>\n\n\n\n<p>J\u2019ai contact\u00e9 John le lendemain et je lui ai expliqu\u00e9 ce qui \u00e9tait arriv\u00e9 \u00e0 mon estomac. Il a \u00e9crit : <em>\u00ab\u00a0Pas de probl\u00e8me. Nous pouvons faire quelque chose de diff\u00e9rent. Permettez-moi de parler \u00e0 la cr\u00e9ation et de revenir vers vous.<\/em>\u00ab\u00a0<\/p>\n<\/blockquote>\n\n\n\n<p>Comme beaucoup d\u2019entre vous le savent, Dawn Marie a fini par \u00eatre l\u2019arbitre invit\u00e9e sp\u00e9ciale pour le match Lola Vice contre Jaida Parker.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab J\u2019ai eu l\u2019id\u00e9e de devenir chronom\u00e9treur invit\u00e9. J\u2019ai pens\u00e9 \u00e0 un endroit que je pourrais faire avec l\u2019un des gars sur la carte. Il a dit : \u00ab\u00a0<em>Merci pour la suggestion, je vais l\u2019envoyer \u00e0 la cr\u00e9ation.<\/em>\u00a0\u00bb Puis je re\u00e7ois un texto le mardi suivant, c\u2019\u00e9tait la veille, je n\u2019avais rien entendu depuis deux semaines et je me disais : \u00ab<em>\u00a0Je suis r\u00e9serv\u00e9, je pense, mais je n\u2019ai aucune id\u00e9e de ce que je fais.<\/em>\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Le mardi, ils m\u2019envoient un script pour \u00eatre un intervieweur en coulisses. Je me dis : \u00ab\u00a0<em>Ah, je ne peux pas faire \u00e7a.<\/em>\u00a0\u00bb Ma voix est tir\u00e9e. C\u2019\u00e9tait mauvais. Il m\u2019a dit : &lsquo;<em>Est-ce que Johnny Russo est venu avec toi pour demain ?<\/em>&lsquo; J\u2019ai dit : \u00ab Je n\u2019ai pas eu de nouvelles de lui, on ne m\u2019a pas contact\u00e9 depuis la semaine derni\u00e8re, je ne sais rien de demain. \u00bb C\u2019\u00e9tait \u00e0 neuf heures la veille \u00bb<\/p>\n\n\n\n<p> \u00ab\u00a0Johnny Russo m\u2019envoie un texto \u00e0 10 heures avec le script pour les coulisses. Je r\u00e9ponds : \u00ab\u00a0Johnny, j\u2019ai tellement honte de dire \u00e7a. Je n\u2019ai pas de voix. Je n\u2019ai pas de voix. \u00c7a n\u2019allait tout simplement pas marcher. Je dis litt\u00e9ralement : \u00ab\u00a0<em>Si vous voulez me retirer de la s\u00e9rie, je comprends parfaitement. Pas de chaleur. C\u2019est de ma faute. Je ne peux pas travailler comme ils le veulent, je ne peux pas parler, qu\u2019est-ce que je vais faire ?<\/em>\u00a0\u00bb Quelques gar\u00e7ons m\u2019ont dit : \u00ab\u00a0Tu peux t\u2019asseoir au premier rang. C\u2019est ce qu\u2019ils font avec beaucoup de l\u00e9gendes. J\u2019ai dit : \u00ab <em>Veux-tu quand m\u00eame que je vienne m\u00eame si je ne peux pas parler ? <\/em>\u00bb <\/p>\n\n\n\n<p>Il m\u2019a dit : \u00ab\u00a0<em>On trouvera une solution demain. Voyons comment vous en \u00eates le matin et partons de l\u00e0. Nous pourrions vous faire asseoir dans la foule ou \u00eatre un chronom\u00e9treur. Nous ferons en sorte que cela fonctionne, ne vous inqui\u00e9tez pas<\/em>\u00ab\u00a0.<\/p>\n\n\n\n<p> J\u2019ai propos\u00e9 de rester \u00e0 la maison, mais \u00e0 ce moment-l\u00e0, ils ont fait l\u2019ouverture et ils m\u2019ont mis \u00e0 l\u2019ouverture du spectacle. Je suppose qu\u2019il \u00e9tait trop tard pour me tirer, ou qu\u2019ils pensaient que je devrais \u00eatre l\u00e0, ce que j\u2019ai appr\u00e9ci\u00e9.<\/p>\n<\/blockquote>\n\n\n\n<p>Enfin, Francine a not\u00e9 qu\u2019elle s\u2019attendait \u00e0 entendre son nom annonc\u00e9 dans l\u2019ar\u00e8ne, mais ce n\u2019\u00e9tait pas le cas. Elle a d\u00e9clar\u00e9 :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab En regardant les r\u00e9seaux sociaux et en voyant certains des fans de la vieille \u00e9cole en col\u00e8re et en disant : \u00ab\u00a0Ils auraient pu faire quelque chose de plus avec toi que de te coincer dans la foule.\u00a0\u00bb Oui, ils auraient pu, mais c\u2019est moi qui n\u2019ai pas pu le faire. Je voulais juste que ce soit parfaitement clair. Aurais-je aim\u00e9 en faire plus ? Bien s\u00fbr. J\u2019aurais ador\u00e9 avoir une entr\u00e9e, marcher jusqu\u2019au ring et faire quelque chose. Ce n\u2019\u00e9tait tout simplement pas dans les cartes pour moi. Le simple fait d\u2019\u00eatre inclus me suffisait. Je n\u2019avais besoin de rien de plus que \u00e7a.<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"1mHazb8ioz\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/11\/06\/resultats-et-video-pour-le-wwe-nxt-du-6-novembre-2024\/\">R\u00e9sultats et Vid\u00e9o pour le WWE NXT du 6 Novembre 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le WWE NXT du 6 Novembre 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/11\/06\/resultats-et-video-pour-le-wwe-nxt-du-6-novembre-2024\/embed\/#?secret=FvulMZqjcN#?secret=1mHazb8ioz\" data-secret=\"1mHazb8ioz\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Francine a fait une apparition dans l\u2019\u00e9pisode de WWE NXT du 6 novembre depuis la 2300 Arena (ECW Arena) \u00e0 Philadelphie, Pennsylvanie. Elle a rejoint Bubba Ray Dudley, D-Von Dudley, Rob Van Dam, Dawn Marie, Rhyno, Little Guido et d\u2019autres en tant qu\u2019ECW Originals qui sont apparus dans l\u2019\u00e9mission. Bien que Francine n\u2019apparaisse que dans&#8230;<\/p>\n","protected":false},"author":665,"featured_media":107436,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84,30,4,85,23],"tags":[],"ppma_author":[289],"class_list":["post-107386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecw","category-ex-wwe","category-news","category-nxt","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/107386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=107386"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/107386\/revisions"}],"predecessor-version":[{"id":107437,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/107386\/revisions\/107437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/107436"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=107386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=107386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=107386"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=107386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}