{"id":106928,"date":"2024-11-03T14:30:22","date_gmt":"2024-11-03T19:30:22","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=106928"},"modified":"2024-11-03T14:30:24","modified_gmt":"2024-11-03T19:30:24","slug":"goldberg-annonce-son-intention-de-prendre-sa-retraite-en-2025","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/11\/03\/goldberg-annonce-son-intention-de-prendre-sa-retraite-en-2025\/","title":{"rendered":"Goldberg annonce son intention de prendre sa retraite en 2025"},"content":{"rendered":"\n<p>Goldberg prendra sa retraite en 2025.<\/p>\n\n\n\n<p>Alors qu\u2019il faisait une apparition sur le r\u00e9seau SEC avant le match de football universitaire d\u2019aujourd\u2019hui entre les Florida Gators et les Georgia Bulldogs, le WWE Hall of Famer a annonc\u00e9 son intention de prendre sa retraite \u00e0 un moment donn\u00e9 l\u2019ann\u00e9e prochaine. Dire<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab&nbsp;Je pense que nous savons qui est le sujet ou la victime, le favori en ce moment, nous savons qui c\u2019est.&nbsp;\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Bien s\u00fbr, il s\u2019agit d\u2019une r\u00e9f\u00e9rence \u00e0 GUNTHER, qui s\u2019est r\u00e9cemment lanc\u00e9 avec \u00ab&nbsp;Da Man&nbsp;\u00bb lors de l\u2019\u00e9v\u00e9nement pay-per-view WWE Bad Blood 2024.<\/p>\n\n\n\n<p>Goldberg a ajout\u00e9 que Triple H, Nick Khan et Chris Legentil ont tous sign\u00e9 le match.<\/p>\n\n\n\n<p>Au moment d\u2019\u00e9crire ces lignes, on ne sait pas exactement quand l\u2019ann\u00e9e prochaine le match de retraite aura lieu.<\/p>\n\n\n\n<p>Vous pouvez consulter l\u2019annonce ci-dessous :<\/p>\n\n\n\n<p>Le dernier match de Goldberg a eu lieu lors de l\u2019\u00e9v\u00e9nement pay-per-view WWE Elimination Chamber 2022, o\u00f9 il a perdu contre Roman Reigns.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"en\" dir=\"ltr\"> BREAKING: <a href=\"https:\/\/twitter.com\/Goldberg?ref_src=twsrc%5Etfw\">@Goldberg<\/a> just announced that his retirement match will take place NEXT YEAR! <br><br>: <a href=\"https:\/\/twitter.com\/SECNetwork?ref_src=twsrc%5Etfw\">@SECNetwork<\/a> <a href=\"https:\/\/t.co\/e5KtwfOGnY\">pic.twitter.com\/e5KtwfOGnY<\/a><\/p>&mdash; WWE (@WWE) <a href=\"https:\/\/twitter.com\/WWE\/status\/1852758243824574544?ref_src=twsrc%5Etfw\">November 2, 2024<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Goldberg prendra sa retraite en 2025. Alors qu\u2019il faisait une apparition sur le r\u00e9seau SEC avant le match de football universitaire d\u2019aujourd\u2019hui entre les Florida Gators et les Georgia Bulldogs, le WWE Hall of Famer a annonc\u00e9 son intention de prendre sa retraite \u00e0 un moment donn\u00e9 l\u2019ann\u00e9e prochaine. Dire \u00ab&nbsp;Je pense que nous savons&#8230;<\/p>\n","protected":false},"author":665,"featured_media":107005,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81,4,45,42,23],"tags":[],"ppma_author":[289],"class_list":["post-106928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crown-jewel","category-news","category-ppv-wwe","category-wrestlemania","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=106928"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106928\/revisions"}],"predecessor-version":[{"id":107006,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106928\/revisions\/107006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/107005"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=106928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=106928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=106928"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=106928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}