{"id":106452,"date":"2024-10-26T15:16:00","date_gmt":"2024-10-26T19:16:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=106452"},"modified":"2024-10-31T17:01:18","modified_gmt":"2024-10-31T21:01:18","slug":"joe-hendry-invite-stone-cold-steve-austin-a-apparaitre-a-la-tna-bound-for-glory-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/10\/26\/joe-hendry-invite-stone-cold-steve-austin-a-apparaitre-a-la-tna-bound-for-glory-2024\/","title":{"rendered":"Joe Hendry invite \u00ab\u00a0Stone Cold\u00a0\u00bb Steve Austin \u00e0 appara\u00eetre \u00e0 la TNA Bound For Glory 2024"},"content":{"rendered":"\n<p>Joe Hendry s\u2019adresse \u00e0 toutes sortes de grands noms pour appara\u00eetre en tant qu\u2019invit\u00e9 au plus grand show de lutte de la TNA de l\u2019ann\u00e9e.<\/p>\n\n\n\n<p>Avant le TNA Bound For Glory 2024 le samedi soir 26 octobre au Wayne State Fieldhouse de Detroit, dans le Michigan, Hendry a invit\u00e9 la l\u00e9gende du hip-hop Eminem et la l\u00e9gende du catch professionnel \u00ab&nbsp;Stone Cold&nbsp;\u00bb Steve Austin.<\/p>\n\n\n\n<p>Lors d\u2019une interview avec TheOneMonaa pour promouvoir l\u2019\u00e9v\u00e9nement PPV 10\/26, Hendry a invit\u00e9 \u00ab&nbsp;The Texas Rattlesnake&nbsp;\u00bb \u00e0 appara\u00eetre \u00e0 TNA Bound For Glory 2024 ce week-end.<\/p>\n\n\n\n<p>\u00ab\u00a0Donc, pour le contexte, j\u2019ai demand\u00e9 \u00e0 Mick Foley : &lsquo;As-tu des conseils pour devenir champion du monde TNA ?&rsquo; Il dit : \u00ab&nbsp;Tout ce que vous avez \u00e0 faire, c\u2019est de vous assurer que vous avez Steve Austin pr\u00eat \u00e0 casser quelqu\u2019un avec une chaise.&nbsp;\u00bb Je me suis dit : &lsquo;Mick, c\u2019est tout ce que j\u2019avais \u00e0 faire ?! Pourquoi personne ne me l\u2019a dit ?<\/p>\n\n\n\n<p>Hendry a poursuivi : \u00ab\u00a0Donc, vous savez, j\u2019ai d\u00e9j\u00e0 invit\u00e9 Eminem \u00e0 l\u2019\u00e9mission. J\u2019interpelle John Cena depuis environ un an. J\u2019ai dit que je voulais une confrontation avec The Rock. Autant ajouter Steve Austin.<\/p>\n\n\n\n<p>\u00c0 partir de l\u00e0, il a fait l\u2019invitation officielle \u00e0 la l\u00e9gende du WWE Hall of Fame pour faire ce qui serait sa toute premi\u00e8re apparition \u00e0 la TNA Wrestling.<\/p>\n\n\n\n<p>\u00ab Steve, si vous regardez et que vous avez un moyen de vous rendre \u00e0 Detroit pour m\u2019aider ici \u00bb, a-t-il dit. \u00ab\u00a0J\u2019esp\u00e8re qu\u2019Eminem va \u00eatre de mon c\u00f4t\u00e9. Mais si vous avez Eminem d\u2019un c\u00f4t\u00e9 et &lsquo;Stone Cold&rsquo; Steve Austin de l\u2019autre, alors je ne pense pas que nous devions trop nous inqui\u00e9ter de Frankie Kazarian.<\/p>\n\n\n\n<p>Joe Hendry d\u00e9fie Nic Nemeth pour le championnat du monde de la TNA, avec Frankie Kazarian comme arbitre invit\u00e9 sp\u00e9cial, lors du main event de TNA Bound For Glory 2024 le 26 octobre au Wayne State Fieldhouse \u00e0 Detroit, MI.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Joe Hendry s\u2019adresse \u00e0 toutes sortes de grands noms pour appara\u00eetre en tant qu\u2019invit\u00e9 au plus grand show de lutte de la TNA de l\u2019ann\u00e9e. Avant le TNA Bound For Glory 2024 le samedi soir 26 octobre au Wayne State Fieldhouse de Detroit, dans le Michigan, Hendry a invit\u00e9 la l\u00e9gende du hip-hop Eminem et&#8230;<\/p>\n","protected":false},"author":665,"featured_media":106851,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,64,30,77,41],"tags":[],"ppma_author":[289],"class_list":["post-106452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-bound-for-glory","category-ex-wwe","category-hall-of-fame","category-tna-impact"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=106452"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106452\/revisions"}],"predecessor-version":[{"id":106853,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106452\/revisions\/106853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/106851"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=106452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=106452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=106452"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=106452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}