{"id":106186,"date":"2024-10-21T10:03:00","date_gmt":"2024-10-21T14:03:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=106186"},"modified":"2024-10-21T14:16:06","modified_gmt":"2024-10-21T18:16:06","slug":"cody-rhodes-explique-ou-il-considere-quil-est-letoile-polaire-de-lindustrie-pour-la-lutte-professionnelle","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/10\/21\/cody-rhodes-explique-ou-il-considere-quil-est-letoile-polaire-de-lindustrie-pour-la-lutte-professionnelle\/","title":{"rendered":"Cody Rhodes explique o\u00f9 il consid\u00e8re qu\u2019il est \u00ab\u00a0l\u2019\u00e9toile polaire de l\u2019industrie\u00a0\u00bb pour la lutte professionnelle !"},"content":{"rendered":"\n<p>Les Carolines ont une grande importance pour Cody Rhodes.<\/p>\n\n\n\n<p>C\u2019est quelque chose de sp\u00e9cial pour lui.<\/p>\n\n\n\n<p>\u00ab&nbsp;The American Nightmare&nbsp;\u00bb en a parl\u00e9 lors d\u2019une r\u00e9cente interview sur WLTX pour promouvoir l\u2019\u00e9pisode du 18 octobre de WWE SmackDown plus t\u00f4t cette semaine.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab&nbsp;Mais pour moi, Jim Crockett Promotions, mon p\u00e8re, quand il luttait et quand il produisait, \u00e9tait tous ici dans les Carolines et en G\u00e9orgie dans cette r\u00e9gion&nbsp;\u00bb<\/p>\n\n\n\n<p>\u00ab Donc, m\u00eame si j\u2019essaie de traiter chaque endroit comme si c\u2019\u00e9tait ma maison, et c\u2019est ce que je fais, il y a une diff\u00e9rence entre quand vous \u00eates vraiment pr\u00e8s de chez vous, en fait. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Il y a quelque chose de sp\u00e9cial \u00e0 \u00eatre dans les Carolines, \u00e0 \u00eatre un Rhodes et \u00e0 avoir ce que nous consid\u00e9rerions comme l\u2019\u00e9toile polaire de l\u2019industrie, ce qui est inattendu. Je n\u2019aurais jamais pens\u00e9 que cela arriverait et maintenant c\u2019est tout simplement la meilleure chose de pouvoir l\u2019emmener dans chacune de ces villes.<\/p>\n<\/blockquote>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/S4Stw959QPA?si=E7w0DZ6zMEHp2wgD\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"8Ngr9dNhBw\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/10\/19\/ladversaire-tres-probable-pour-cody-rhodes-pour-le-grand-retour-du-saterday-night-main-event-en-decembre-un-house-show-denvergure-au-madison-square-garden-de-new-york-et-plus\/\">L&rsquo;adversaire tr\u00e8s probable pour Cody Rhodes pour le grand retour du Saterday Night Main Event en d\u00e9cembre ! Un House Show d&rsquo;envergure au Madison Square Garden de New York, et plus!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0L&rsquo;adversaire tr\u00e8s probable pour Cody Rhodes pour le grand retour du Saterday Night Main Event en d\u00e9cembre ! Un House Show d&rsquo;envergure au Madison Square Garden de New York, et plus!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/10\/19\/ladversaire-tres-probable-pour-cody-rhodes-pour-le-grand-retour-du-saterday-night-main-event-en-decembre-un-house-show-denvergure-au-madison-square-garden-de-new-york-et-plus\/embed\/#?secret=nbvSIW48qX#?secret=8Ngr9dNhBw\" data-secret=\"8Ngr9dNhBw\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Les Carolines ont une grande importance pour Cody Rhodes. C\u2019est quelque chose de sp\u00e9cial pour lui. \u00ab&nbsp;The American Nightmare&nbsp;\u00bb en a parl\u00e9 lors d\u2019une r\u00e9cente interview sur WLTX pour promouvoir l\u2019\u00e9pisode du 18 octobre de WWE SmackDown plus t\u00f4t cette semaine. \u00ab&nbsp;Mais pour moi, Jim Crockett Promotions, mon p\u00e8re, quand il luttait et quand il&#8230;<\/p>\n","protected":false},"author":665,"featured_media":106198,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,36,23],"tags":[],"ppma_author":[289],"class_list":["post-106186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-smackdown","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=106186"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106186\/revisions"}],"predecessor-version":[{"id":106206,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106186\/revisions\/106206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/106198"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=106186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=106186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=106186"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=106186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}