{"id":106071,"date":"2024-10-17T19:39:00","date_gmt":"2024-10-17T23:39:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=106071"},"modified":"2024-10-20T20:05:59","modified_gmt":"2024-10-21T00:05:59","slug":"resultats-et-video-pour-le-tna-impact-wrestling-du-17-octobre-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/10\/17\/resultats-et-video-pour-le-tna-impact-wrestling-du-17-octobre-2024\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le TNA Impact Wrestling du 17 Octobre 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/10\/17\/reprise-video-pour-le-tna-impact-wrestling-du-17-octobre-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Impact, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>TNA Impact Nashville, Tennessee, diffusion du 17 octobre 2024<\/strong><br>Les commentateurs sont Matthew Rehwoldt et Tom Hannifan.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>TNA Digital Media &amp; International Heavyweight Championship<\/strong><\/p>\n\n\n\n<p><strong>Pick Your Poison Match <\/strong><br><strong>Rhino vs PCO \u00a9<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Rhino sort une table et la pose dans le coin du ring. Il s\u2019\u00e9lance vers PCO pour le faire passer \u00e0 travers, mais PCO l\u2019\u00e9vite et Rhino s\u2019\u00e9crase directement dans la table. PCO encha\u00eene avec un PCO-Sault pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant&nbsp;: PCO <\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, Gia Miller interview Nic Nemeth. Le champion est excit\u00e9 d\u2019affronter Cardona en Main Event. Il voulait mettre en jeu son titre, mais Santino Marella a refus\u00e9 car cela pourrait compromettre le match pr\u00e9vu \u00e0 Bound For Glory contre Joe Hendry. Nemeth dit qu\u2019il est pr\u00eat \u00e0 planifier un autre match pour le championnat de la TNA contre Cardona, apr\u00e8s Bound For Glory.<\/p>\n\n\n\n<p><strong>Ash by Elegance&nbsp;<em>acc du concierge personnel<\/em>&nbsp;vs Brinley Reece<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, le concierge personnel monte sur le tablier pour d\u00e9concentrer Brinley Reece, ce qui permet \u00e0 Ash de faire un reverse DDT, suivi de son Rarified Air pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante&nbsp;: Ash by Elegance<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, le concierge personnel annonce qu\u2019il y aura un VIP Makeover Launch Party by Elegance d\u2019organis\u00e9 la semaine prochaine. Ash by Elegance sort son rouge \u00e0 l\u00e8vre et commence \u00e0 dessiner avec sur le visage de Brinley Reece, jusqu\u2019\u00e0 ce que Xia Brookside vienne la chasser du ring.<\/p>\n\n\n\n<p>&#8211; Une vid\u00e9o promo dans laquelle Wendy Choo et Rosemary annoncent leurs cibles comme \u00e9tant Dani Luna et Jody Threat est diffus\u00e9e.<\/p>\n\n\n\n<p><strong>X-Division Championship<\/strong><br>Mike Bailey \u00a9 vs Leon Slater<\/p>\n\n\n\n<p>\u00c0 la fin du match, Bailey fait deux superkicks, suivi d\u2019un tornado kick sur Slater dans le coin. Il poursuit avec son Ultima Weapon et un Flamingo Driver pour conserver son titre.<\/p>\n\n\n\n<p><em>Gagnant&nbsp;: Mike Bailey<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, Slater serre la main du champion, qui le f\u00e9licite pour sa combativit\u00e9. Il est annonc\u00e9 que&nbsp;Bailey d\u00e9fendra le championnat X-Division contre El Hijo del Vikingo \u00e0 Bound For Glory&nbsp;!<\/p>\n\n\n\n<p>&#8211; En coulisses, ABC et les Hardys parlent du 8-Tag Team Match qui les attend contre le System la semaine prochaine. Matt Hardy dit qu\u2019ils sont sur la m\u00eame page, mais \u00e0 Bound For Glory, ils seront comp\u00e9titeurs et iront chercher les titres par \u00e9quipe. Ace Austin \u00e9voque le fait que MCMG ne voulait pas passer le flambeau mais ABC ont d\u00fb le prendre. Malheureusement, ils vont devoir le refaire \u00e0 Bound For Glory.<\/p>\n\n\n\n<p>&#8211; Steve Maclin fait son entr\u00e9e sur le ring. Josh Alexander le rejoint avec la Northern Armory. Il s\u2019interroge sur le changement de comportement de Maclin, apr\u00e8s que ce dernier ait parl\u00e9 avec Eric Young. Personnelement, les fans lui ont tourn\u00e9 le dos, alors comment pourraient-ils croire en un \u00e9chec comme Maclin&nbsp;? Celui-ci dit qu\u2019ils n&rsquo;ont absolument rien en commun. Travis Williams et Judas Icarus encerclent Maclin, qui finit par subir une situation de trois contre un. Alexander attache les mains de Maclin dans son dos et le frappe. Il finit par lui faire un C4 Spike. Leur match est officiel pour Bound For Glory.<\/p>\n\n\n\n<p>&#8211; Alors que Myers et Santana devait s\u2019affronter, le portoricain a pr\u00e9f\u00e9r\u00e9 frapper son adversaire avec une chaine avant de faire subir le m\u00eame sort aux autres membres du System. Il fait un Spin The Block avec la cha\u00eene sur Myers puis prend le micro. Il appelle Moose, mais comme celui-ci ne vient pas, Santana va directement le chercher en coulisses. Moose arrive par derri\u00e8re et le frappe avec une batte. Il laisse Santana par terre en le pr\u00e9venant de faire attention \u00e0 ce qu\u2019il veut.<\/p>\n\n\n\n<p>&#8211; Matthew Rehwoldt pr\u00e9sente le face \u00e0 face entre Masha Slamovich et Jordynne Grace. Slamovich montre sa jalousie en reprochant \u00e0 Grace de ne jamais avoir pens\u00e9 \u00e0 elle lorsqu\u2019elle a atteint le sommet de la division Knockouts. De son c\u00f4t\u00e9, Grace admet qu\u2019elle \u00e9tait d\u00e9\u00e7ue lorsque ce n\u2019\u00e9tait pas sa musique qui r\u00e9sonnait lors des Open Challenge, parce qu\u2019affronter Slamovich est un vrai challenge pour elle. Cependant, il se passera exactement la m\u00eame chose qu\u2019il y a deux ans, elle va la battre. Slamovich dit \u00eatre d\u00e9sol\u00e9, elle aime Grace, mais elle repartira avec le titre quoi qu\u2019il en co\u00fbte.<\/p>\n\n\n\n<p>&#8211; Avant le Main Event, Frankie Kazarian s\u2019installe aux c\u00f4t\u00e9s de Hannifan \u00e0 la table des commentateurs, en remplacement de Rehwoldt. Le \u00ab&nbsp;roi de la TNA&nbsp;\u00bb d\u00e9clare qu\u2019il a un plan pour \u00eatre impliqu\u00e9 dans le match de championnat de Bound For Glory.<\/p>\n\n\n\n<p><strong>Pick Your Poison Match<\/strong><br>Nic Nemeth vs Matt Cardona<\/p>\n\n\n\n<p>\u00c0 la fin du match, Matt Cardona fait un Low Blow sur Nemeth dans le dos de l\u2019arbitre. La musique de PCO se lance et le champion Digital Media se d\u00e9barrasse de la s\u00e9curit\u00e9 sur la rampe. La distraction permet \u00e0 Nemeth de surprendre Cardona avec un Danger Zone pour la victoire&nbsp;!<\/p>\n\n\n\n<p><em>Gagnant&nbsp;: Nic Nemeth<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le match, PCO prend Cardona sur ses \u00e9paules et repart en coulisses. Frankie Kazarian quitte la table des commentateurs pour attaquer Nemeth par derri\u00e8re. Joe Hendry fait son entr\u00e9e et s\u2019allie avec le champion de la TNA pour sortir Kaz du ring. Ce dernier prend le micro et annonce qu\u2019il sera le special guest referee du Main Event de Bound For Glory entre Nemeth et Hendry !<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/10\/17\/reprise-video-pour-le-tna-impact-wrestling-du-17-octobre-2024\/\">Pour voir Impact, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"VgvXLTZBgp\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/10\/17\/reprise-video-pour-le-tna-impact-wrestling-du-17-octobre-2024\/\">Reprise Vid\u00e9o pour le TNA Impact Wrestling du 17 Octobre 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le TNA Impact Wrestling du 17 Octobre 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/10\/17\/reprise-video-pour-le-tna-impact-wrestling-du-17-octobre-2024\/embed\/#?secret=x2Uh5Wa1Rh#?secret=VgvXLTZBgp\" data-secret=\"VgvXLTZBgp\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>TNA Impact Nashville, Tennessee, diffusion du 17 octobre 2024Les commentateurs sont Matthew Rehwoldt et Tom Hannifan. TNA Digital Media &amp; International Heavyweight Championship Pick Your Poison Match Rhino vs PCO \u00a9 \u00c0 la fin du match, Rhino sort une table et la pose dans le coin du ring. Il s\u2019\u00e9lance vers PCO pour le faire&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":106072,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,84,30,93,21,41],"tags":[],"ppma_author":[297],"class_list":["post-106071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ecw","category-ex-wwe","category-nxt-ex-wwe","category-resultats","category-tna-impact"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=106071"}],"version-history":[{"count":5,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106071\/revisions"}],"predecessor-version":[{"id":106150,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106071\/revisions\/106150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/106072"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=106071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=106071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=106071"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=106071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}