{"id":106048,"date":"2024-10-17T23:55:00","date_gmt":"2024-10-18T03:55:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=106048"},"modified":"2024-10-20T20:12:33","modified_gmt":"2024-10-21T00:12:33","slug":"la-liste-complete-du-pwi-250-feminin-de-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/10\/17\/la-liste-complete-du-pwi-250-feminin-de-2024\/","title":{"rendered":"La Liste Compl\u00e8te du PWI 250 F\u00e9minin de 2024!"},"content":{"rendered":"\n<p>Cette semaine est sorti le classement annuel du PWI 250 qui regroupe les 250 meilleures catcheuses du monde selon diff\u00e9rents crit\u00e8res durant la p\u00e9riode du premier octobre 2023 au 30 septembre 2024,&nbsp;remport\u00e9 cette ann\u00e9e par Toni Storm&nbsp;pour la premi\u00e8re fois de sa carri\u00e8re.<\/p>\n\n\n\n<p>On vous propose maintenant de d\u00e9couvrir la liste compl\u00e8te de ce classement (via Reddit) :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Toni Storm&nbsp;<\/li>\n\n\n\n<li>Jordynne Grace&nbsp;<\/li>\n\n\n\n<li>Rhea Ripley&nbsp;<\/li>\n\n\n\n<li>Maika&nbsp;<\/li>\n\n\n\n<li>Stephanie Vaquer&nbsp;<\/li>\n\n\n\n<li>Sareee&nbsp;<\/li>\n\n\n\n<li>Bayley&nbsp;<\/li>\n\n\n\n<li>Willow Nightingale&nbsp;<\/li>\n\n\n\n<li>Mariah May&nbsp;<\/li>\n\n\n\n<li>Athena&nbsp;<\/li>\n\n\n\n<li>Roxanne Perez&nbsp;<\/li>\n\n\n\n<li>Liv Morgan&nbsp;<\/li>\n\n\n\n<li>Iyo Sky&nbsp;<\/li>\n\n\n\n<li>Mayu Iwatani&nbsp;<\/li>\n\n\n\n<li>Masha Slamovich&nbsp;<\/li>\n\n\n\n<li>Mina Shirakawa&nbsp;<\/li>\n\n\n\n<li>Becky Lynch&nbsp;<\/li>\n\n\n\n<li>Miu Watanabe&nbsp;<\/li>\n\n\n\n<li>Miyu Yamashita&nbsp;<\/li>\n\n\n\n<li>Lyra Valkyria&nbsp;<\/li>\n\n\n\n<li>Giulia&nbsp;<\/li>\n\n\n\n<li>Nia Jax&nbsp;<\/li>\n\n\n\n<li>Dani Luna&nbsp;<\/li>\n\n\n\n<li>Kenzie Paige&nbsp;<\/li>\n\n\n\n<li>Rhio&nbsp;<\/li>\n\n\n\n<li>Julia Hart&nbsp;<\/li>\n\n\n\n<li>Saori Anou&nbsp;<\/li>\n\n\n\n<li>Tam Nakano&nbsp;<\/li>\n\n\n\n<li>Kelani Jordan&nbsp;<\/li>\n\n\n\n<li>Naomi&nbsp;<\/li>\n\n\n\n<li>Hikaru Shida&nbsp;<\/li>\n\n\n\n<li>Tiffany Stratton&nbsp;<\/li>\n\n\n\n<li>Billie Starkz&nbsp;<\/li>\n\n\n\n<li>Bianca Belair&nbsp;<\/li>\n\n\n\n<li>Hyan&nbsp;<\/li>\n\n\n\n<li>Kris Statlander&nbsp;<\/li>\n\n\n\n<li>Janai Kai&nbsp;<\/li>\n\n\n\n<li>Mika Iwata&nbsp;<\/li>\n\n\n\n<li>Deonna Purazzo&nbsp;<\/li>\n\n\n\n<li>Natsupoi&nbsp;<\/li>\n\n\n\n<li>Megan Bayne&nbsp;<\/li>\n\n\n\n<li>Alex Windsor&nbsp;<\/li>\n\n\n\n<li>Natsuko Tora&nbsp;<\/li>\n\n\n\n<li>Jade Cargill&nbsp;<\/li>\n\n\n\n<li>Ash By Elegance&nbsp;<\/li>\n\n\n\n<li>Shayna Baszler&nbsp;<\/li>\n\n\n\n<li>Chihiro Hashimoto&nbsp;<\/li>\n\n\n\n<li>Zeuxis&nbsp;<\/li>\n\n\n\n<li>Shazza Mckenzie&nbsp;<\/li>\n\n\n\n<li>Hanan&nbsp;<\/li>\n\n\n\n<li>Red Velvet&nbsp;<\/li>\n\n\n\n<li>Nina Samuels&nbsp;<\/li>\n\n\n\n<li>Viva Van&nbsp;<\/li>\n\n\n\n<li>Skye Blue&nbsp;<\/li>\n\n\n\n<li>Queen Aminata&nbsp;<\/li>\n\n\n\n<li>Miku Aono&nbsp;<\/li>\n\n\n\n<li>Natsumi Showzuki&nbsp;<\/li>\n\n\n\n<li>Rina&nbsp;<\/li>\n\n\n\n<li>Max the Impaler&nbsp;<\/li>\n\n\n\n<li>Mei Seira<\/li>\n\n\n\n<li>Vertvixen<\/li>\n\n\n\n<li>MIRAI<\/li>\n\n\n\n<li>AZM&nbsp;<\/li>\n\n\n\n<li>Utami Hayashishita&nbsp;<\/li>\n\n\n\n<li>Thunder Rosa&nbsp;<\/li>\n\n\n\n<li>Delmi Exo&nbsp;<\/li>\n\n\n\n<li>Momo Watanabe&nbsp;<\/li>\n\n\n\n<li>Kristara&nbsp;<\/li>\n\n\n\n<li>Maki Itoh&nbsp;<\/li>\n\n\n\n<li>DELTA&nbsp;<\/li>\n\n\n\n<li>Unagi Sayaka&nbsp;<\/li>\n\n\n\n<li>Syuri&nbsp;<\/li>\n\n\n\n<li>Arianna Grace&nbsp;<\/li>\n\n\n\n<li>Asuka&nbsp;<\/li>\n\n\n\n<li>Bozilla&nbsp;<\/li>\n\n\n\n<li>Jody Threat&nbsp;<\/li>\n\n\n\n<li>Thekla&nbsp;<\/li>\n\n\n\n<li>Ava Everett&nbsp;<\/li>\n\n\n\n<li>Zoey Stark&nbsp;<\/li>\n\n\n\n<li>Takumi Iroha&nbsp;<\/li>\n\n\n\n<li>Marina Shafir&nbsp;<\/li>\n\n\n\n<li>Allie Katch&nbsp;<\/li>\n\n\n\n<li>Suzu Suzuki&nbsp;<\/li>\n\n\n\n<li>Loue O\u2019Farrell&nbsp;<\/li>\n\n\n\n<li>VENY&nbsp;<\/li>\n\n\n\n<li>Sandra Moone&nbsp;<\/li>\n\n\n\n<li>Session Moth Martina&nbsp;<\/li>\n\n\n\n<li>Aliss Ink&nbsp;<\/li>\n\n\n\n<li>Saya Kamitani&nbsp;<\/li>\n\n\n\n<li>Jaida Parker&nbsp;<\/li>\n\n\n\n<li>Alexis Lee&nbsp;<\/li>\n\n\n\n<li>Gisele Shaw&nbsp;<\/li>\n\n\n\n<li>Anna Jay&nbsp;<\/li>\n\n\n\n<li>La Catalina&nbsp;<\/li>\n\n\n\n<li>Lola Vice&nbsp;<\/li>\n\n\n\n<li>Lana Austin&nbsp;<\/li>\n\n\n\n<li>Mizuki&nbsp;<\/li>\n\n\n\n<li>Lizzy Evo&nbsp;<\/li>\n\n\n\n<li>Lena Kross&nbsp;<\/li>\n\n\n\n<li>Natalya&nbsp;<\/li>\n\n\n\n<li>Steph De Lander&nbsp;<\/li>\n\n\n\n<li>YuuRi&nbsp;<\/li>\n\n\n\n<li>Sierra&nbsp;<\/li>\n\n\n\n<li>Konami&nbsp;<\/li>\n\n\n\n<li>Nyla Rose&nbsp;<\/li>\n\n\n\n<li>Starlight Kid&nbsp;<\/li>\n\n\n\n<li>Sol Ruca&nbsp;<\/li>\n\n\n\n<li>Yuki Arai&nbsp;<\/li>\n\n\n\n<li>Dani Mo&nbsp;<\/li>\n\n\n\n<li>Debbie Keitel&nbsp;<\/li>\n\n\n\n<li>Yuu&nbsp;<\/li>\n\n\n\n<li>Chelsea Green&nbsp;<\/li>\n\n\n\n<li>Serena Deeb&nbsp;<\/li>\n\n\n\n<li>Nightshade&nbsp;<\/li>\n\n\n\n<li>Gabby Forza&nbsp;<\/li>\n\n\n\n<li>Haruka Umesaki&nbsp;<\/li>\n\n\n\n<li>Lluvia&nbsp;<\/li>\n\n\n\n<li>Kylie Paige&nbsp;<\/li>\n\n\n\n<li>Flammer&nbsp;<\/li>\n\n\n\n<li>Missa Kate&nbsp;<\/li>\n\n\n\n<li>Jessy Jay&nbsp;<\/li>\n\n\n\n<li>Kacy Diamond&nbsp;<\/li>\n\n\n\n<li>Zayda Steel&nbsp;<\/li>\n\n\n\n<li>Ryo Mizunami&nbsp;<\/li>\n\n\n\n<li>Rita Stone&nbsp;<\/li>\n\n\n\n<li>Mio Momono&nbsp;<\/li>\n\n\n\n<li>Dream Girl Ellie&nbsp;<\/li>\n\n\n\n<li>Sexy Star II<\/li>\n\n\n\n<li>Shoko Nakajima&nbsp;<\/li>\n\n\n\n<li>Mila Smidt&nbsp;<\/li>\n\n\n\n<li>Kira Chimera&nbsp;<\/li>\n\n\n\n<li>Erica Leigh&nbsp;<\/li>\n\n\n\n<li>Kanji&nbsp;<\/li>\n\n\n\n<li>Safire Reed&nbsp;<\/li>\n\n\n\n<li>Aysha&nbsp;<\/li>\n\n\n\n<li>Mazzerati&nbsp;<\/li>\n\n\n\n<li>Taya Valkyrie&nbsp;<\/li>\n\n\n\n<li>Heather Reckless&nbsp;<\/li>\n\n\n\n<li>Blair Davenport&nbsp;<\/li>\n\n\n\n<li>Trish Adora&nbsp;<\/li>\n\n\n\n<li>Tatum Paxley&nbsp;<\/li>\n\n\n\n<li>Kylie Rae&nbsp;<\/li>\n\n\n\n<li>Leyla Hirsch&nbsp;<\/li>\n\n\n\n<li>Reyna Isis&nbsp;<\/li>\n\n\n\n<li>Miyuki Takase&nbsp;<\/li>\n\n\n\n<li>Tiffany Nieves&nbsp;<\/li>\n\n\n\n<li>Miyu Amasaki&nbsp;<\/li>\n\n\n\n<li>Leila Grey&nbsp;<\/li>\n\n\n\n<li>Izzi Dame&nbsp;<\/li>\n\n\n\n<li>L A Taylor&nbsp;<\/li>\n\n\n\n<li>Keyra&nbsp;<\/li>\n\n\n\n<li>Fallon Henley&nbsp;<\/li>\n\n\n\n<li>Abadon&nbsp;<\/li>\n\n\n\n<li>Diamante&nbsp;<\/li>\n\n\n\n<li>Tessa Blanchard&nbsp;<\/li>\n\n\n\n<li>Millie McKenzie&nbsp;<\/li>\n\n\n\n<li>Rika Tatsumi&nbsp;<\/li>\n\n\n\n<li>Zoe Sager&nbsp;<\/li>\n\n\n\n<li>Zara Zakher&nbsp;<\/li>\n\n\n\n<li>Su Yung&nbsp;<\/li>\n\n\n\n<li>Chantal Jordan&nbsp;<\/li>\n\n\n\n<li>Marti Belle&nbsp;<\/li>\n\n\n\n<li>Freya the Slaya&nbsp;<\/li>\n\n\n\n<li>Natalia Markova&nbsp;<\/li>\n\n\n\n<li>Nanae Takahashi&nbsp;<\/li>\n\n\n\n<li>Jessica Troy&nbsp;<\/li>\n\n\n\n<li>Lash Legend&nbsp;<\/li>\n\n\n\n<li>Ella Envy&nbsp;<\/li>\n\n\n\n<li>Taryn From Accounting&nbsp;<\/li>\n\n\n\n<li>Risa Sera&nbsp;<\/li>\n\n\n\n<li>Harley Hudson&nbsp;<\/li>\n\n\n\n<li>Nicole Matthews&nbsp;<\/li>\n\n\n\n<li>Michin&nbsp;<\/li>\n\n\n\n<li>Allysin Kay&nbsp;<\/li>\n\n\n\n<li>Maika Ozaki&nbsp;<\/li>\n\n\n\n<li>Koguma&nbsp;<\/li>\n\n\n\n<li>Aleah James&nbsp;<\/li>\n\n\n\n<li>Tegan Nox&nbsp;<\/li>\n\n\n\n<li>Kiera Hogan&nbsp;<\/li>\n\n\n\n<li>Saki Kashima&nbsp;<\/li>\n\n\n\n<li>Tasha Steelz&nbsp;<\/li>\n\n\n\n<li>J-Rod&nbsp;<\/li>\n\n\n\n<li>Mei Suruga&nbsp;<\/li>\n\n\n\n<li>Maya World&nbsp;<\/li>\n\n\n\n<li>Dark Silueta&nbsp;<\/li>\n\n\n\n<li>Yuki Kamifuku&nbsp;<\/li>\n\n\n\n<li>Brittnie Brooks&nbsp;<\/li>\n\n\n\n<li>Maya Yukihi&nbsp;<\/li>\n\n\n\n<li>Ivelisse&nbsp;<\/li>\n\n\n\n<li>Chik Tormenta&nbsp;<\/li>\n\n\n\n<li>Lady Frost&nbsp;<\/li>\n\n\n\n<li>Hazuki&nbsp;<\/li>\n\n\n\n<li>Gia Scott&nbsp;<\/li>\n\n\n\n<li>Thea Hail&nbsp;<\/li>\n\n\n\n<li>Evie de la Rosa&nbsp;<\/li>\n\n\n\n<li>Angelica Risk&nbsp;<\/li>\n\n\n\n<li>Myla Grace&nbsp;<\/li>\n\n\n\n<li>Yuki Aino&nbsp;<\/li>\n\n\n\n<li>Rachael Ellering&nbsp;<\/li>\n\n\n\n<li>MYLO&nbsp;<\/li>\n\n\n\n<li>Haley J&nbsp;<\/li>\n\n\n\n<li>Christina Marie&nbsp;<\/li>\n\n\n\n<li>Cherry Stephens&nbsp;<\/li>\n\n\n\n<li>Kaori Yoneyama&nbsp;<\/li>\n\n\n\n<li>Kiana James&nbsp;<\/li>\n\n\n\n<li>SAKI&nbsp;<\/li>\n\n\n\n<li>Vita Von Starr&nbsp;<\/li>\n\n\n\n<li>Victoria Yuzuki&nbsp;<\/li>\n\n\n\n<li>Charli Evans&nbsp;<\/li>\n\n\n\n<li>Yuuki Mashiro&nbsp;<\/li>\n\n\n\n<li>Saya Iida&nbsp;<\/li>\n\n\n\n<li>Itsuki Aoki&nbsp;<\/li>\n\n\n\n<li>Xena&nbsp;<\/li>\n\n\n\n<li>Aja Kong&nbsp;<\/li>\n\n\n\n<li>Yuna Manase&nbsp;<\/li>\n\n\n\n<li>Mai Sakurai&nbsp;<\/li>\n\n\n\n<li>Savannah Evans&nbsp;<\/li>\n\n\n\n<li>Little Mean Kathleen&nbsp;<\/li>\n\n\n\n<li>Seleziya Sparx&nbsp;<\/li>\n\n\n\n<li>Xia Brookside&nbsp;<\/li>\n\n\n\n<li>Wendy Choo&nbsp;<\/li>\n\n\n\n<li>Ami Sourei&nbsp;<\/li>\n\n\n\n<li>Emerson Jayne&nbsp;<\/li>\n\n\n\n<li>Ram Kaichow&nbsp;<\/li>\n\n\n\n<li>Rebecca Scott&nbsp;<\/li>\n\n\n\n<li>Zamaya&nbsp;<\/li>\n\n\n\n<li>Jordan Blade&nbsp;<\/li>\n\n\n\n<li>Jasmin Allure&nbsp;<\/li>\n\n\n\n<li>Maggie Lee&nbsp;<\/li>\n\n\n\n<li>Ruthie Jay&nbsp;<\/li>\n\n\n\n<li>Nanami&nbsp;<\/li>\n\n\n\n<li>Katie Arquette&nbsp;<\/li>\n\n\n\n<li>Kaia McKenna&nbsp;<\/li>\n\n\n\n<li>Laynie Luck&nbsp;<\/li>\n\n\n\n<li>Azaelle&nbsp;<\/li>\n\n\n\n<li>Alice Crowley&nbsp;<\/li>\n\n\n\n<li>Vicious Vicki&nbsp;<\/li>\n\n\n\n<li>Delilah Doom&nbsp;<\/li>\n\n\n\n<li>Riko Kawahata&nbsp;<\/li>\n\n\n\n<li>Alex Gracia&nbsp;<\/li>\n\n\n\n<li>Blair Onyx&nbsp;<\/li>\n\n\n\n<li>ZONES&nbsp;<\/li>\n\n\n\n<li>Kelsey Raegan&nbsp;<\/li>\n\n\n\n<li>Dev Lynn&nbsp;<\/li>\n\n\n\n<li>Nathalya Perez&nbsp;<\/li>\n\n\n\n<li>Tiara James&nbsp;<\/li>\n\n\n\n<li>Brooke Havok&nbsp;<\/li>\n\n\n\n<li>Alexis Littlefoot&nbsp;<\/li>\n\n\n\n<li>Jazzy Yang&nbsp;<\/li>\n\n\n\n<li>Nahir Robles<\/li>\n<\/ol>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Cette semaine est sorti le classement annuel du PWI 250 qui regroupe les 250 meilleures catcheuses du monde selon diff\u00e9rents crit\u00e8res durant la p\u00e9riode du premier octobre 2023 au 30 septembre 2024,&nbsp;remport\u00e9 cette ann\u00e9e par Toni Storm&nbsp;pour la premi\u00e8re fois de sa carri\u00e8re. On vous propose maintenant de d\u00e9couvrir la liste compl\u00e8te de ce classement&#8230;<\/p>\n","protected":false},"author":609,"featured_media":106049,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,38,24,30,22,55,4,61,85,49,41,23],"tags":[],"ppma_author":[295],"class_list":["post-106048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aaa","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-indy","category-njpw","category-news","category-nwa","category-nxt","category-roh","category-tna-impact","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=106048"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106048\/revisions"}],"predecessor-version":[{"id":106151,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106048\/revisions\/106151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/106049"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=106048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=106048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=106048"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=106048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}