{"id":106002,"date":"2024-10-15T22:32:00","date_gmt":"2024-10-16T02:32:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=106002"},"modified":"2024-10-16T15:36:20","modified_gmt":"2024-10-16T19:36:20","slug":"les-premiers-matchs-sannoncent-pour-nxt-halloween-havoc-2024-avec-les-stipulations-qui-ont-ete-tournees-en-direct-a-nxt","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/10\/15\/les-premiers-matchs-sannoncent-pour-nxt-halloween-havoc-2024-avec-les-stipulations-qui-ont-ete-tournees-en-direct-a-nxt\/","title":{"rendered":"Les premiers matchs s&rsquo;annoncent pour NXT Halloween Havoc 2024 avec les stip\u00fblations qui ont \u00e9t\u00e9 tourn\u00e9es en direct \u00e0 NXT."},"content":{"rendered":"\n<p>La carte du sp\u00e9cial Halloween Havoc de NXT, commence \u00e0 prendre forme pendant WWE NXT cette semaine maintenant que la grande premi\u00e8re sur CW Network est derri\u00e8re nous.<\/p>\n\n\n\n<p>Cette ann\u00e9e Halloween Havoc est un peu diff\u00e9rent puisqu&rsquo;il ne s&rsquo;agit pas d&rsquo;un show hebdomadaire de NXT comme par le pass\u00e9, mais bien d&rsquo;un PLE \u00e0 part enti\u00e8re pour la division de NXT. Le show aura lieu le dimanche 27 octobre 2024 dans la nuit de dimanche \u00e0 lundi pour nos amis en Europe, en direct du Giant Center de la ville d&rsquo;Hersey en Pennsylvanie.<\/p>\n\n\n\n<p>Quelques matchs ont \u00e9t\u00e9 annonc\u00e9 lors du\u00a0WWE NXT ce mardi. Oba Femi n&rsquo;a pas perdu de temps pour demander son rematch face \u00e0 Tony D&rsquo;Angelo. Il n&rsquo;a pas appr\u00e9ci\u00e9 l&rsquo;intervention de la Famille dans leur dernier combat qui a potentiellement caus\u00e9 sa perte de titre. Ainsi, Femi a tourn\u00e9 la roue d&rsquo;Halloween Havoc et ils vont s&rsquo;affronter dans un \u00a0\u00bbTables, Ladders and Scares\u00a0\u00bb Match au PLE pour le titre Nord-Am\u00e9ricain. Il s&rsquo;agit d&rsquo;un TLC Match sp\u00e9cial Halloween.<\/p>\n\n\n\n<p>Ensuite, Trick Williams attendait de d\u00e9couvrir qui serait son prochain aspirant pour le championnat de NXT. Je&rsquo;Von Evans, Ethan Page et Wes Lee s&rsquo;affrontaient dans un Triple Threat Match pour d\u00e9terminer qui allait un match de championnat. Alors que Je&rsquo;Von Evans croyait remporter l&rsquo;affrontement apr\u00e8s avoir fait son Twisted Splash sur Wes Lee, Ethan Page est revenu par surprise pour lui faire un Roll Up et s&rsquo;\u00e9chapper avec la victoire.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"wD07FBYv8Z\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/10\/15\/resultats-et-video-pour-le-wwe-nxt-du-15-octobre-2024\/\">R\u00e9sultats et Vid\u00e9o pour le WWE NXT du 15 Octobre 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le WWE NXT du 15 Octobre 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/10\/15\/resultats-et-video-pour-le-wwe-nxt-du-15-octobre-2024\/embed\/#?secret=t3qHJjQC8a#?secret=wD07FBYv8Z\" data-secret=\"wD07FBYv8Z\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La carte du sp\u00e9cial Halloween Havoc de NXT, commence \u00e0 prendre forme pendant WWE NXT cette semaine maintenant que la grande premi\u00e8re sur CW Network est derri\u00e8re nous. Cette ann\u00e9e Halloween Havoc est un peu diff\u00e9rent puisqu&rsquo;il ne s&rsquo;agit pas d&rsquo;un show hebdomadaire de NXT comme par le pass\u00e9, mais bien d&rsquo;un PLE \u00e0 part&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":106003,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,85,45,23],"tags":[114,115,109,110],"ppma_author":[297],"class_list":["post-106002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-nxt","category-ppv-wwe","category-wwe","tag-halloween-havoc","tag-nxt-wwe","tag-ple","tag-ppv"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=106002"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106002\/revisions"}],"predecessor-version":[{"id":106004,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/106002\/revisions\/106004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/106003"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=106002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=106002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=106002"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=106002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}