{"id":105744,"date":"2024-10-12T15:16:00","date_gmt":"2024-10-12T19:16:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=105744"},"modified":"2024-10-14T13:23:42","modified_gmt":"2024-10-14T17:23:42","slug":"carte-info-et-storyline-pour-le-ppv-de-la-aew-wrestledream-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/10\/12\/carte-info-et-storyline-pour-le-ppv-de-la-aew-wrestledream-2024\/","title":{"rendered":"Reprise Vid\u00e9o pour le PPV de la AEW WrestleDream 2024 + Carte et Storylines!"},"content":{"rendered":"\n<p>La seconde \u00e9dition de AEW WrestleDream de l\u2019histoire de la All Elite Wrestling se tient ce samedi 12 octobre 2024 au Tacoma Dome de Tacoma, dans l\u2019\u00c9tat de Washington. <\/p>\n\n\n\n<p>Neuf combats dont six matchs de championnat composent la carte principale de l\u2019\u00e9v\u00e9nement, alors que Bryan Danielson et Jon Moxley s\u2019affronteront pour le titre mondial de la AEW dans le main event.<\/p>\n\n\n\n<p>Bien <\/p>\n\n\n\n<p>Le show principal va d\u00e9buter \u00e0 20H fuseau de l&rsquo;est et don 2h pour nos amis en Europe. Le PPV sera diffus\u00e9 sur TrillerTV et sur le YouTube payant de la AEW. Nous vous passerons bien s\u00fbre des liens pour vous d\u00e9panner pour le voir en direct ou en reprise. <\/p>\n\n\n\n<p><em>* Les storyline d\u00e9taill\u00e9es suivent la carte.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">DAILYMOTION VIDEOS (HD QUALITY)<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"http:\/\/thechefonline.com\/reports\/megaup.php?File=dmrep_6%26mainid=20241012APV\" target=\"_blank\" rel=\"noreferrer noopener\">Preshow<\/a>&nbsp;<a href=\"http:\/\/thechefonline.com\/reports\/megaup.php?File=dmrep_1%26mainid=20241012APV\" target=\"_blank\" rel=\"noreferrer noopener\">Part1<\/a>&nbsp;<a href=\"http:\/\/thechefonline.com\/reports\/megaup.php?File=dmrep_2%26mainid=20241012APV\" target=\"_blank\" rel=\"noreferrer noopener\">Part2<\/a>&nbsp;<a href=\"http:\/\/thechefonline.com\/reports\/megaup.php?File=dmrep_3%26mainid=20241012APV\" target=\"_blank\" rel=\"noreferrer noopener\">Part3<\/a>&nbsp;<a href=\"http:\/\/thechefonline.com\/reports\/megaup.php?File=dmrep_4%26mainid=20241012APV\" target=\"_blank\" rel=\"noreferrer noopener\">Part4<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\">PVPHD VIDEOS (HD QUALITY)<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"http:\/\/thechefonline.com\/reports\/megaup.php?File=tuberep_6%26mainid=20241012APV\" target=\"_blank\" rel=\"noreferrer noopener\">Preshow<\/a>&nbsp;<a href=\"http:\/\/thechefonline.com\/reports\/megaup.php?File=tuberep_1%26mainid=20241012APV\" target=\"_blank\" rel=\"noreferrer noopener\">Part1<\/a>&nbsp;<a href=\"http:\/\/thechefonline.com\/reports\/megaup.php?File=tuberep_2%26mainid=20241012APV\" target=\"_blank\" rel=\"noreferrer noopener\">Part2<\/a>&nbsp;<a href=\"http:\/\/thechefonline.com\/reports\/megaup.php?File=tuberep_3%26mainid=20241012APV\" target=\"_blank\" rel=\"noreferrer noopener\">Part3<\/a>&nbsp;<a href=\"http:\/\/thechefonline.com\/reports\/megaup.php?File=tuberep_4%26mainid=20241012APV\" target=\"_blank\" rel=\"noreferrer noopener\">Part4<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\">PVPHD VIDEOS (HD QUALITY)<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"http:\/\/thechefonline.com\/reports\/megaup.php?File=tuberep_6%26mainid=20241012APV\" target=\"_blank\" rel=\"noreferrer noopener\">Preshow<\/a>&nbsp;<a href=\"http:\/\/thechefonline.com\/reports\/megaup.php?File=tuberep_7%26mainid=20241012APV\" target=\"_blank\" rel=\"noreferrer noopener\">Fullshow HDV1<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\">SINGLE LINKS VIDEOS (HD QUALITY)<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/multiupnow.com\/files\/?id=10132024085531\" target=\"_blank\" rel=\"noreferrer noopener\">Preshow SD HD LQ<\/a>&nbsp;<a href=\"https:\/\/multiupnow.com\/files\/?id=10132024101337\" target=\"_blank\" rel=\"noreferrer noopener\">MultiUp SHD SD LQ<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-vivid-red-background-color has-text-color has-background\" style=\"font-size:25px\"><strong>Pour voir WrestleDream en direct ou en reprise :<\/strong><br><a href=\"https:\/\/watchwrestlingup.org\/watch-aew-wrestledream-2024-ppv-live-10-12-24-october-12th-2024-online-full-show-free\/\" target=\"_blank\" rel=\"noreferrer noopener\">Source #1<\/a><a rel=\"noreferrer noopener\" href=\"https:\/\/watchwrestlingup.org\/watch-wwe-smackdown-live-9-20-24-september-20th-2024-online-full-show-free\/\" target=\"_blank\">,<\/a> <a href=\"https:\/\/tempsiteadd.blogspot.com\/?m=0\" target=\"_blank\" rel=\"noreferrer noopener\">Source #2<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/GZR0ipcXkAAVs7u?format=jpg&amp;name=large\" alt=\"\"\/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Carte de AEW WrestleDream 2024 :<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Carte principale<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Championnat du monde de la AEW :<\/strong>&nbsp;<br>Bryan Danielson \u00a9 vs Jon Moxley<\/li>\n\n\n\n<li><strong>Championnat du monde f\u00e9minin de la AEW :<\/strong>&nbsp;<br>Mariah May \u00a9 contre&nbsp;Willow Nightingale<\/li>\n\n\n\n<li><strong>Championnat du monde de la ROH :<\/strong>&nbsp;<br>Mark Briscoe \u00a9 vs Chris Jericho<\/li>\n\n\n\n<li><strong>Championnats du monde par \u00e9quipe de la AEW :&nbsp;<\/strong><br>The Young Bucks \u00a9 vs Private Party<\/li>\n\n\n\n<li><strong>Triple Menace : Championnat International de la AEW :<\/strong>&nbsp;<br>Will Ospreay \u00a9 vs Konosuke Takeshita vs Ricochet <\/li>\n\n\n\n<li><strong>Championnat TNT de l\u2019AEW :<\/strong>&nbsp;Jack Perry (c) contre Katsuyori Shibata<\/li>\n\n\n\n<li>Jay White vs \u00ab&nbsp;Hangman&nbsp;\u00bb Page<\/li>\n\n\n\n<li>Darby Allin vs Brody King<\/li>\n\n\n\n<li><strong>Match Deux de Trois<\/strong> <br>Hologram vs The Beast Mortos <\/li>\n\n\n\n<li>Swerve Strickland de retour<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Pr\u00e9-show (Zero Hour)<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Championnat du monde TV de la ROH <\/strong><br>&nbsp;Atlantis Jr. \u00a9 contre Brian Cage<\/li>\n<\/ul>\n\n\n\n<center><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/center>\n\n\n\n<p class=\"has-large-font-size\"><strong>STORYLINE<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Bryan vs. Mox : qui remportera la guerre ?<\/h4>\n\n\n\n<p>Treize jours apr\u00e8s avoir remport\u00e9 le championnat du monde de l\u2019AEW \u00e0&nbsp;All In London,&nbsp;Bryan Danielson&nbsp;remettait son titre en jeu \u00e0 Chicago face \u00e0 Jack Perry dans le co-main event de&nbsp;AEW All Out. Alors qu\u2019il venait de conserver sa ceinture, les membres du Blackpool Combat Club sont venus c\u00e9l\u00e9brer la victoire \u00e0 ses c\u00f4t\u00e9s, avant que&nbsp;Jon Moxley&nbsp;n\u2019attaque brutalement&nbsp;<em>The American Dragon<\/em>. Aid\u00e9 par&nbsp;Claudio Castagnoli&nbsp;et PAC qui ont emp\u00each\u00e9 Wheeler YUTA de sauver le champion du monde, Jon Moxley a ainsi fait passer un message clair : Bryan Danielson n\u2019incarne pas l\u2019image de champion qu\u2019il souhaite pour la All Elite Wrestling.<\/p>\n\n\n\n<p>Quelques semaines plus tard, Jon Moxley a battu Darby Allin pour devenir le nouveau challenger n\u00b01 au championnat du monde de l\u2019AEW et s\u2019offrir une chance d\u2019affronter Bryan Danielson ce samedi 12 octobre \u00e0 WrestleDream. La guerre est d\u00e9clar\u00e9e entre les deux anciens partenaires ; reste \u00e0 observer qui ressortira vainqueur de la premi\u00e8re bataille.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L\u2019heure de la r\u00e9demption pour Willow Nightingale ?<\/h3>\n\n\n\n<p>Willow Nightingale a remport\u00e9 un&nbsp;<em>Fatal 4-Way match<\/em>&nbsp;face \u00e0 Jamie Hayter, Nyla Rose et Saraya ce mardi \u00e0 Dynamite Title Tuesday pour devenir la pr\u00e9tendante au titre mondial f\u00e9minin de l\u2019AEW et empocher son ticket pour WrestleDream. Elle affrontera ainsi la championne&nbsp;Mariah May&nbsp;et tentera de d\u00e9crocher un nouveau titre dans sa carri\u00e8re, alors qu\u2019elle reste sur plusieurs \u00e9checs ces derni\u00e8res semaines ; en effet, battue par Kris Statlander \u00e0 All Out dans un&nbsp;<em>Chicago Street Fight match<\/em>&nbsp;brutal, elle a \u00e9galement perdu le championnat du monde f\u00e9minin du CMLL le 13 septembre dernier face \u00e0 Zeuxis. Saisira-t-elle l\u2019opportunit\u00e9 qu\u2019elle a obtenue pour se relever samedi soir \u00e0 Tacoma ?<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">The Ocho est mort, vive le Nueve<\/h4>\n\n\n\n<p>Un troisi\u00e8me match de championnat du monde aura lieu \u00e0 AEW WrestleDream 2024. Le champion du monde de la ROH, Mark Briscoe, d\u00e9fendra son titre face \u00e0&nbsp;Chris Jericho. Ce dernier veut mettre fin \u00e0 l\u2019\u00e8re de&nbsp;<em>The Ocho<\/em>&nbsp;pour instaurer celle du&nbsp;<em>Nueve<\/em>&nbsp;en remportant le neuvi\u00e8me championnat du monde de sa carri\u00e8re. Chris Jericho a par ailleurs d\u00e9j\u00e0 \u00e9t\u00e9 champion du monde de la ROH, entre septembre et d\u00e9cembre 2022, tandis que Mark Briscoe d\u00e9tient la ceinture depuis sa victoire face \u00e0 Eddie Kingston \u00e0&nbsp;ROH SuperCard of Honor&nbsp;qui s\u2019est tenu le vendredi 5 avril dernier, durant le WrestleMania Weekend.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Private Party : un premier sacre en ligne de mire<\/h4>\n\n\n\n<p>Du c\u00f4t\u00e9 de la division par \u00e9quipe, les&nbsp;Young Bucks&nbsp;remettront les championnats du monde par \u00e9quipe de l\u2019AEW en jeu face \u00e0 Private Party. Isiah Kassidy et Marq Quen ont l\u2019ambition de faire leur retour sur le devant de la sc\u00e8ne et veulent d\u00e9crocher leurs premiers titres du c\u00f4t\u00e9 de la All Elite Wrestling. Ils n\u2019ont pas \u00e9t\u00e9 champions depuis mars 2019 lorsqu\u2019ils d\u00e9tenaient les championnats par \u00e9quipe de la Warriors Of Wrestling (WOW).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Championnats secondaires, matchs majeurs<\/h4>\n\n\n\n<p>Deux autres matchs de championnat sont au programme du show.<\/p>\n\n\n\n<p>Tout d\u2019abord,&nbsp;Will Ospreay&nbsp;d\u00e9fendra le titre International de l\u2019AEW dans un&nbsp;<em>3-Way match<\/em>&nbsp;face \u00e0 Ricochet et Konosuke Takeshita. Ce dernier est intervenu lors du match entre Ospreay et Ricochet le 2 octobre dernier \u00e0&nbsp;Dynamite 5-Year Anniversary, emp\u00eachant alors le combat de se solder autrement que par une disqualification. Le message \u00e9tait alors clair : Konosuke Takeshita veut detr\u00f4ner&nbsp;<em>The Aerial Assassin<\/em>&nbsp;lui-m\u00eame et d\u00e9crocher son premier titre \u00e0 l\u2019AEW.<\/p>\n\n\n\n<p>Puis, le championnat TNT sera \u00e9galement en jeu, puisque Jack Perry le d\u00e9fendra face \u00e0 Katsuyori Shibata.&nbsp;<em>The Scapegoat<\/em>&nbsp;est champion depuis&nbsp;AEW x NJPW Forbidden Door, alors qu\u2019il avait d\u00e9croch\u00e9 la ceinture dans un&nbsp;<em>Ladder match<\/em>&nbsp;o\u00f9 le titre TNT \u00e9tait vacant. Il le remettra en jeu pour la sixi\u00e8me fois depuis le d\u00e9but de son r\u00e8gne \u00e0 WrestleDream samedi soir.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Swerve Strickland fait son retour<\/h4>\n\n\n\n<p>Par ailleurs, le retour de l\u2019ancien champion du monde de l\u2019AEW,&nbsp;Swerve Strickland, a \u00e9t\u00e9 annonc\u00e9 pour le pay-per-view.&nbsp;<em>The Realest<\/em>&nbsp;n\u2019est pas apparu sur les programmes de la All Elite Wrestling depuis sa d\u00e9faite face \u00e0 \u00ab&nbsp;Hangman&nbsp;\u00bb Adam Page \u00e0 All Out le 7 septembre dernier. Qu\u2019aura-t-il \u00e0 dire, alors que MVP lui a propos\u00e9 ses services par le biais d\u2019une confrontation avec Prince Nana lors de l\u2019\u00e9pisode de&nbsp;Dynamite Grand Slam 2024&nbsp;?<\/p>\n\n\n\n<p>De plus, trois autres combats ont \u00e9t\u00e9 annonc\u00e9s pour l\u2019\u00e9v\u00e9nement.<\/p>\n\n\n\n<p>Jay White, qui a fait son retour \u00e0 AEW Dynamite le 2 octobre dernier, affrontera&nbsp;Adam Page.<\/p>\n\n\n\n<p>Darby Allin sera quant \u00e0 lui oppos\u00e9 \u00e0 Brody King, suite \u00e0 l\u2019open challenge qu\u2019il a lanc\u00e9 il y quelques jours.<\/p>\n\n\n\n<p>Enfin, Hologram et The Beast Mortos s\u2019affronteront dans un&nbsp;<em>2 Out of 3 Falls match<\/em>.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La seconde \u00e9dition de AEW WrestleDream de l\u2019histoire de la All Elite Wrestling se tient ce samedi 12 octobre 2024 au Tacoma Dome de Tacoma, dans l\u2019\u00c9tat de Washington. Neuf combats dont six matchs de championnat composent la carte principale de l\u2019\u00e9v\u00e9nement, alors que Bryan Danielson et Jon Moxley s\u2019affronteront pour le titre mondial de&#8230;<\/p>\n","protected":false},"author":55,"featured_media":105447,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,68,30,45,29,20,94],"tags":[],"ppma_author":[288],"class_list":["post-105744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-carte","category-ex-wwe","category-ppv-wwe","category-streaming","category-videos","category-wrestledream"],"authors":[{"term_id":288,"user_id":55,"is_guest":0,"slug":"mark-green","display_name":"Watch Wrestling","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48aa7229968e08b18e4ac74ae48666f742d5f4460d3a972818733f8de3e505c2?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/105744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=105744"}],"version-history":[{"count":6,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/105744\/revisions"}],"predecessor-version":[{"id":105855,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/105744\/revisions\/105855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/105447"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=105744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=105744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=105744"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=105744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}