{"id":105624,"date":"2024-10-07T20:19:00","date_gmt":"2024-10-08T00:19:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=105624"},"modified":"2024-10-07T21:59:01","modified_gmt":"2024-10-08T01:59:01","slug":"seth-rollins-veut-envoyer-cm-punk-a-la-retraite","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/10\/07\/seth-rollins-veut-envoyer-cm-punk-a-la-retraite\/","title":{"rendered":"Seth Rollins veut envoyer CM Punk \u00e0 la retraite !"},"content":{"rendered":"\n<p>48 heures apr\u00e8s sa victoire contre Drew McIntyre \u00e0 Bad Blood, CM Punk a ouvert\u00a0WWE RAW le lundi 7 octobre 2024. Toujours marqu\u00e9 par les s\u00e9quelles de son Hell in a Cell Match brutal, le \u00ab\u00a0Best in the World\u00a0\u00bb en a profit\u00e9 pour faire le point sur son avenir.<\/p>\n\n\n\n<p>CM Punk a pris le temps de remercier ses fans, ses coll\u00e8gues, ainsi que ceux qui ne l&rsquo;appr\u00e9cient pas, les invitant m\u00eame \u00e0 continuer de douter de lui. Maintenant que sa rivalit\u00e9 avec Drew McIntyre est termin\u00e9e, on n&rsquo;a le droit de se demander se sera quoi la suite pour lui. <\/p>\n\n\n\n<p>Il a d\u00e9clar\u00e9 sur la sc\u00e8ne de RAW qu&rsquo;il allait rentrer chez lui pour revoir sa femme, qu&rsquo;il n&rsquo;a pas vue depuis cinq semaines, avant de conclure en disant qu&rsquo;il aimerait promettre un retour rapide, mais \u00ab\u00a0il ne sait pas.\u00a0\u00bb<\/p>\n\n\n\n<p>Visiblement,\u00a0CM Punk\u00a0va s&rsquo;absenter des shows de la WWE pour un certain temps, mais sa prochaine rivalit\u00e9 semble d\u00e9j\u00e0 se dessiner. En effet,\u00a0Seth Rollins, qui avait fait son retour une semaine plus t\u00f4t, est venu le confronter et avait quelques mots \u00e0 lui adresser :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0R\u00e9tablis-toi vite car plus vite tu reviendras, plus vite je pourrai te botter le cul et t&rsquo;envoyer \u00e0 la retraite pour de bon.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/ddqn1K7FjHk?si=tgwM3tK1y_H_FfxH\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"zfzZEta6JD\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/10\/07\/resultats-pour-le-wwe-monday-night-raw-du-7-octobre-2024\/\">R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 7 octobre 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 7 octobre 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/10\/07\/resultats-pour-le-wwe-monday-night-raw-du-7-octobre-2024\/embed\/#?secret=wtMAuSUXyK#?secret=zfzZEta6JD\" data-secret=\"zfzZEta6JD\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>48 heures apr\u00e8s sa victoire contre Drew McIntyre \u00e0 Bad Blood, CM Punk a ouvert\u00a0WWE RAW le lundi 7 octobre 2024. Toujours marqu\u00e9 par les s\u00e9quelles de son Hell in a Cell Match brutal, le \u00ab\u00a0Best in the World\u00a0\u00bb en a profit\u00e9 pour faire le point sur son avenir. CM Punk a pris le temps&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":105625,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,23],"tags":[],"ppma_author":[297],"class_list":["post-105624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/105624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=105624"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/105624\/revisions"}],"predecessor-version":[{"id":105632,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/105624\/revisions\/105632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/105625"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=105624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=105624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=105624"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=105624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}