{"id":105108,"date":"2024-09-24T15:16:00","date_gmt":"2024-09-24T19:16:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=105108"},"modified":"2024-09-24T15:40:50","modified_gmt":"2024-09-24T19:40:50","slug":"mise-a-jour-des-coulisses-sur-le-making-of-de-la-serie-documentaire-mr-mcmahon-de-netflix-a-quoi-sattendre-et-plus-encore","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/09\/24\/mise-a-jour-des-coulisses-sur-le-making-of-de-la-serie-documentaire-mr-mcmahon-de-netflix-a-quoi-sattendre-et-plus-encore\/","title":{"rendered":"Mise \u00e0 jour des coulisses sur le making of de la s\u00e9rie documentaire \u00ab Mr. McMahon \u00bb de Netflix, \u00e0 quoi s&rsquo;attendre et plus encore"},"content":{"rendered":"\n<p>D\u2019autres d\u00e9tails ont fait surface concernant la tr\u00e8s attendue s\u00e9rie documentaire \u00ab Mr. McMahon \u00bb.<\/p>\n\n\n\n<p>Les interviews que Vince McMahon a film\u00e9es pour la s\u00e9rie ont eu lieu avant sa \u00ab retraite \u00bb la premi\u00e8re fois. La WWE pense que des avertissements seraient inclus concernant de nombreuses t\u00eates parlantes pr\u00e9sent\u00e9es pour des interviews dans les archives qui ont \u00e9t\u00e9 tourn\u00e9es avant cette date, afin de rendre les critiques \u00e9logieuses sur Vince meilleures avec le recul.<\/p>\n\n\n\n<p>Vince ne fournirait pas beaucoup d\u2019informations nouvelles concernant les sujets controvers\u00e9s, y compris ceux m\u00eame ant\u00e9rieurs \u00e0 l\u2019affaire Janel Grant.<\/p>\n\n\n\n<p>Un certain nombre de personnes qui ont \u00e9t\u00e9 \u00ab l\u00e9s\u00e9es \u00bb dans le monde du catch ont \u00e9galement \u00e9t\u00e9 interview\u00e9es pour le projet, mais McMahon lui-m\u00eame n\u2019a pratiquement pas \u00e9labor\u00e9 sur quoi que ce soit li\u00e9 \u00e0 ces questions ou \u00e0 ces sujets controvers\u00e9s lorsqu\u2019il a \u00e9t\u00e9 invit\u00e9 \u00e0 commenter pendant son interview.<\/p>\n\n\n\n<p>Comme indiqu\u00e9, Vince McMahon aurait essay\u00e9 d\u2019acheter et de fermer la s\u00e9rie documentaire de Netflix pour \u00e9viter sa diffusion. <\/p>\n\n\n\n<p>Selon une source, ce qu&rsquo;il essayait de soutenir:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p> \u00ab n&rsquo;\u00e9tait m\u00eame pas si grave, surtout compte tenu de la nature des all\u00e9gations port\u00e9es contre lui \u00bb.<\/p>\n<\/blockquote>\n\n\n\n<p>La s\u00e9rie documentaire en plusieurs parties \u00ab Mr. McMahon \u00bb sera diffus\u00e9e sur Netflix \u00e0 partir du mercredi 25 septembre.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"p7FZkC8Mvm\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/09\/24\/vince-mcmahon-voulait-racheter-les-droits-sur-sa-serie-a-netflix-une-declaration-surprenante-de-lancien-chairman-de-la-wwe-et-plus\/\">Vince McMahon voulait racheter les droits sur sa s\u00e9rie \u00e0 Netflix! Une d\u00e9claration surprenante de l&rsquo;ancien Chairman de la WWE, et plus!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Vince McMahon voulait racheter les droits sur sa s\u00e9rie \u00e0 Netflix! Une d\u00e9claration surprenante de l&rsquo;ancien Chairman de la WWE, et plus!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/09\/24\/vince-mcmahon-voulait-racheter-les-droits-sur-sa-serie-a-netflix-une-declaration-surprenante-de-lancien-chairman-de-la-wwe-et-plus\/embed\/#?secret=odKpMSC9F3#?secret=p7FZkC8Mvm\" data-secret=\"p7FZkC8Mvm\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>D\u2019autres d\u00e9tails ont fait surface concernant la tr\u00e8s attendue s\u00e9rie documentaire \u00ab Mr. McMahon \u00bb. Les interviews que Vince McMahon a film\u00e9es pour la s\u00e9rie ont eu lieu avant sa \u00ab retraite \u00bb la premi\u00e8re fois. La WWE pense que des avertissements seraient inclus concernant de nombreuses t\u00eates parlantes pr\u00e9sent\u00e9es pour des interviews dans les&#8230;<\/p>\n","protected":false},"author":609,"featured_media":105109,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,100,23],"tags":[],"ppma_author":[295],"class_list":["post-105108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-tko","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/105108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=105108"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/105108\/revisions"}],"predecessor-version":[{"id":105110,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/105108\/revisions\/105110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/105109"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=105108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=105108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=105108"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=105108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}