{"id":104836,"date":"2024-09-16T13:34:59","date_gmt":"2024-09-16T17:34:59","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=104836"},"modified":"2024-09-16T13:47:58","modified_gmt":"2024-09-16T17:47:58","slug":"jbl-parle-de-son-retour-dans-le-ring-du-cote-de-la-tna","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/09\/16\/jbl-parle-de-son-retour-dans-le-ring-du-cote-de-la-tna\/","title":{"rendered":"JBL parle de son retour dans le ring du c\u00f4t\u00e9 de la TNA!"},"content":{"rendered":"\n<p>JBL ajoute \u00e0 son h\u00e9ritage de lutte professionnelle ces derni\u00e8res semaines.<\/p>\n\n\n\n<p>Apr\u00e8s sa carri\u00e8re post-active \u00e0 la WWE aux c\u00f4t\u00e9s du baron Corbin, la l\u00e9gende du Temple de la renomm\u00e9e de la WWE a refait surface ces derni\u00e8res semaines, faisant des apparitions surprise \u00e0 TNA Emergence 2024, TNA Victory Road 2024 et MLW Fightland 2024.<\/p>\n\n\n\n<p>Lors de son dernier week-end combo un-deux, avec des apparitions aux \u00e9missions de TNA et MLW dans des soir\u00e9es cons\u00e9cutives, la l\u00e9gende de la lutte professionnelle a parl\u00e9 de \u00ab\u00a0What&rsquo;s Next\u00a0\u00bb pour sa carri\u00e8re lors d&rsquo;une apparition sur l&rsquo;immense podcast pop.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00abJ&rsquo;esp\u00e8re faire quelque chose\u00bb<\/p>\n\n\n\n<p> \u00ab\u00a0Vous avez mentionn\u00e9 Baron Corbin, et je me sens mal parce que si vous allez bl\u00e2mer quelqu&rsquo;un, bl\u00e2mez-moi. Je suis le vieil homme. Je ne veux pas que ce soit mon dernier souvenir de la lutte. Si mon dernier souvenir \u00e9tait Rey Mysterio et 23 secondes, c&rsquo;est comme \u00e7a que je voulais sortir. \u00ab\u00a0<\/p>\n\n\n\n<p> \u00abLes von Erichs entraient dans le Temple de la renomm\u00e9e, c&rsquo;\u00e9tait au Texas. C&rsquo;\u00e9tait une chanson de cygne parfaite. Ensuite, je suis revenu et cela n&rsquo;a pas fonctionn\u00e9. Je ne veux pas que ce soit le dernier. Je ne sais pas ce que je vais faire. J&rsquo;ai quelques id\u00e9es, mais j&rsquo;esp\u00e8re que ce ne sera pas la chanson de cygne. \u00ab\u00a0<\/p>\n<\/blockquote>\n\n\n\n<p>D\u00e9couvrez l&rsquo;interview compl\u00e8te de JBL sur un \u00e9norme pop sur Apple.com.<\/p>\n\n\n\n<center><iframe allow=\"autoplay *; encrypted-media *; fullscreen *; clipboard-write\" frameborder=\"0\" height=\"175\" style=\"width:100%;max-width:660px;overflow:hidden;border-radius:10px;\" sandbox=\"allow-forms allow-popups allow-same-origin allow-scripts allow-storage-access-by-user-activation allow-top-navigation-by-user-activation\" src=\"https:\/\/embed.podcasts.apple.com\/us\/podcast\/huge-pop-with-donnie-dasilva-and-jimmy-korderas-episode\/id1313647764?i=1000669621031\"><\/iframe><\/center>\n\n\n\n<p>De plus, JBL continue de visiter des promotions en dehors de la WWE, semant parfois le chaos. Apr\u00e8s avoir particip\u00e9 \u00e0 l\u2019\u00e9v\u00e9nement Victory Road de la TNA vendredi, \u201cThe Wrestling God\u201d \u00e9tait pr\u00e9sent, lors de l\u2019\u00e9v\u00e9nement Fightland de Major League Wrestling.<\/p>\n\n\n\n<p>JBL est venu attaquer Mr. Thomas avec un \u201cClothesline from Hell\u201d, aidant ainsi Brock Anderson et C.W. Anderson \u00e0 rempoter leur match contre The Bomaye Fight Club. Il a suite murmur\u00e9 quelque chose dans l\u2019oreille de Brock Anderson.<\/p>\n\n\n\n<p>On a \u00e9galement vu JBL r\u00e9cemment \u00e0 la AAA et \u00e0 Game Changer Wrestling. Est-ce qu\u2019il pr\u00e9pare l\u2019arriv\u00e9e d\u2019un nouveau clan, et si oui \u00e0 quel endroit?<\/p>\n\n\n\n<p>Rappelons que JBL a un contrat de l\u00e9gende de la WWE mais sous la Triple H Era, il semble que des passes droites sont accord\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"FY5oGManSD\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/09\/14\/reprise-video-pour-le-ppv-tna-victory-road-2024\/\">Reprise Vid\u00e9o pour le PPV TNA Victory Road 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le PPV TNA Victory Road 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/09\/14\/reprise-video-pour-le-ppv-tna-victory-road-2024\/embed\/#?secret=eltziI6svb#?secret=FY5oGManSD\" data-secret=\"FY5oGManSD\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"SUv3OCH88O\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/09\/12\/reprise-video-pour-le-tna-impact-wrestling-du-12-septembre-2024\/\">Reprise Vid\u00e9o pour le TNA Impact Wrestling du 12 Septembre 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le TNA Impact Wrestling du 12 Septembre 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/09\/12\/reprise-video-pour-le-tna-impact-wrestling-du-12-septembre-2024\/embed\/#?secret=D3A03NmXiS#?secret=SUv3OCH88O\" data-secret=\"SUv3OCH88O\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>JBL ajoute \u00e0 son h\u00e9ritage de lutte professionnelle ces derni\u00e8res semaines. Apr\u00e8s sa carri\u00e8re post-active \u00e0 la WWE aux c\u00f4t\u00e9s du baron Corbin, la l\u00e9gende du Temple de la renomm\u00e9e de la WWE a refait surface ces derni\u00e8res semaines, faisant des apparitions surprise \u00e0 TNA Emergence 2024, TNA Victory Road 2024 et MLW Fightland 2024&#8230;.<\/p>\n","protected":false},"author":2,"featured_media":104837,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,77,4,41],"tags":[],"ppma_author":[287],"class_list":["post-104836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-hall-of-fame","category-news","category-tna-impact"],"authors":[{"term_id":287,"user_id":2,"is_guest":0,"slug":"jason","display_name":"Jason Desc\u00f4teaux","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/f64adf6d13198c3a532c061cecd8672089a1e9a3d07c702dffe886a7e55a15eb?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/104836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=104836"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/104836\/revisions"}],"predecessor-version":[{"id":104844,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/104836\/revisions\/104844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/104837"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=104836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=104836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=104836"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=104836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}