{"id":104761,"date":"2024-09-11T20:07:00","date_gmt":"2024-09-12T00:07:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=104761"},"modified":"2024-09-16T13:01:13","modified_gmt":"2024-09-16T17:01:13","slug":"resultats-et-video-pour-le-aew-dynamite-du-11-septembre-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/09\/11\/resultats-et-video-pour-le-aew-dynamite-du-11-septembre-2024\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AEW Dynamite du 11 Septembre 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/09\/11\/avant-gout-pour-le-aew-dynamite-du-11-septembre-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Dynamite, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>AEW Dynamite Lexington, Kentucky, 11 septembre 2024<\/strong><br>Les commentateurs sont Taz, Tony Schiavone et Excalibur.<\/p>\n\n\n\n<p>&#8211; Le show d\u00e9marre avec une vid\u00e9o de&nbsp;<strong>Jon Moxley.<\/strong>&nbsp;Ce dernier dit que Bryan Danielson n&rsquo;a pas la passion pour faire \u00e7a. Il y a deux ans ils ont pris la d\u00e9cision de construire quelque chose ensemble, quelque chose qu&rsquo;ils devaient en \u00eatre fi\u00e8re. Quelque chose qui n&rsquo;\u00e9tait pour l&rsquo;argent ou bien la reconnaissance. C&rsquo;\u00e9tait quelque chose qui valait simplement la peine. <\/p>\n\n\n\n<p>Moxley ajoute qu&rsquo;il ne voit que des \u00e9gos hors de contr\u00f4lent \u00e0 l&rsquo;AEW. Moxley dit qu&rsquo;ils sont ce qu&rsquo;ils sont, ils ne pr\u00e9tendent pas \u00eatre autre chose. Maintenant il bien exactement pourquoi Dieu l&rsquo;a mis ici. Il est le vrai roi de ce terrain. Aujourd&rsquo;hui il a choisi la guerre.<\/p>\n\n\n\n<p>&#8211; Darby Allin arrive en skateboard dans le stationnement interrieur de l&rsquo;ar\u00e9na.<\/p>\n\n\n\n<p>&#8211; Tony Schiavone est sur le ring et nous pr\u00e9sente&nbsp;<strong>Christian Cage<\/strong>&nbsp;avec le Patriarchy qui arrivent sur le ring. Schiavone dit que Christian Cage a gagn\u00e9 un Gauntlet Match pour avoir un contrat lui donnant un match de titre quand il veut et o\u00f9 il veut. Cage r\u00e9pond que son fils l&rsquo;a avis\u00e9 que dans la rue il se dit que Christian Cage a un aura infini. Avec ce contrat c&rsquo;est maintenant ind\u00e9niable. La perte des titres Trios AEW n&rsquo;a pas \u00e9t\u00e9 comme pr\u00e9vu, mais la Famille s&rsquo;est r\u00e9organis\u00e9e pour le Gauntlet Match. Lorsque Killswitch l&rsquo;a pris par le cou, Killswitch a r\u00e9alis\u00e9 pr\u00e9cis\u00e9ment ce qu&rsquo;il \u00e9tait et ce qu&rsquo;il doit faire. Cage dit que Killswitch est un monstre, un tuer et Killswitch lui revient. Schiavone dit qu&rsquo;\u00e0 All Out Christian Cage a essay\u00e9 d&rsquo;encaisser son contrat, mais ce n&rsquo;est pas arriv\u00e9. La foule chante \u00a0\u00bbLuchasaurus\u00a0\u00bb. <\/p>\n\n\n\n<p>Cage ajoute que le nom est Killswitch.&nbsp;Cage dit qu&rsquo;il \u00e9tait pr\u00eat \u00e0 encaisser son contrat et le rendre officiel, mais il a r\u00e9alis\u00e9 que ce n&rsquo;\u00e9tait pas le bon moment. Les jours de Danielson sont compt\u00e9s.&nbsp;Il va battre Danielson si fort que Danielson aurait souhait\u00e9 que Brie Bella souffre de ETC (d\u00e9g\u00e9n\u00e9rescence progressive des cellules c\u00e9r\u00e9brales) pour qu&rsquo;elle ne r\u00e9alise pas \u00e0 quel point Danielson \u00e9tait une honte comme champion. Cage dit qu&rsquo;il est l&rsquo;image de TBS maintenant et pour toujours, et maintenant il est le futur champion mondial AEW.<\/p>\n\n\n\n<p>&#8211; En coulisses, Renee Paquette est avec le clan de Don Callis et Will Ospreay. Callis dit qu&rsquo;il a eu cette bonne id\u00e9e pour Ospreay. Ospreay a remport\u00e9 tous les Casino Gauntlet Match. Alors qu&rsquo;est-ce qui ne serait pas mieux qu&rsquo;un Ospreay et Kyle Fletcher dans le Casino Gauntlet Match pour ce soir ?<\/p>\n\n\n\n<p> Ospreay r\u00e9pond qu&rsquo;il pr\u00e9f\u00e8re rester concentrer sur Ricochet. Callis dit qu&rsquo;il a rendu faveur \u00e0 Ospreay et maintenant c&rsquo;est \u00e0 son tour, en prime avec son ami Fletcher.&nbsp;Fletcher dit qu&rsquo;il n&rsquo;en peut plus de ne jamais devenir champion. Ils ont fait \u00e9quipe dans de nombreux pays, il adorait devenir champion ici avec lui. Ospreay accepte.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>TNT Championship <\/strong><\/p>\n\n\n\n<p><strong>Jack Perry \u00a9 vs Lio Rush&nbsp;<em>accompagn\u00e9 d&rsquo;Action Andretti<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Perry bloque un saut Springboard de Rush avec un coup de genou. Perry enchaine avec un Running Knee pour le compte de trois sur Rush.<\/p>\n\n\n\n<p><em>Gagnant : Jack Perry<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, Alex Marvez arr\u00eate Jack Perry pour avoir ses commentaires sur All Out. Perry dit que des gens comme lui se font crucifier pour revenir le lendemain. Perry quitte dans sa voiture.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur l&rsquo;histoire entre Adam Page et Swerve Strickland.<\/p>\n\n\n\n<p>&#8211; En coulisses, Renee Paquette est avec<strong>&nbsp;Adam Page<\/strong>&nbsp;pour avoir ses commentaires sur All Out suite \u00e0 sa victoire. Adam Page dit que s&rsquo;il aurait trouv\u00e9 1 000 maisons de Swerve Strickland, il aurait br\u00fbl\u00e9 toutes les maisons. Et il aurait pu passer l&rsquo;\u00e9ternit\u00e9 \u00e0 punir Strickland \u00e0 All Out pour ce qu&rsquo;il a fait \u00e0 sa famille. Il pensait vraiment tous les mots qu&rsquo;il a dit et il pensait vraiment chacune des goutes de sang qui ont coul\u00e9 \u00e0 All Out.&nbsp;Maintenant si quelqu&rsquo;un se met entre lui et Strickland, pour prot\u00e9ger Strickland de lui, il va trouver cette personne et lui fera mal.<\/p>\n\n\n\n<p>Adam Page marche plus loin et frappe un catcheur local. Page croise Top Flight et ensuite le Dark Order. Jeff Jarrett arr\u00eate Adam Page. Jarrett dit que sa famille a souvent vu des gars comme Page. Oui Page veut aller plus loin, mais \u00e7a termine toujours avec des remords et des regrets. Page va regretter le jour o\u00f9 il a mis ses mains sur sa femme. Page va r\u00e9aliser que le pire salopard est celui qu&rsquo;il va voir dans le miroir. Adam Page commence \u00e0 rouer de coups Jarrett ! Des officiels arrivent pour stopper Page.<\/p>\n\n\n\n<p>&#8211; Private Party et Komander arrivent sur le ring pour un Trios Match contre trois catcheurs locaux, mais&nbsp;le Blackpool Combat Club arrive sur le ring pour attaquer&nbsp;les six catcheurs avant le d\u00e9but du match. PAC prend le micro et dit qu&rsquo;assez est assez. Cette compagnie est cass\u00e9e. C&rsquo;\u00e9tait in\u00e9vitable ce qui est arriv\u00e9 \u00e0 All Out. Il a \u00e9t\u00e9 perdu pendant un long moment, mais ce n&rsquo;est plus le cas. Maintenant il a quelque chose en quoi il peut croire, une raison de vivre. Cette compagnie pue la merde.<\/p>\n\n\n\n<p>&#8211; Le clan de Chris Jericho arrive dans le parking interieur, Y2J dit que c&rsquo;est une belle journ\u00e9e pour \u00eatre dans le Learning Cree. Il a sa belle voiture, sa famille et surtout son veston sur lequel Orange Cassidy a vers\u00e9 du jus d&rsquo;orange. C&rsquo;est pour cette raison qu&rsquo;il a pris le sac \u00e0 dos \u00e0 Orange Cassidy car il veut son argent.&nbsp;Il n&rsquo;a pas trouv\u00e9 de l&rsquo;argent dans le sac, mais il a trouv\u00e9 quelque chose de tr\u00e8s int\u00e9ressant dedans qu&rsquo;il va d\u00e9voiler un peu plus tard \u00e0 tout le monde.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Ricochet vs Sammy Guevara<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Guevara veut faire son GTH, mais Ricochet le bloque et lui porte un coup de genou. Ricochet enchaine avec son Vertigo pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Ricochet<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, Ricochet c\u00e9l\u00e8bre sa victoire, mais Beast Mortos d\u00e9barque et lui fait un Spear ! Sammy Guevara entre sur le ring avec une chaise pour faire peur \u00e0 Mortos et il prend la fuite. Guevara aide Ricochet \u00e0 se relever et les deux se serrent la main.<\/p>\n\n\n\n<p>&#8211;  Renee Paquette est avec Kazuchika Okada pour savoir ce qui l&rsquo;attend pour la suite apr\u00e8s All Out. Okada dit qu&rsquo;All Out \u00e9tait la bataille la plus difficile de sa vie, mais il l&rsquo;a fait, c&rsquo;\u00e9tait si facile. <\/p>\n\n\n\n<p>Don Callis et Konosuke Takeshita arrivent. Callis dit qu&rsquo;Okada a gagn\u00e9, mais il l&rsquo;a pas fait le compte sur Takeshita. Okada dit que Takeshita pourra \u00eatre champion, mais ce ne sera pas le Continental Champion&#8230; garce !<\/p>\n\n\n\n<p>&#8211;&nbsp;<strong>Darby Allin<\/strong>&nbsp;arrive sur le ring et prend le micro. Allin dit quelqu&rsquo;un le cherchait et maintenant il est ici. La musique de Jon Moxley se lance et il arrive avec Marina Shafir sur le ring. Moxley dit qu&rsquo;il ne sait pas ce que Allin a entendu, mais rien n&rsquo;a chang\u00e9 entre eux. Allin dit que \u00e7a suffit. Il a beaucoup de choses qu&rsquo;il veut parler. Ils ne ressemblent pas \u00e0 des Superstars. Il \u00e9tait un sans-abri \u00e0 laver de la vaisselle. Il ne prend rien pour acquis, il ne sait jamais quand \u00e7a va se terminer. <\/p>\n\n\n\n<p>Allin ajoute qu&rsquo;il a regard\u00e9 Jon Moxley et il admirait Moxley car il ne voulait jamais se vendre ou bien changer. Depuis le d\u00e9but Moxley catchait dans des lyc\u00e9es sur la sc\u00e8ne ind\u00e9pendante. Il a rencontr\u00e9 Moxley dans un lyc\u00e9e, il \u00e9tait si nerveux de l&rsquo;affronter, il a perdu mais il a gagn\u00e9 la confiance en l&rsquo;affrontant. Quelqu&rsquo;un qui peut nommer comme une famille, mais apr\u00e8s ce que Moxley a fait \u00e0 Bryan Danielson ce n&rsquo;est plus le cas. Alors pourquoi Moxley a nomm\u00e9 son nom ?<\/p>\n\n\n\n<p>Moxley propose que Allin a une chance pour le titre mondial \u00e0 Grand Slam, mais \u00e7a n&rsquo;arrivera pas car le champion mondial n&rsquo;est pas disponible. C&rsquo;est une bonne chose car Allin n&rsquo;est pas pr\u00eat pour \u00eatre un champion mondial. Allin n&rsquo;\u00e9tait pas pr\u00eat il y a 5 ans et Allin n&rsquo;est pas pr\u00eat aujourd&rsquo;hui. Alors Allin devra lui donner cette chance pour le titre mondial. Allin demande si Moxley est stupide ou s&rsquo;il a recommenc\u00e9 \u00e0 boire. Allin dit qu&rsquo;il a gagn\u00e9 cette chance, il ne va pas simplement lui donner. Si Moxley le veut \u00e0 ce point, Moxley peut faire quelque chose pour l&rsquo;avoir. Moxley dit qu&rsquo;\u00e0 Grand Slam il veut affronter Darby Allin avec sa chance pour le titre mondial en jeu.&nbsp;Allin ne sera jamais champion, il n&rsquo;a pas le temps de tout lui expliquer, mais Allin doit le croire. Cette chance pour le titre sera la sienne et cette fois-ci il va lui apprendre la le\u00e7on \u00e0 la dure. Allin dit qu&rsquo;il accepte.<\/p>\n\n\n\n<p>&#8211; En coulisses, Alex Marvez est avec Christopher Daniels pour avoir sa r\u00e9action. Daniels dit que Darby Allin prend toujours des risques, mais cette fois-ci \u00e7a semble encore trop pour rien. Nigel McGuinness arrive et dit \u00e0 Daniels de le suivre car il voudra entendre ce que Tony Khan va lui dire.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW Women&rsquo;s Eliminator <\/strong><\/p>\n\n\n\n<p><strong>Mariah May vs Queen Aminata<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, May fait un Running Knee \u00e0 Aminata et enchaine avec son Storm Zero pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Mariah May<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, May prend le micro et dit qu&rsquo;elle n&rsquo;a toujours pas eu sa c\u00e9l\u00e9bration pour le titre mondial AEW. Quelque chose lui manque, quelqu&rsquo;un lui manque. Elle demande \u00e0 Mina Shirakawa de revenir par piti\u00e9.<\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve les Young Bucks. Matthew Jackson dit qu&rsquo;en lan\u00e7ant la compagnie ils ont dit qu&rsquo;ils voulaient la meilleure division par \u00e9quipe. Mais en fait ils parlaient d&rsquo;eux-m\u00eames. Au lancement de l&rsquo;AEW, on aurait pu croire qu&rsquo;ils ne feraient que le boulot de directeurs, mais non c&rsquo;est eux qui repr\u00e9sentent encore la division. Il n&rsquo;y a aucune \u00e9quipe capable des remplacer. Nicholas dit que c&rsquo;est pour cette raison qu&rsquo;ils ont organis\u00e9 ce Casino Gauntlet Match. L&rsquo;\u00e9quipe gagnante viendra les affronter \u00e0 Grand Slam et ils vont suivre le tout en live.<\/p>\n\n\n\n<p>&#8211; Le Learning Tree arrive sur le ring.<\/p>\n\n\n\n<p><strong>Chris Jericho, Bryan Keith et Big Bill vs Bronson, Boulder et Jacked Jameson<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Keith fait son Cutter du coin \u00e0 Jameson et Jericho prend la tag pour faire le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Chris Jericho, Bryan Keith et Big Bill<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, Jericho prend le micro pour saluer tout le monde. Jericho dit qu&rsquo;il est ici dans son veston sur mesure qu&rsquo;il a pay\u00e9 7 000$. Un veston qu&rsquo;Orange Cassidy a ruin\u00e9 avec du jus d&rsquo;orange il y a 4 ans. Il veut retrouver son 7 000$, mais on dirait que Cassidy ne veut pas lui redonner. Alors il a pris le sac \u00e0 dos de Cassidy et il a trouv\u00e9 quelque chose d&rsquo;int\u00e9ressant, une photo de Cassidy avec ses anciens meilleurs amis. C&rsquo;est le probl\u00e8me de Cassidy, Cassidy est toujours obs\u00e9d\u00e9 avec l&rsquo;amiti\u00e9. Alors voici la le\u00e7on, il n&rsquo;y a aucune amiti\u00e9 dans le catch. Si on pense avoir un ami, on se fait abuser par d\u00e9faut. <\/p>\n\n\n\n<p>Jericho ajoute que c&rsquo;est le moment pour Cassidy de le payer. Orange Cassidy d\u00e9barque sur le TitanTron. Cassidy dit qu&rsquo;il n&rsquo;a pas encore le 7 000$ au complet, mais ses gars vont lui amener. Mark Briscoe et Kyle O&rsquo;Reilly conduisent un tracteur et versent 7 000$ en pi\u00e8ce dans la voiture de Jericho.<\/p>\n\n\n\n<p>&#8211; <strong>Nigel McGuinness<\/strong>&nbsp;est sur le ring. McGuinness dit qu&rsquo;il veut s&rsquo;exprimer sur un sujet. Avec Darby Allin qui met sa chance pour le titre mondial en jeu \u00e0 Grand Slam, \u00e7a signifie qu&rsquo;il n&rsquo;y aura pas de match de titre mondial AEW. Ce qui est bon pour le champion qui doit encore chercher de l&rsquo;air. Mais il croit qu&rsquo;un \u00e9v\u00e9nement comme Grand Slam devrait au moins avoir le champion mondial dans un match. Ce qui le m\u00e8ne \u00e0 ce contrat. Pendant combien d&rsquo;ann\u00e9es il a \u00e9t\u00e9 forc\u00e9 de regarder la carri\u00e8re de Danielson sur la touche ? Un succ\u00e8s qui aurait d\u00fb \u00eatre le sien. Bryan Danielson a peur de lui, Bryan Danielson a peur du match que tout le monde veut voir, mais Tony Khan n&rsquo;a pas peur. Tony Khan sait o\u00f9 est l&rsquo;argent.&nbsp;Alors \u00e0 Grand Slam nous aurons Bryan Danielson contre Nigel McGuinness. McGuinness dit qu&rsquo;il peut garantir que Oasis va l&rsquo;amener sur le ring, mais est-ce que Danielson va le rejoindre pour le Final Countdown ou bien nous verrons le dernier match du l\u00e2che am\u00e9ricain ?<\/p>\n\n\n\n<p>&#8211; En vid\u00e9o, on retrouve HOOK qui dit qu&rsquo;il a du respect pour Roderick Strong. Mais son respect est perturb\u00e9 lorsqu&rsquo;il est attaqu\u00e9 par les amis de Strong. Il vient de retrouver le titre FTW en battant une l\u00e9gende \u00e0 All In et maintenant il challenge Strong. Il attend la r\u00e9ponse de Strong. Strong peut choisir le moment.<\/p>\n\n\n\n<p>&#8211; Les Young Bucks prennent place sur la sc\u00e8ne pour le prochain match.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Casino Gauntlet Match<\/strong><br><em>Les gagnants vont affronter les Young Bucks \u00e0 Grand Slam.<\/em><\/p>\n\n\n\n<p><strong>Participants : FTR (Cash Wheeler et Dax Harwood), Will Ospreay et Kyle Fletcher, Vincent et Dutch, Matt Taven et Mike Bennett, The Acclaimed (Max Caster et Anthony Bowens), MxM Collection (Mansoor et Mason Madden), Top Flight (Darius et Dante Martin), Outrunners (Turbo Floyd et Truth Magnum), et Grizzled Young Veterans (James Drake et Zack Gibson)<\/strong><\/p>\n\n\n\n<p>Vers la fin du combat, les Grizzled Young Veterans font leur entr\u00e9e, FTR d\u00e9cide de quitter le ring et aller les affronter sur la sc\u00e8ne.<\/p>\n\n\n\n<p>En fin de match, Fletcher bloque un Splash de Dante avec ses genoux. Ospreay en profite pour faire son Hidden Blade \u00e0 Dante. Fletcher fait le compte de trois \u00e0 Dante pendant qu&rsquo;Ospreay bloque les catcheurs \u00e0 stopper le compte.<\/p>\n\n\n\n<p><em>Gagnants : Will Ospreay et Kyle Fletcher<\/em><\/p>\n\n\n\n<p>Le show se termine avec un face \u00e0 face entre les Young Bucks et l&rsquo;\u00e9quipe gagnante.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2024\/09\/11\/avant-gout-pour-le-aew-dynamite-du-11-septembre-2024\/\" target=\"_blank\">Pour voir Dynamite, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"fHa7JFZxtV\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/09\/11\/avant-gout-pour-le-aew-dynamite-du-11-septembre-2024\/\">Reprise Vid\u00e9o et Programme pour le AEW Dynamite du 11 Septembre 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le AEW Dynamite du 11 Septembre 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/09\/11\/avant-gout-pour-le-aew-dynamite-du-11-septembre-2024\/embed\/#?secret=kKDb1YUmuo#?secret=fHa7JFZxtV\" data-secret=\"fHa7JFZxtV\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>AEW Dynamite Lexington, Kentucky, 11 septembre 2024Les commentateurs sont Taz, Tony Schiavone et Excalibur. &#8211; Le show d\u00e9marre avec une vid\u00e9o de&nbsp;Jon Moxley.&nbsp;Ce dernier dit que Bryan Danielson n&rsquo;a pas la passion pour faire \u00e7a. Il y a deux ans ils ont pris la d\u00e9cision de construire quelque chose ensemble, quelque chose qu&rsquo;ils devaient en&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":104762,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,50,30,21,83],"tags":[],"ppma_author":[297],"class_list":["post-104761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-dynamite","category-ex-wwe","category-resultats","category-wcw"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/104761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=104761"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/104761\/revisions"}],"predecessor-version":[{"id":104821,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/104761\/revisions\/104821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/104762"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=104761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=104761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=104761"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=104761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}