{"id":104657,"date":"2024-09-08T15:20:00","date_gmt":"2024-09-08T19:20:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=104657"},"modified":"2024-09-09T15:22:28","modified_gmt":"2024-09-09T19:22:28","slug":"une-lutteuse-retiree-par-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/09\/08\/une-lutteuse-retiree-par-la-wwe\/","title":{"rendered":"Une lutteuse retir\u00e9e par la WWE!"},"content":{"rendered":"\n<p>Il semble bien que Kiana James a perdu sa place dans le roster de la WWE.<\/p>\n\n\n\n<p>C&rsquo;est le PWI qui nous informe que Kiana James a \u00e9t\u00e9 retir\u00e9e du roster des catcheuses actives de la WWE au niveau de la liste en interne selon leurs informations. Elle se retrouve actuellement dans la cat\u00e9gorie \u00ab\u00a0divers\u00a0\u00bb qui permet de r\u00e9pertorier les Superstars bless\u00e9es, \u00e0 temps partiel ou bien dans une situation particuli\u00e8re comme une blessure.<\/p>\n\n\n\n<p>La raison pr\u00e9cise de ce changement pour Kiana James est pr\u00e9sentement inconnue. Il faut remonter au mois de juin 2024 \u00e0 RAW pour les qualifications de Money in the Bank pour voir son dernier match.<\/p>\n\n\n\n<p>Seul le temps nous en dira plus au sujet du futur de Kiana James \u00e0 la WWE. Depuis son transfert de NXT vers RAW lors du dernier WWE Draft, elle n&rsquo;a pas eu la chance de faire beaucoup de matchs, seulement deux \u00e0 RAW.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Il semble bien que Kiana James a perdu sa place dans le roster de la WWE. C&rsquo;est le PWI qui nous informe que Kiana James a \u00e9t\u00e9 retir\u00e9e du roster des catcheuses actives de la WWE au niveau de la liste en interne selon leurs informations. Elle se retrouve actuellement dans la cat\u00e9gorie \u00ab\u00a0divers\u00a0\u00bb qui&#8230;<\/p>\n","protected":false},"author":4,"featured_media":104658,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,85,23],"tags":[],"ppma_author":[292],"class_list":["post-104657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-nxt","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/104657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=104657"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/104657\/revisions"}],"predecessor-version":[{"id":104659,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/104657\/revisions\/104659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/104658"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=104657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=104657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=104657"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=104657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}