{"id":104359,"date":"2024-08-30T12:38:39","date_gmt":"2024-08-30T16:38:39","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=104359"},"modified":"2024-09-02T18:05:17","modified_gmt":"2024-09-02T22:05:17","slug":"kickoff-du-wwe-bash-in-berlin-2024-la-conference-de-presse-avant-le-grand-soir","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/08\/30\/kickoff-du-wwe-bash-in-berlin-2024-la-conference-de-presse-avant-le-grand-soir\/","title":{"rendered":"Kickoff du WWE Bash In Berlin 2024, la conf\u00e9rence de Presse avant le grand soir!"},"content":{"rendered":"\n<p>La WWE va pr\u00e9senter son Kickoff de WWE Bash In Berlin 2024 le 30 ao\u00fbt.<\/p>\n\n\n\n<p>Il s&rsquo;agit de la conf\u00e9rence de presse d&rsquo;avant le PLE qui est pr\u00e9sent\u00e9e en direct du <strong>Uber Platz<\/strong> juste devant le <strong>Uber Arena<\/strong> de Berlin qui va recevoir le ce show tant attendu. L&rsquo;acc\u00e8s \u00e9tait gratuit pour tous les fans qui voulaient y assister.<\/p>\n\n\n\n<p> Damian Priest, Rhea Ripley, Liv Morgan, Dominik Mysterio, Gunther, Randy Orton, CM Punk et Drew McIntyre \u00e9tait pr\u00e9sent. Il s&rsquo;agit du dernier moment o\u00f9 les WWE Superstars feront des face \u00e0 face avant Bash in Berlin 2024.<\/p>\n\n\n\n<p>Nous aurons la transcriptions de certains passages plus tard, en attendant vous pouvez le voir ci-dessous:<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/DJbEON1Nwfw?si=S4jzvoOQiAMlIJnW\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La WWE va pr\u00e9senter son Kickoff de WWE Bash In Berlin 2024 le 30 ao\u00fbt. Il s&rsquo;agit de la conf\u00e9rence de presse d&rsquo;avant le PLE qui est pr\u00e9sent\u00e9e en direct du Uber Platz juste devant le Uber Arena de Berlin qui va recevoir le ce show tant attendu. L&rsquo;acc\u00e8s \u00e9tait gratuit pour tous les fans&#8230;<\/p>\n","protected":false},"author":4,"featured_media":104360,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105,20,23],"tags":[108,14,109,110,107],"ppma_author":[292],"class_list":["post-104359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bash","category-videos","category-wwe","tag-bashinberlin","tag-en-direct","tag-ple","tag-ppv","tag-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/104359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=104359"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/104359\/revisions"}],"predecessor-version":[{"id":104362,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/104359\/revisions\/104362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/104360"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=104359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=104359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=104359"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=104359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}