{"id":103971,"date":"2024-08-19T13:37:52","date_gmt":"2024-08-19T17:37:52","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=103971"},"modified":"2024-08-19T13:37:54","modified_gmt":"2024-08-19T17:37:54","slug":"bien-que-ce-fut-officieux-cest-maintenant-officiel-que-john-cena-sera-present-pour-le-premier-raw-sur-netflix","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/08\/19\/bien-que-ce-fut-officieux-cest-maintenant-officiel-que-john-cena-sera-present-pour-le-premier-raw-sur-netflix\/","title":{"rendered":"Bien que ce f\u00fbt officieux, C&rsquo;est Maintenant Officiel que John Cena sera Pr\u00e9sent pour le Premier RAW sur NETFLIX!"},"content":{"rendered":"\n<p>Il en avait parl\u00e9 \u00e0 son dernier passage \u00e0 la WWE mais c&rsquo;est maintenant confirm\u00e9 par le principal int\u00e9ress\u00e9.<\/p>\n\n\n\n<p>Le 16 fois champion mondial de la WWE a donc r\u00e9it\u00e9r\u00e9 qu&rsquo;il sera pr\u00e9sent lors du tout premier RAW  qui sera diffus\u00e9 sur Netflix, pr\u00e9vu pour le 6 janvier 2025. <\/p>\n\n\n\n<p>Cet \u00e9v\u00e9nement sera l&rsquo;un des\u00a036 shows\u00a0auxquels The Champ participera l&rsquo;ann\u00e9e prochaine.<\/p>\n\n\n\n<p>Dans une interview avec Complex,\u00a0John Cena\u00a0a d\u00e9clar\u00e9 :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Je peux vous assurer que je serai pr\u00e9sent pour le lancement de RAW sur Netflix.<\/p>\n\n\n\n<p> Je pense que c&rsquo;est le 6 janvier. Je n&rsquo;en suis pas s\u00fbr, mais je crois que c&rsquo;est le cas. C&rsquo;est un jour historique pour la WWE. Je suis extr\u00eamement fier de la WWE. <\/p>\n\n\n\n<p>J&rsquo;adore ce partenariat. J&rsquo;adore les deux entreprises, la WWE et Netflix, et c&rsquo;est un \u00e9v\u00e9nement que je ne manquerai pas. Je serai l\u00e0.\u00a0\u00bb<\/p>\n<\/blockquote>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/ECra8YpHr8M?si=59UxCglaMlh4Afkl\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Il en avait parl\u00e9 \u00e0 son dernier passage \u00e0 la WWE mais c&rsquo;est maintenant confirm\u00e9 par le principal int\u00e9ress\u00e9. Le 16 fois champion mondial de la WWE a donc r\u00e9it\u00e9r\u00e9 qu&rsquo;il sera pr\u00e9sent lors du tout premier RAW qui sera diffus\u00e9 sur Netflix, pr\u00e9vu pour le 6 janvier 2025. Cet \u00e9v\u00e9nement sera l&rsquo;un des\u00a036 shows\u00a0auxquels&#8230;<\/p>\n","protected":false},"author":4,"featured_media":103973,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,23],"tags":[],"ppma_author":[292],"class_list":["post-103971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/103971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=103971"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/103971\/revisions"}],"predecessor-version":[{"id":103974,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/103971\/revisions\/103974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/103973"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=103971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=103971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=103971"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=103971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}