{"id":103889,"date":"2024-08-15T12:50:00","date_gmt":"2024-08-15T16:50:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=103889"},"modified":"2024-08-15T13:57:18","modified_gmt":"2024-08-15T17:57:18","slug":"damien-priest-a-cru-quil-allait-se-faire-libere-quand-edge-est-parti-la-wwe-fait-un-pas-de-recul-concernant-le-judgment-day-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/08\/15\/damien-priest-a-cru-quil-allait-se-faire-libere-quand-edge-est-parti-la-wwe-fait-un-pas-de-recul-concernant-le-judgment-day-et-plus\/","title":{"rendered":"Damien Priest a cru qu&rsquo;il allait se faire lib\u00e9r\u00e9 quand Edge est parti! La WWE fait un pas de recul concernant le Judgment Day, et plus!"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>&#8211; Quelques heures avant le dernier RAW, nous \u00e9voquions un\u00a0possible changement de nom pour le Judgment Day\u00a0suite au d\u00e9part de Rhea Ripley et Damian Priest, et l&rsquo;arriv\u00e9e de Liv Morgan. L&rsquo;une des id\u00e9es pour le nouveau nom du groupe \u00e9tait \u00ab\u00a0Street Trash\u00a0\u00bb.<\/p>\n\n\n\n<p>Cependant, ce nom n&rsquo;a pas \u00e9t\u00e9 bien re\u00e7u par l&rsquo;Univers de la WWE sur les r\u00e9seaux sociaux, poussant visiblement la compagnie \u00e0 revoir sa d\u00e9cision. Selon WrestleVotes,\u00a0la WWE a finalement choisi de conserver le nom \u00ab\u00a0Judgment Day\u00a0\u00bb.<\/p>\n\n\n\n<p>Il est \u00e9galement rapport\u00e9 que \u00ab\u00a0Street Trash\u00a0\u00bb avait \u00e9t\u00e9 propos\u00e9 par Finn Balor, avec du merchandising d\u00e9j\u00e0 en pr\u00e9paration. En revanche, nous devrions entendre ce nom \u00e0 l&rsquo;avenir puisqu&rsquo;il sera int\u00e9gr\u00e9 \u00e0 l&rsquo;image du groupe.<\/p>\n\n\n\n<p>&#8211; Et parlant du Judgment Day,  pour ceux qui l&rsquo;aurait oubli\u00e9, le groupe a \u00e9t\u00e9 fond\u00e9 par Edge et Damian Priest en avril 2022. Peu apr\u00e8s, Rhea Ripley a rejoint le groupe, mais en juin 2022, Edge a \u00e9t\u00e9 \u00e9vinc\u00e9 du clan lorsque Finn Balor est arriv\u00e9 pour ensuite faire un dernier match \u00e0 Toronto avant de rejoindre la AEW et lutter sous son vrai nom d&rsquo;Adam Copeland\u00a0. <\/p>\n\n\n\n<p>Dans une r\u00e9cente interview avec le Sports Illustrated, Damian Priest a \u00e9voqu\u00e9 le moment o\u00f9 il a appris qu&rsquo;Edge allait quitter le Judgment Day. Il se souvient que tous les membres du groupe \u00e9taient frustr\u00e9s, et il craignait m\u00eame d&rsquo;\u00eatre licenci\u00e9 par la WWE.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0C&rsquo;est Edge qui m&rsquo;a annonc\u00e9 qu&rsquo;il quittait le groupe. Il a attendu de me le dire apr\u00e8s un show t\u00e9l\u00e9. Je croyais que c&rsquo;\u00e9tait fini, j&rsquo;\u00e9tais vraiment \u00e9nerv\u00e9. Quand Rhea [Ripley] l&rsquo;a appris, elle \u00e9tait encore plus \u00e9nerv\u00e9e que moi. Edge l&rsquo;\u00e9tait aussi. Je lui parle toujours, il nous soutenait beaucoup.<\/p>\n\n\n\n<p>Quand il m&rsquo;a appris la nouvelle, je me rappelle qu&rsquo;il a dit : &lsquo;Tout \u00e7a pour rien.&rsquo; Et j&rsquo;ai r\u00e9p\u00e9t\u00e9 : &lsquo;Pour rien.&rsquo; C&rsquo;est ce que j&rsquo;ai ressenti \u00e0 l&rsquo;\u00e9poque. J&rsquo;attendais qu&rsquo;on m&rsquo;appelle pour mon licenciement. \u00c9videmment, \u00e7a s&rsquo;est pass\u00e9 autrement.\u00a0\u00bb<\/p>\n<\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211; Quelques heures avant le dernier RAW, nous \u00e9voquions un\u00a0possible changement de nom pour le Judgment Day\u00a0suite au d\u00e9part de Rhea Ripley et Damian Priest, et l&rsquo;arriv\u00e9e de Liv Morgan. L&rsquo;une des id\u00e9es pour le nouveau nom du groupe \u00e9tait \u00ab\u00a0Street Trash\u00a0\u00bb. Cependant, ce nom n&rsquo;a pas \u00e9t\u00e9 bien re\u00e7u par l&rsquo;Univers de la WWE&#8230;<\/p>\n","protected":false},"author":609,"featured_media":103890,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,30,77,4,43,23],"tags":[],"ppma_author":[295],"class_list":["post-103889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-ex-wwe","category-hall-of-fame","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/103889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=103889"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/103889\/revisions"}],"predecessor-version":[{"id":103891,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/103889\/revisions\/103891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/103890"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=103889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=103889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=103889"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=103889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}