{"id":103860,"date":"2024-08-14T20:23:00","date_gmt":"2024-08-15T00:23:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=103860"},"modified":"2024-08-17T11:16:07","modified_gmt":"2024-08-17T15:16:07","slug":"resultats-et-video-pour-le-aew-dynamite-du-14-aout-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/08\/14\/resultats-et-video-pour-le-aew-dynamite-du-14-aout-2024\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AEW Dynamite du 14 Ao\u00fbt 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2024\/08\/14\/avant-gout-pour-le-aew-dynamite-du-14-aout-2024\/\" target=\"_blank\"><strong>Pour voir Dynamite, cliquez ici.<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW Dynamite Norfolk, Virginie, 14 ao\u00fbt 2024<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Taz, Tony Schiavone et Excalibur.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>TBS Championship <\/strong><\/p>\n\n\n\n<p><strong>Mercedes Mon\u00e9 <em>\u00a9 &nbsp;acc de Kamille<\/em>&nbsp;vs Hikaru Shida<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Mon\u00e9 menace d&rsquo;utiliser un Kendo Stick, l&rsquo;arbitre lui enl\u00e8ve. Kamille en profite pour faire une Big Boot \u00e0 Shida qui \u00e9tait en ringside. Kamille la repousse sur le ring. Mon\u00e9 enchaine avec son Mon\u00e9 Maker pour le compte de trois sur Shida.<\/p>\n\n\n\n<p><em>Gagnante : Mercedes Mon\u00e9<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, la musique de Britt Baker commence. Kamille veut l&rsquo;attendre sur la rampe, mais personne n&rsquo;arrive. Kamille voit dans la foule une personne masqu\u00e9e comme Britt Baker la derni\u00e8re fois et l&rsquo;attaque, mais ce n&rsquo;est pas Baker. Baker arrive par l&rsquo;autre c\u00f4t\u00e9 et pousse Mon\u00e9 au sol. Baker veut lui appliquer un Lock Jaw, mais Kamille tire Mon\u00e9 pour la sortir du ring et la sauver.<\/p>\n\n\n\n<p>&#8211; En coulisses, Renee Paquette est avec le clan de Jeff Jarrett pour avoir leurs commentaires sur Adam Page. Lethal dit qu&rsquo;ils n&rsquo;aiment pas Page comme Page ne l&rsquo;aime pas. Adam Page d\u00e9barque et commence \u00e0 rouer de coups tout le monde. Lethal et Page vont se battre pr\u00e8s de la sc\u00e8ne puis vont sur le ring pour lancer le match.<\/p>\n\n\n\n<p><strong>Adam Hangman Page vs Jay Lethal<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Lethal r\u00e9siste \u00e0 un compte rapide, mais Page lui fait une Clothesline. Page enchaine avec son Buckshot Clothesline pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Adam Page<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Lethal re\u00e7oit des soins du m\u00e9decin.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre MJF et Will Ospreay. La semaine prochaine, tous les deux se feront un face \u00e0 face.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, en coulisses, PAC dit que ce n&rsquo;est pas Will Ospreay qui est l&rsquo;aspirant pour le titre International ou bien \u00a0\u00bbAmerican\u00a0\u00bb. C&rsquo;est lui l&rsquo;aspirant, mais Will Ospreay est pass\u00e9 dans son dos pour demander un match \u00e0 Tony Khan. Il ne peut plus endurer cette manipulation. C&rsquo;\u00e9tait son billet pour All In, mais il aura sa vengeance.&nbsp;Peu importe qui quittera All In comme champion, deux semaines plus tard il va l&rsquo;affronter \u00e0 AEW All Out. Il va prendre ce qui lui revient et montrer ce qu&rsquo;il est capable de faire.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur l&rsquo;ascension de Darby Allin jusqu&rsquo;\u00e0 l&rsquo;AEW. Allin explique qu&rsquo;il auirait aim\u00e9 voir Jack Perry vir\u00e9 pour tout ce qu&rsquo;il a fait, mais \u00e0 All In il va en terminer avec Perry pour de bon.<\/p>\n\n\n\n<p>&#8211; Darby Allin arrive sur le ring pour son match, mais Jack Perry arrive et le charge avec un Running Knee ! Perry d\u00e9cide de l&rsquo;amener en coulisses o\u00f9 les deux catcheurs \u00e9changent des coups. <\/p>\n\n\n\n<p>Perry lance une poubelle sur Allin pour prendre l&rsquo;avantage et lui ferme une porte de garage dessus. Perry veut charger Allin avec une caisse, mais des agents de s\u00e9curit\u00e9 arrivent pour l&rsquo;arr\u00eater.&nbsp;Perry dit qu&rsquo;il va battre Darby Allin au Wembley Stadium dans un Coffin Match&nbsp;!<\/p>\n\n\n\n<p>&#8211; En vid\u00e9o promo: <strong>Mariah May&nbsp;<\/strong>d\u00e9clare&nbsp;que Toni Storm a \u00e9chou\u00e9 et cette ann\u00e9e tout sera pour elle. May dit que c&rsquo;est le moment de br\u00fbler toute cette histoire, Storm est obs\u00e9d\u00e9e par elle alors qu&rsquo;elle l&rsquo;a oubli\u00e9e. Elle a mieux \u00e0 faire et elle va passer \u00e0 autre chose apr\u00e8s All In.<\/p>\n\n\n\n<p>&#8211; En coulisses, Renee Paquette est avec Mina Shirakawa pour avoir son opinion sur cette histoire entre Toni Storm et Mariah May.<\/p>\n\n\n\n<p>Shirakawa r\u00e9pond qu&rsquo;elle n&rsquo;a parl\u00e9 \u00e0 aucune des deux. Elle est toujours d\u00e9chir\u00e9e par ce qui est arriv\u00e9. Paquette demande si elle s&rsquo;attendait \u00e0 ce changement. Shirakawa dit qu&rsquo;elle n&rsquo;a jamais vu May si vicieuse. Elle ne peut pas croire que c&rsquo;est les m\u00eames personnes. Paquette demande qui va gagner \u00e0 All In selon elle. Shirakawa dit qu&rsquo;elle esp\u00e8re juste que personne ne sera bless\u00e9.<\/p>\n\n\n\n<p>&#8211; Les commentateurs confirment que le match entre Allin et Perry sera un Coffin Match \u00e0 AEW All In.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Qualification Casino Gauntlet Match<\/strong><\/p>\n\n\n\n<p><strong>Kyle O&rsquo;Reilly vs Orange Cassidy vs Roderick Strong<\/strong><\/p>\n\n\n\n<p>Pendant le combat, Matt Taven et Mike Bennett arrivent en ringside pour potentiellement intervenir, mais Mark Briscoe et Ishii arrivent pour les repousser en coulisses.<\/p>\n\n\n\n<p>\u00c0 la fin du combat, O&rsquo;Reilly applique un Arm Bar sur Strong, Strong r\u00e9siste. Cassidy en profite pour faire un compte rapide \u00e0 O&rsquo;Reilly pour la victoire.<\/p>\n\n\n\n<p><em>Gagnant : Orange Cassidy<\/em><\/p>\n\n\n\n<center><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/center>\n\n\n\n<p>&#8211; En coulisses,&nbsp;<strong>Renee Paquette <\/strong>est avec<strong> Claudio Castagnoli <\/strong>et <strong>Kazuchika Okada<\/strong>&nbsp;pour leur face \u00e0 face. Paquette demande \u00e0 Castagnoli ce que le titre Continental repr\u00e9sente pour lui. Castagnoli r\u00e9ponds qu&rsquo;il a toujours eu l&rsquo;impression que le titre Continental lui \u00e9tait destin\u00e9. Alors perdre dans le tournoi Continental a \u00e9t\u00e9 difficile. Mais il a continu\u00e9 de se battre et maintenant il aura sa chance pour le premier AEW Dynamite en Europe. Okada dit que c&rsquo;\u00e9tait un beau message&#8230; mais il est le seul champion, il est le meilleur catcheur de l&rsquo;histoire. Un 4 fois gagnant du G1. Castagnoli devra le respecter lorsqu&rsquo;il va le battre et il restera le champion. Alors bonne chance \u00e0 la garce. Castagnoli dit qu&rsquo;il esp\u00e8re avoir le vrai Okada, le vrai Rainmaker et non l&rsquo;ami des directeurs qui fait des blagues.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisses, Renee Paquette est avec<strong>&nbsp;le clan de Christian Cage<\/strong>&nbsp;pour en savoir plus sur comment les titres seront d\u00e9fendus \u00e0 All In&nbsp;apr\u00e8s l&rsquo;\u00e9galit\u00e9 \u00e0 Collision. Cage dit qu&rsquo;il a officialis\u00e9 le match de mani\u00e8re \u00e9quitable. Les deux \u00e9quipes n&rsquo;ont pas \u00e9t\u00e9 en mesure de respecter le compte de dix, c&rsquo;est de leur faute. Il a promis qu&rsquo;ils allaient remporter les titres Trios et ils l&rsquo;ont fait. Maintenant il veut remporter tous les titres en m\u00eame temps. Cage dit que Nick Wayne va affronter l&rsquo;autre loser de Kip Sabian, mais malheureusement il ne sera pas l\u00e0. Paquette demande si Cage a peur de se faire attaquer en ringside. Cage dit \u00e0 Paquette de retourner s&rsquo;occuper de son r\u00f4le de m\u00e8re, un r\u00f4le dans lequel elle est peut \u00eatre encore pire que comme intervieweuse. Cage dit qu&rsquo;ils seront champions pour toujours.<\/p>\n\n\n\n<p>&#8211; Tony Schiavone est sur le ring et pr\u00e9sente&nbsp;<strong>HOOK<\/strong>. Schiavone dit qu&rsquo;il veut savoir comment va l&rsquo;oeil de HOOK. HOOK dit qu&rsquo;il ne peut pas voir o\u00f9 il y a le bandage. Chris Jericho lui a pris un oeil, mais il esp\u00e8re que Jericho voit le probl\u00e8me. Il peut voir tr\u00e8s bien avec l&rsquo;autre oeil. Il veut retrouver son titre FTW, il ne peut plus endurer Jericho, il veut affronter Jericho pour le titre ce soir ! La musique de Chris Jericho se lance et le clan du Learning Tree arrive. Jericho dit que HOOK est vraiment stupide. Apr\u00e8s l&rsquo;avoir aveugl\u00e9 avec une boule de feu, HOOK veut le challenger pour un match ce soir. Jericho dit que HOOK n&rsquo;aura pas ce match, se battre ici n&rsquo;en vaut pas la peine. Mais le Wembley Stadium en vaut bien la peine. Alors il va donner un match pour le titre FTW \u00e0 HOOK pour All In, mais il y a quelques stipulations. Le match de Wembley sera la derni\u00e8re chance de HOOK et lorsqu&rsquo;il va gagner HOOK devra l&rsquo;oublier pour toujours. Et ensuite la semaine prochaine \u00e0 Dynamite HOOK devra affronter Big Bill. Big Bill dit qu&rsquo;il va \u00e9craser HOOK et le renvoyer dans le cul de Taz.&nbsp;Alors ils vont se revoir \u00e0 Wembley si HOOK est d&rsquo;accord. HOOK dit qu&rsquo;il accepte. Il a h\u00e2te de faire tomber la Big Garce sur le cul et d\u00e9chirer Jericho en morceaux.&nbsp;Jericho ne sera plus jamais le m\u00eame apr\u00e8s.<\/p>\n\n\n\n<p>&#8211; De retour, les Young Bucks arrivent, mais ils se font attaquer dans le dos par The Acclaimed pendant leur entr\u00e9e.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW World Tag Team Championship <\/strong><\/p>\n\n\n\n<p><strong>The Young Bucks (c)<em>&nbsp;(Nicholas et Matthew Jackson)<\/em>&nbsp;vs The Acclaimed<em>&nbsp;(Max Caster et Anthony Bowens) accompagn\u00e9 de Billy Gunn<\/em><\/strong><\/p>\n\n\n\n<p>Pendant le combat, l&rsquo;arbitre d\u00e9cide d&rsquo;expulser Billy Gunn en ringside lorsque Nicholas lui passe une chaise et que l&rsquo;arbitre pense que Billy Gunn voulait l&rsquo;utiliser sur Nicholas.<\/p>\n\n\n\n<p>\u00c0 la fin du combat, Caster veut donner la tag, mais Matthew fait une Powerbomb \u00e0 Bowens en ringside pour le repousser. Nicholas fait un Roll Up \u00e0 Caster, mais il r\u00e9siste. Matthew prend la tag et ils pr\u00e9parent un TK-Driver, mais Caster repousse les deux. Caster tombe sur l&rsquo;arbitre par l&rsquo;erreur, Matthew en profite pour faire un Low Blow \u00e0 Caster ! Matthew va chercher une ceinture, mais Cash Wheeler et Dax Harwood arrivent pour l&rsquo;arr\u00eater. Matthew lui crache au visage, Dax Harwood d\u00e9cide de l&rsquo;attaquer. L&rsquo;arbitre arr\u00eate le match.<\/p>\n\n\n\n<p><em>Gagnants : The Young Bucks&nbsp;par DQ<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, The Acclaimed est en col\u00e8re pour la disqualification. La s\u00e9curit\u00e9 arrive pour s\u00e9parer The Acclaimed et FTR.<\/p>\n\n\n\n<p>&#8211; En coulisses, Renee Paquette demande \u00e0 Christopher Daniels ses commentaires sur cette fin de match. Daniels dit que ce n&rsquo;\u00e9tait pas une victoire d\u00e9finitive. Ce n&rsquo;est pas termin\u00e9 ce probl\u00e8me entre les Bucks et The Acclaimed.&nbsp;Alors samedi \u00e0 Collision, FTR va affronter The Acclaimed et les gagnants iront affronter les Young Bucks \u00e0 All In.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la carri\u00e8re de Bryan Danielson.<\/p>\n\n\n\n<p><strong>Wheeler Yuta&nbsp;<em>acc de Bryan Danielson<\/em>&nbsp;vs Swerve Strickland&nbsp;<em>acc de Prince Nana<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Yuta donne des coups \u00e0 Strickland, mais il ne tombe pas. Strickland lui fait un House Call. Strickland attend que Yuta se rel\u00e8ve et lui fait un second House Call. Strickland le rel\u00e8ve et lui fait un troisi\u00e8me House Call. Strickland commence \u00e0 rouer de coups Yuta \u00e0 la t\u00eate, Yuta ne r\u00e9pond plus, l&rsquo;arbitre arr\u00eate le combat.<\/p>\n\n\n\n<p><em>Gagnant : Swerve Strickland&nbsp;par arr\u00eat de l&rsquo;arbitre<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Strickland n&rsquo;arr\u00eate pas de donner des coups, Bryan Danielson entre sur le ring, mais Strickland s&rsquo;\u00e9chappe sur la rampe. Strickland prend le micro et dit qu&rsquo;il a un message pour Bryan Danielson. Il avait dit qu&rsquo;il allait montrer pourquoi il \u00e9tait l&rsquo;homme le plus dangereux de l&rsquo;AEW. Ce soir n&rsquo;\u00e9tait qu&rsquo;un exemple de ce qui attend Danielson \u00e0 Wembley devant 50 000 personnes. La famille de Danielson sera en ringside au m\u00eame endroit afin de regarder la m\u00eame chose que ce soir. Il va forcer Danielson \u00e0 prendre sa retraite lorsqu&rsquo;il va le paralyser.<\/p>\n\n\n\n<p>Strickland quitte en coulisses. Danielson se retourne vers Yuta pour voir s&rsquo;il va bien, mais Strickland revient sur le ring et lui fait un House Call dans le dos ! Le show se termine avec une c\u00e9l\u00e9bration de Strickland.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/08\/14\/avant-gout-pour-le-aew-dynamite-du-14-aout-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour voir Dynamite, cliquez ici.<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"mzigNhr7D2\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/08\/14\/avant-gout-pour-le-aew-dynamite-du-14-aout-2024\/\">Reprise Vid\u00e9o et Programme pour le AEW Dynamite du 14 Ao\u00fbt 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le AEW Dynamite du 14 Ao\u00fbt 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/08\/14\/avant-gout-pour-le-aew-dynamite-du-14-aout-2024\/embed\/#?secret=z6AWhAJw66#?secret=mzigNhr7D2\" data-secret=\"mzigNhr7D2\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>AEW Dynamite Norfolk, Virginie, 14 ao\u00fbt 2024 Les commentateurs sont Taz, Tony Schiavone et Excalibur. TBS Championship Mercedes Mon\u00e9 \u00a9 &nbsp;acc de Kamille&nbsp;vs Hikaru Shida \u00c0 la fin du combat, Mon\u00e9 menace d&rsquo;utiliser un Kendo Stick, l&rsquo;arbitre lui enl\u00e8ve. Kamille en profite pour faire une Big Boot \u00e0 Shida qui \u00e9tait en ringside. Kamille la&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":103861,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,91,68,50,30],"tags":[],"ppma_author":[297],"class_list":["post-103860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-all-in","category-carte","category-dynamite","category-ex-wwe"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/103860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=103860"}],"version-history":[{"count":5,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/103860\/revisions"}],"predecessor-version":[{"id":103874,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/103860\/revisions\/103874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/103861"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=103860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=103860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=103860"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=103860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}