{"id":103528,"date":"2024-08-07T20:11:00","date_gmt":"2024-08-08T00:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=103528"},"modified":"2024-08-09T21:00:59","modified_gmt":"2024-08-10T01:00:59","slug":"resultats-pour-le-aew-dynamite-du-7-aout-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/08\/07\/resultats-pour-le-aew-dynamite-du-7-aout-2024\/","title":{"rendered":"R\u00e9sultats pour le AEW Dynamite du 7 Ao\u00fbt 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/08\/07\/avant-gout-pour-le-aew-dynamite-du-7-aout-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Dynamite, cliquez ici.<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>AEW Dynamite Winston-Salem, Caroline du Nord, 7 juillet 2024<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Taz, Tony Schiavone et Excalibur.<\/p>\n\n\n\n<p>&#8211; Le show d\u00e9marre avec MJF qui arrive le premier sur le ring. Le match d\u00e9marre mais MJF quitte le ring et prend le micro. MJF avise Fletcher de l&rsquo;affronter comme un vrai catcheur, sinon il se casse avec son titre.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW American Eliminator <\/strong><\/p>\n\n\n\n<p><strong>MJF vs Kyle Fletcher<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Fletcher fait un Pile Driver sur MJF et le couvre, mais il r\u00e9siste \u00e0 deux. Don Callis d\u00e9barque en ringside et passe un tournevis \u00e0 Fletcher. Callis distrait l&rsquo;arbitre, mais Fletcher refuse d&rsquo;utiliser le tournevis. MJF en profite pour faire un Low Blow \u00e0 Fletcher et enchaine avec le Kangourou Kick. MJF fait un Brain Buster \u00e0 Fletcher pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : MJF<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, on voit Will Ospreay en coulisses qui n&rsquo;est pas content du r\u00e9sultat par tricherie et d\u00e9cide de se diriger vers le ring.<\/p>\n\n\n\n<p>Sur le ring, MJF d\u00e9cide de frapper l&rsquo;arbitre avec son titre American ! MJF sort sa bague et frappe Fletcher en pleine t\u00eate. MJF commence \u00e0 rouer de coups Fletcher \u00e0 la t\u00eate alors qu&rsquo;il saigne. MJF dit qu&rsquo;il va faire quelque chose qu&rsquo;Ospreay n&rsquo;a pas les couilles de faire. MJF se pr\u00e9pare pour un Tiger Driver, mais Will Ospreay arrive sur le ring. MJF prend la fuite dans la foule. Ospreay demande l&rsquo;aide du m\u00e9decin pour s&rsquo;occuper de Fletcher.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Danielson et Jarrett.<\/p>\n\n\n\n<p>&#8211; Le prochain match est pr\u00e9sent\u00e9 par les Singles de Krafts et les faces de mandiants amateurs. <\/p>\n\n\n\n<p><strong>Mariah May vs Viva Van<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, May fait un Running Knee \u00e0 Van et enchaine avec son May Day. May enchaine avec un Storm Zero pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Mariah May<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, un technicien arrive avec un cadeau pour Mariah May. May l&rsquo;ouvre et il s&rsquo;agit d&rsquo;une photo de Toni Storm qui fait un c\u00e2lin \u00e0 May. May tourne la photo et r\u00e9alise que c&rsquo;est \u00e9crit \u00a0\u00bbMeurt May\u00a0\u00bb. Toni Storm d\u00e9barque par derri\u00e8re pour attaquer May. Storm veut la frapper avec le soulier, mais les officiels arrivent pour s\u00e9parer les deux.<\/p>\n\n\n\n<p>&#8211; En vid\u00e9o, Jack Perry regarde une replay du Blood and Guts. Perry commence \u00e0 casser des \u00e9crans avec les images d&rsquo;anciens champion TNT. Perry explique vouloir d\u00e9truire le pass\u00e9 et tout sacrifier pour valider sa place.<\/p>\n\n\n\n<p>&#8211; Backstage coulisses, Darby Allin dit qu&rsquo;il aurait pu incendier Jack Perry au complet \u00e0 Blood and Guts, mais non, il a besoin que Jack Perry soit pr\u00e9sent pour All In. Allin dit que Perry parle de sacrifice, mais Perry n&rsquo;a plus besoin de se sacrifier car il n&rsquo;a pas besoin de venir \u00e0 Rampage, Dynamite ou Collision. Par contre, Perry ferait mieux de se ramener \u00e0 All In.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Bryan Keith&nbsp;<em>accompagn\u00e9 de Chris Jericho et Big Bill<\/em>&nbsp;vs Katsuyori Shibata<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Shibata repousse Keith au sol et lui applique un Arm Bar pour le faire taper.<\/p>\n\n\n\n<p><em>Gagnant : Katsuyori Shibata&nbsp;<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Jericho et Bill attaquent Shibata. La musique de HOOK commence et il repousse Bill du ring pour ensuite rouer de coups Jericho. Jericho arrive \u00e0 s&rsquo;\u00e9chapper du ring avant une Suplex.<\/p>\n\n\n\n<p>&#8211; En coulisses, Renee Paquette dit qu&rsquo;Orange Cassidy devait avoir un rematch, mais&nbsp;son \u00e9quipe est absente&nbsp;en raison de probl\u00e8me de transport,&nbsp;alors il va faire quoi ? <\/p>\n\n\n\n<p>Cassidy r\u00e9pond  qu&rsquo;il va toujours faire le match. Il a trouv\u00e9 quelques gars locaux qui voulaient se battre, alors \u00e7a part.<\/p>\n\n\n\n<p>&#8211; Dans les entrailles de l&rsquo;ar\u00e9na, Renee Paquette est avec Adam Hangman Page pour avoir ses commentaires sur sa d\u00e9faite la semaine derni\u00e8re et sa d\u00e9faite au tournoi Owen Hart. <\/p>\n\n\n\n<p>Page r\u00e9pond qu&rsquo;il y a un homme, un homme qui voulait tout prendre et rien laisser. Mais il y a des douzaines d&rsquo;idiots qui se mettent sur son chemin et l&#8217;emp\u00eache de r\u00e9ussir sa qu\u00eate.&nbsp;Il faut le croire lorsqu&rsquo;il dit qu&rsquo;il aura ce qu&rsquo;il veut !<\/p>\n\n\n\n<p>&#8211; <strong>Jim Ross <\/strong>est <strong>Swerve Strickland<\/strong>&nbsp;pour une interview, et lui demande comment va sa motivation. Strickland dit que c&rsquo;est \u00e9norme entre les deux All In. Ross demande si Strickland a des remords pour ce qu&rsquo;il a fait pour atteindre cette place. <\/p>\n\n\n\n<p>Strickland r\u00e9pond qu&rsquo;il faut faire du bruit pour s&rsquo;imposer. Strickland dit qu&rsquo;il connait bien Bryan Danielson, il l&rsquo;a regard\u00e9 casser des dents. Il sait que Danielson cogne fort. Ross dit que Danielson fera ce match comme son dernier. Strickland dit que c&rsquo;est une question d&rsquo;h\u00e9ritage en plus du titre. Danielson a besoin d&rsquo;une raison pour se lever le matin, mais c&rsquo;est lui qui contr\u00f4le le futur avec ce titre. Ce n&rsquo;est pas important que Danielson soit un p\u00e8re ou bien l&rsquo;homme de Brie. <\/p>\n\n\n\n<p>Ross dit que ce sera un match difficile. Strickland dit que ce ne sera pas difficile lorsque les jambes de Danielson ne vont plus suivre ou bien que le cou de Danielson sera bris\u00e9. Ross demande s&rsquo;il peut battre Danielson au Wembley Stadium. Strickland dit qu&rsquo;il va le battre et l&rsquo;h\u00e9ritage de Danielson lui appartient.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Trios Match<\/strong> <strong>(3 vs 3)<\/strong><\/p>\n\n\n\n<p><strong>Orange Cassidy, Cash Wheeler et Dax Harwood vs Rush, Beast Mortos et Roderick Strong<em>&nbsp;accompagn\u00e9 de Mike Bennett et Matt Taven<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, les catcheurs \u00e9changent les coups et les prises. Rush veut faire son Bull Horn sur Harwood, mais Cassidy intervient et lui fait un Orange Punch. Rush ne tombe pas. FTR donne des coups \u00e0 Rush, mais il ne tombe pas encore. Cassidy fait un autre Orange Punch \u00e0 Rush et FTR compl\u00e8te avec un Shatter Machine pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Orange Cassidy et FTR<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, la musique des Acclaimed se lance et le duo arrive. Max Caster veut parler, mais le micro est ferm\u00e9. Harwood dit que les gens ici ne veulent pas entendre The Acclaimed et l&rsquo;\u00e9quipe technique non plus visiblement. Des agents de s\u00e9curit\u00e9 arrivent pour faire un mur, mais Harwood invite The Acclaimed \u00e0 venir se battre. Les deux \u00e9quipes \u00e9changent quelques coups, mais les catcheurs se font s\u00e9parer.<\/p>\n\n\n\n<p>&#8211; En coulisses, on retrouve le clan de Christian Cage. Christian Cage dit qu&rsquo;il y a un probl\u00e8me au sommet de la division Trios. Christian dit que la House of Black \u00e9tait l&rsquo;\u00e9quipe aspirante, mais elle avait perdu un membre. Voil\u00e0 que la House of Black veut retrouver leur match. <\/p>\n\n\n\n<p>Et il y a le Bang Bang Gang qui veut encore un rematch.&nbsp;Il a parl\u00e9 \u00e0 des gens et ce samedi \u00e0 Collision la House of Black va affronter le Bang Bang Gang et l&rsquo;\u00e9quipe gagnante aura un match pour les titres Trios au plus grand show de l&rsquo;ann\u00e9e \u00e0 AEW All In.&nbsp;Comme ils ont besoin de discipline, il sera l&rsquo;arbitre sp\u00e9cial pour leur match.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Handicap Match<\/strong><\/p>\n\n\n\n<p><strong>Kamille&nbsp;<em>accompagn\u00e9e de Mercedes Mon\u00e9<\/em>&nbsp;vs Jazmyne Hao et Clara Carter<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Kamille fait son Torture Rack Bomb sur Hao et enchaine avec une PowerSlam sur Carter et fait le compte de trois sur les deux catcheuses pour la victoire en moins de deux minutes.<\/p>\n\n\n\n<p><em>Gagnante : Kamille<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Mon\u00e9 prend le micro et demande aux fans de saluer Kamille et leur CEO. Mon\u00e9 dit que ce n&rsquo;est pas n\u00e9cessaire de chanter DMD car elle n&rsquo;est pas l\u00e0 ce soir. Bravo \u00e0 ses directeurs pour avoir suspendu Britt Baker et ainsi on n&rsquo;a pas besoin de l&rsquo;endurer d&rsquo;ici All In. <\/p>\n\n\n\n<p>Mon\u00e9 ajoute que Baker est la premi\u00e8re catcheuse sous contrat \u00e0 l&rsquo;AEW. Oui Baker est la premi\u00e8re, mais Baker ne sera jamais la premi\u00e8re. Les deux titres prouvent qu&rsquo;elle est la meilleure de l&rsquo;AEW. Tony Schiavone intervient et dit qu&rsquo;il vient d&rsquo;apprendre que Tony Khan a lev\u00e9 la suspension de Britt Baker et qu&rsquo;elle est ici via vid\u00e9o.<\/p>\n\n\n\n<p>&nbsp;<strong>Britt Baker<\/strong>&nbsp;apparair Sur le TitanTron pour dire que Mon\u00e9 peut la suspendre comme elle veut, mais le match est bien pr\u00e9vu pour All In. Baker dit qu&rsquo;elle respecte ses obligations jusqu&rsquo;\u00e0 la fin au contraire de Mon\u00e9 qui se casse lorsque les choses ne vont pas comme elle veut. Toute cette histoire va se terminer \u00e0 All In lorsqu&rsquo;elle va devenir la Championne TBS et la premi\u00e8re \u00e0 battre Mercedes Mon\u00e9 \u00e0 la AEW. Maintenant elle a sept jours pour r\u00e9fl\u00e9chir comment elle va attaquer Mon\u00e9.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Danielson et Swerve Strickland.<\/p>\n\n\n\n<p>&#8211; De retour, les commentateurs annoncent que Castagnoli et Okada auront un face \u00e0 face la semaine prochaine \u00e0 Dynamite.<\/p>\n\n\n\n<p>&#8211; Ricky Steamboat prend place avec les commentateurs pour le prochain match comme il est l&rsquo;invit\u00e9 sp\u00e9cial. Bryan Danielson arrive pour le match, mais Jarrett l&rsquo;attaque dans le dos avec sa guitare pendant l&rsquo;entr\u00e9e !<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Anything Goes<\/strong><\/p>\n\n\n\n<p><strong>Bryan Danielson vs Jeff Jarrett<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Jarrett fait son Stroke sur Danielson sur une chaise et le couvre, mais Danielson r\u00e9siste \u00e0 deux. Jarrett enchaine avec un Sharpshooter, Danielson r\u00e9siste et le renverse en Lebell Lock. Jarrett arrive \u00e0 le repousser. Danielson et Jarrett \u00e9changent les coups. Jarrett prend l&rsquo;avantage et veut faire son Stroke, mais Danielson le repousse et lui fait son Running Knee avec l&rsquo;aide d&rsquo;une chaise pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Bryan Danielson<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Ricky Steamboat arrive sur le ring pour f\u00e9liciter les deux catcheurs. Steamboat aide Jarrett \u00e0 se relever et pose avec les deux. Jarrett et Danielson qui se serrent la main, mais la musique de Swerve Strickland commence. Strickland dit qu&rsquo;on vient de voir trois l\u00e9gendes sous nos yeux avec Jarrett, Steamboat et maintenant Swerve Strickland. La diff\u00e9rence entre eux et Danielson est qu&rsquo;ils ont tous \u00e9t\u00e9 World Champion sur TBS.<\/p>\n\n\n\n<p>Strickland dit que ce sera un grand honneur pour lui de terminer la carri\u00e8re de Danielson \u00e0 AEW All In comme Danielson est l&rsquo;un des meilleurs de tous les temps. Il ne va pas h\u00e9siter de porter ce coup fatal. Strickland dit que Danielson vient de terminer ce match avec un mal de dos, des jambes qui tremblent et une perte de sensation dans les mains. Alors Danielson doit imaginer ce qui l&rsquo;attend pour All In si Jarrett a \u00e9t\u00e9 capable de faire \u00e7a.&nbsp;<\/p>\n\n\n\n<p>Strickland ajoute qu&rsquo;il a besoin d&rsquo;un r\u00e9chauffement pour All In et il veut affronter Wheeler Yuta la semaine prochaine.&nbsp;Danielson pourra \u00eatre ringside pour ce match et d\u00e9couvrir pourquoi il est l&rsquo;homme le plus dangereux de la AEW.<\/p>\n\n\n\n<p>Le show se termine avec un face \u00e0 face entre Strickland et Danielson.<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2024\/08\/07\/avant-gout-pour-le-aew-dynamite-du-7-aout-2024\/\" target=\"_blank\"><strong>Pour voir Dynamite, cliquez ici.<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"lgnoUzzjel\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/08\/07\/avant-gout-pour-le-aew-dynamite-du-7-aout-2024\/\">Reprise Vid\u00e9o et Programme pour le AEW Dynamite du 7 Ao\u00fbt 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le AEW Dynamite du 7 Ao\u00fbt 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/08\/07\/avant-gout-pour-le-aew-dynamite-du-7-aout-2024\/embed\/#?secret=BrchAPCF9p#?secret=lgnoUzzjel\" data-secret=\"lgnoUzzjel\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>AEW Dynamite Winston-Salem, Caroline du Nord, 7 juillet 2024 Les commentateurs sont Taz, Tony Schiavone et Excalibur. &#8211; Le show d\u00e9marre avec MJF qui arrive le premier sur le ring. Le match d\u00e9marre mais MJF quitte le ring et prend le micro. MJF avise Fletcher de l&rsquo;affronter comme un vrai catcheur, sinon il se casse&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":103529,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,50,30,21],"tags":[],"ppma_author":[297],"class_list":["post-103528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-dynamite","category-ex-wwe","category-resultats"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/103528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=103528"}],"version-history":[{"count":9,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/103528\/revisions"}],"predecessor-version":[{"id":103618,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/103528\/revisions\/103618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/103529"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=103528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=103528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=103528"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=103528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}