{"id":101721,"date":"2024-07-07T20:11:00","date_gmt":"2024-07-08T00:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=101721"},"modified":"2024-07-09T13:29:34","modified_gmt":"2024-07-09T17:29:34","slug":"resultats-et-video-pour-le-wwe-nxt-heatwave-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/07\/07\/resultats-et-video-pour-le-wwe-nxt-heatwave-2024\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE NXT HeatwavE 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>Pour voir le PLE, cliquez ici.<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>WWE NXT Heatwave Toronto, Canada, 7 juillet 2024<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Vic Joseph et Booker T.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Countdown<\/strong><\/p>\n\n\n\n<p><strong>Arianna Grace et Karmen Petrovic vs Jacy Jayne et Jazmyn Nyx<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Jazmyn Nyx \u00e9vite un coup de Karmen Petrovic puis tente un roll up mais Arianna Grace \u00e0 l&rsquo;ext\u00e9rieur du ring renverse le tomb\u00e9. Petrovic fait gagner son \u00e9quipe sur un roll up.<\/p>\n\n\n\n<p><em>Gagnantes : Arianna Grace et Karmen Petrovic<\/em><\/p>\n\n\n\n<p>&#8211;  le PLE se lance avec une vid\u00e9o qui pr\u00e9sente le programme de la soir\u00e9e. Les commentateurs nous souhaitent la bienvenue puis les catcheurs font leur entr\u00e9e pour le premier match de la soir\u00e9e.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>NXT North American Championship <\/strong><\/p>\n\n\n\n<p><strong>Oba Femi \u00a9 vs Wes Lee<\/strong><br><em>Il s&rsquo;agit du dernier match de Wes Lee contre Oba Femi<\/em><\/p>\n\n\n\n<p>\u00c0 la fin du match, Oba Femi contre une prise de Wes Lee puis l&rsquo;envoie au sol. Le champion enchaine avec sa Powerbomb suivie du tomb\u00e9 pour la victoire.<\/p>\n\n\n\n<p><em>Gagnant : Oba Femi<\/em><\/p>\n\n\n\n<p>&#8211; Une vid\u00e9o sur l&rsquo;histoire entre Kelani Jordan et Sol Ruca est diffus\u00e9e.<\/p>\n\n\n\n<p><strong>NXT Women&rsquo;s North American Championship<\/strong><\/p>\n\n\n\n<p><strong>Kelani Jordan \u00a9  vs Sol Ruca<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Sol Ruca porte Kelani Jordan sur ses \u00e9paules. Jordan tente une prise mais Ruca la retient et monte dans le coin&#8230; Kelani Jordan la surprend avec un Poison Rana et enchaine avec un Moonsault de la troisi\u00e8me corde pour l&#8217;emporter avec un tomb\u00e9.<\/p>\n\n\n\n<p><em>Gagnante : Kelani Jordan<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le match, Kelani Jordan aide Sol Ruca \u00e0 se relever et les deux catcheurs c\u00e9l\u00e8brent ensemble.<\/p>\n\n\n\n<center><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/center>\n\n\n\n<p>&#8211; En coulisses, Arianna Grace et Karmen sont avec Ava. Grace affirme que le r\u00e9sultat aurait \u00e9t\u00e9 catastrophique si Karmen \u00e9tait seule, heureusement qu&rsquo;elle \u00e9tait l\u00e0, c&rsquo;\u00e9tait la MVP du match. Elles ne feront plus \u00e9quipe. Ava annonce un match entre les deux catcheuses ce mardi \u00e0 NXT.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>NXT Tag Team Championship<\/strong><\/p>\n\n\n\n<p><strong>Nathan Frazer et Axiom \u00a9 vs ChaseU&nbsp;<em>(Andre Chase et Duke Hudson)<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Axiom fait le tag avec Nathan Frazer qui monte sur la troisi\u00e8me corde et saute sur Andre Chase&#8230; ce dernier le contre et monte \u00e0 son tour sur la troisi\u00e8me corde. Frazer le rejoint et enchaine avec une Superplex. Axiom a pris le tag et en termine avec son Golden Ratio sur Chase suivi du tomb\u00e9 pour l&#8217;emporter, tandis que Frazer s&rsquo;est envol\u00e9 par dessus la troisi\u00e8me corde poour atterir sur Duke Hudson.<\/p>\n\n\n\n<p><em>Gagnants : Nathan Frazer et Axiom<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, Wes Lee est d\u00e9\u00e7u de sa d\u00e9faite. Il devait retrouver le titre et il a \u00e9chou\u00e9, Oba Femi \u00e9tait meilleur ce soir. Il a besoin de temps pour r\u00e9fl\u00e9chir \u00e0 la suite.<\/p>\n\n\n\n<p>&#8211; NXT The Great Americain Bash aura lieu le 6 ao\u00fbt 2024.<\/p>\n\n\n\n<p>&#8211; Une vid\u00e9o sur l&rsquo;histoire entre Roxanne Perez et Lola Vice est diffus\u00e9e.<\/p>\n\n\n\n<p><strong>NXT Women&rsquo;s Championship<\/strong><\/p>\n\n\n\n<p><strong>Roxanne Perez \u00a9 vs Lola Vice<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Roxanne Perez installe Lola Vice sur la table des commentateurs puis lui fait son Pop Rox sur la table ! Perez ram\u00e8ne Vice sur le ring puis tente le tomb\u00e9 mais son adversaire se rel\u00e8ve. Roxanne Perez applique un Crossface sur Lola Vice qui r\u00e9siste et s&rsquo;approche des cordes&#8230; La championne fait 2-3 Pop Rox d&rsquo;afil\u00e9e sur Lola Vice suivis du tomb\u00e9 pour l&#8217;emporter.<\/p>\n\n\n\n<p><em>Gagnante : Roxanne Perez<\/em><\/p>\n\n\n\n<center><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/center>\n\n\n\n<p><strong>Mardi prochain \u00e0 NXT : <\/strong><br> * Lexis King vs Tony D&rsquo;Angelo dans un Heritage Cup Match <br> * Karmen Petrovic vs Arianna Grace <br> *  Luke Gallows et Karl Anderson vs OTM <br> *  Gallus vs Tyson Dupont et Tyriek Igwe <br> * Wes Lee nous parlera de son futur.<\/p>\n\n\n\n<p>&#8211; Une vid\u00e9o sur l&rsquo;histoire du Main Event est diffus\u00e9e.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>NXT Championship &#8211; Fatal 4-Way Match<\/strong><\/p>\n\n\n\n<p><strong>Trick Williams \u00a9 vs Je&rsquo;Von Evans vs Shawn Spears vs Ethan Page<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Ethan Page fait son Ego&rsquo;s Edge sur Trick Williams suivi du tomb\u00e9 mais Je\u2019Von Evans place sa jambe sur la corde. L&rsquo;ancien de la AEW ram\u00e8ne Evans sur le ring et l&rsquo;attaque. Trick Williams veut mettre un coup de genou sur Ethan Page mais ce dernier l&rsquo;\u00e9vite et c&rsquo;est Je\u2019Vo Evans qui se le prend, faisant tomber Shawn Spears du tablier du ring. Evans enchaine avec un autre coup de genou sur Ethan Page qui tombe sur Trick Williams&#8230; l&rsquo;arbitre fait le tomb\u00e9 tandis que Shawn Spears retient Je\u2019Vo Evans \u00e0 l&rsquo;ext\u00e9rieur du ring !<\/p>\n\n\n\n<p><em>Gagnant et nouveau champion: Ethan Page <\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match, le nouveau champion de NXT &#8211; Ethan Page &#8211; c\u00e9l\u00e8bre sa victoire puis nous voyons de br\u00e8ves images de Joe Hendry.<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/07\/07\/carte-pour-le-wwe-nxt-heatwave-ce-dimsanche\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir NXT HeatwavE 2024<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"taBp1pftxX\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/07\/07\/carte-pour-le-wwe-nxt-heatwave-ce-dimsanche\/\">Reprise Vid\u00e9o et Carte pour le WWE NXT Heatwave ce dimanche!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Carte pour le WWE NXT Heatwave ce dimanche!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/07\/07\/carte-pour-le-wwe-nxt-heatwave-ce-dimsanche\/embed\/#?secret=Vy76TZJV85#?secret=taBp1pftxX\" data-secret=\"taBp1pftxX\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE NXT Heatwave Toronto, Canada, 7 juillet 2024 Les commentateurs sont Vic Joseph et Booker T. Countdown Arianna Grace et Karmen Petrovic vs Jacy Jayne et Jazmyn Nyx \u00c0 la fin du match, Jazmyn Nyx \u00e9vite un coup de Karmen Petrovic puis tente un roll up mais Arianna Grace \u00e0 l&rsquo;ext\u00e9rieur du ring renverse le&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":101745,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,45,21,23],"tags":[],"ppma_author":[297],"class_list":["post-101721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nxt","category-ppv-wwe","category-resultats","category-wwe"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/101721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=101721"}],"version-history":[{"count":9,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/101721\/revisions"}],"predecessor-version":[{"id":101853,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/101721\/revisions\/101853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/101745"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=101721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=101721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=101721"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=101721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}