{"id":100970,"date":"2024-06-23T11:11:00","date_gmt":"2024-06-23T15:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=100970"},"modified":"2024-06-23T17:00:41","modified_gmt":"2024-06-23T21:00:41","slug":"cody-rhodes-a-subi-deux-cotes-cassees-a-smackdown-la-wwe-lui-a-propose-de-lui-donner-du-temps-libre-mais-il-repond-hell-no","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/06\/23\/cody-rhodes-a-subi-deux-cotes-cassees-a-smackdown-la-wwe-lui-a-propose-de-lui-donner-du-temps-libre-mais-il-repond-hell-no\/","title":{"rendered":"Cody Rhodes a subi deux c\u00f4tes cass\u00e9es \u00e0 SmackDown, la WWE lui a propos\u00e9 de lui donner du temps libre mais il r\u00e9pond \u00ab\u00a0Hell No\u00a0\u00bb."},"content":{"rendered":"\n<p>La lutte professionnelle n\u2019est pas du ballet.<\/p>\n\n\n\n<p>\u00ab&nbsp;The American Nightmare&nbsp;\u00bb le sait de premi\u00e8re main.<\/p>\n\n\n\n<p>Cody Rhodes a coup\u00e9 une promo en plus de lutter lors de l\u2019\u00e9v\u00e9nement en direct de la WWE samedi soir \u00e0 Bloomington, IL., et en s\u2019adressant \u00e0 la foule, le champion universel de la WWE a affirm\u00e9 qu\u2019il souffrait d\u2019une blessure.<\/p>\n\n\n\n<p>Selon le champion incontest\u00e9 de la WWE, il a subi deux c\u00f4tes cass\u00e9es \u00e0 la suite de l\u2019attaque de The Bloodline, qui a culmin\u00e9 avec le nouveau membre Jacob Fatu qui l\u2019a fait passer \u00e0 travers la table des commentateurs avec un splash au sol lors de l\u2019\u00e9pisode de WWE SmackDown du 21 juin \u00e0 Chicago.<\/p>\n\n\n\n<p>Rhodes a not\u00e9 que la WWE voulait lui donner le week-end de cong\u00e9, ainsi que le SmackDown de vendredi prochain au Madison Square Garden \u00e0 New York, mais il a dit \u00ab\u00a0Hell no\u00a0!\u00a0\u00bb<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n\n<blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"en\" dir=\"ltr\">WHAT <a href=\"https:\/\/t.co\/GFX5XZi8ZT\">pic.twitter.com\/GFX5XZi8ZT<\/a><\/p>&mdash; maddy (@rhodecross) <a href=\"https:\/\/twitter.com\/rhodecross\/status\/1804720093609210282?ref_src=twsrc%5Etfw\">June 23, 2024<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"mV7UyvMagN\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/06\/21\/resultats-et-video-pour-le-wwe-friday-night-smackdown-du-21-juin-2024\/\">R\u00e9sultats et Vid\u00e9o pour le WWE Friday Night Smackdown du 21 Juin 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le WWE Friday Night Smackdown du 21 Juin 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/06\/21\/resultats-et-video-pour-le-wwe-friday-night-smackdown-du-21-juin-2024\/embed\/#?secret=tOPatVOq6e#?secret=mV7UyvMagN\" data-secret=\"mV7UyvMagN\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La lutte professionnelle n\u2019est pas du ballet. \u00ab&nbsp;The American Nightmare&nbsp;\u00bb le sait de premi\u00e8re main. Cody Rhodes a coup\u00e9 une promo en plus de lutter lors de l\u2019\u00e9v\u00e9nement en direct de la WWE samedi soir \u00e0 Bloomington, IL., et en s\u2019adressant \u00e0 la foule, le champion universel de la WWE a affirm\u00e9 qu\u2019il souffrait d\u2019une&#8230;<\/p>\n","protected":false},"author":665,"featured_media":101003,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,36,23],"tags":[],"ppma_author":[289],"class_list":["post-100970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-smackdown","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=100970"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100970\/revisions"}],"predecessor-version":[{"id":101004,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100970\/revisions\/101004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/101003"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=100970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=100970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=100970"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=100970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}