{"id":100618,"date":"2024-06-14T20:22:00","date_gmt":"2024-06-15T00:22:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=100618"},"modified":"2024-06-18T12:51:51","modified_gmt":"2024-06-18T16:51:51","slug":"resultats-et-video-pour-le-tna-against-all-odds-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/06\/14\/resultats-et-video-pour-le-tna-against-all-odds-2024\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le TNA Against All Odds 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/06\/15\/reprise-video-pour-le-tna-against-all-odds-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Against All Odds, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>Jonathan Gresham vs Sami Callihan<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, l\u2019arbitre demande \u00e0 Gresham de l\u00e2cher Callihan car il met ses doigts dans les yeux de Callihan. Gresham, \u00e9nerv\u00e9, arrache le masque de l\u2019arbitre. Pendant que l\u2019arbitre s\u2019occupe de remettre son masque, Kushida arrive par derri\u00e8re et pr\u00e9l\u00e8ve de l\u2019encre noire de la bouche de Gresham. La distraction permet \u00e0 Callihan de porter son Cactus Driver 97 pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Sami Callihan<\/em><\/p>\n\n\n\n<p><strong>Knockouts World Tag Team Championship<\/strong><\/p>\n\n\n\n<p><strong>Alisha Edwards et Masha Slamovich accompagn\u00e9e du System \u00a9 vs The Hex<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, The Hex font leur The Hex Marks The Spot sur Alisha Edwards, mais Masha Slamovich revient juste \u00e0 temps pour briser le compte. Alisha Edwards r\u00e9alise ensuite un Top Rope Bulldog sur Marti Belle pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Alisha Edwards et Masha Slamovich<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong>Carte Principale<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Mike Santana et Steve Maclin vs The Rascalz<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Trey Miguel se saisit de sa bombe de peinture et tente de l\u2019utiliser sur Santana mais Maclin est vigilant et le bloque. Santana place ensuite Trey Miguel sur la troisi\u00e8me corde, la t\u00eate vers le sol. Steve Maclin lui fait son \u00ab Caught in the Crosshairs \u00bb. Mike Santana met fin au match avec un Spin The Block sur Zachary Wentz.<\/p>\n\n\n\n<p><strong>Gagnant : Mike Santana et Steve Maclin<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, Steve Maclin et Mike Santana se serrent la main.<\/p>\n\n\n\n<p>&#8211; Matt Hardy dit que ce soir il va devenir champion de la TNA pour la troisi\u00e8me fois. Il va rendre The System obsol\u00e8te, il va briser Moose. Ce sera un match \u00ab Broken Rules \u00bb, c\u2019est-\u00e0-dire qu\u2019il n\u2019y a pas de r\u00e8gles. La soir\u00e9e se terminera avec lui qui tiendra le titre entre ses mains.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>PCO vs Rich Swann&nbsp;<em>accompagn\u00e9 de AJ Francis<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, PCO applique un Lungblower sur Rich Swann dans le coin du ring. AJ Francis tente d\u2019intervenir encore une fois mais PCO se venge en lui plongeant dessus \u00e0 l\u2019ext\u00e9rieur du ring. PCO s\u2019occupe par la suite de Rich Swann avec un PCO soars et remporte le match.<\/p>\n\n\n\n<p><em>Gagnant : PCO<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, Steph De Lander fait son entr\u00e9e sur le ring. Elle prend un micro pour s\u2019exprimer. Elle dit \u00e0 PCO qu\u2019elle l\u2019a fait attendre assez, donc elle va r\u00e9pondre \u00e0 sa lettre d\u2019amour : Elle accepte un date avec lui.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Dirty Dango arrive en ringside pour suivre le prochain match.<\/p>\n\n\n\n<p><strong>TNA World Tag Team Championship<\/strong><\/p>\n\n\n\n<p><strong>The System (Eddie Edwards et Brian Myers) \u00a9 &nbsp;<em>accompagn\u00e9s de Alisha Edwards<\/em>&nbsp;vs Nic et Ryan Nemeth<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Ryan Nemeth envoie Brian Myers dans le poteau. Nic Nemeth fait son Danger Zone sur Eddie Edwards, mais Moose fait sortir l\u2019arbitre du ring juste avant le compte de trois ! Nic Nemeth saute depuis la troisi\u00e8me corde sur Moose \u00e0 l\u2019ext\u00e9rieur du ring. Dirty Dango profite que l\u2019arbitre soit en dehors du ring pour frapper Ryan Nemeth au visage ! Eddie Edwards porte son Boston Knee Party sur Ryan Nemeth pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : The System<\/em><\/p>\n\n\n\n<p>&#8211; Gia Miller interview ABC. Elle demande si les chances ne sont pas contre eux apr\u00e8s leur d\u00e9faite \u00e0 TNA Impact hier soir. Ace Austin dit qu\u2019ils ne jouent pas \u00e0 ce jeu. Ce soir est le plus important. Ils vont regagner en momentum et ensuite se concentrer sur leur rematch pour le championnat par \u00e9quipe. Chris Bey dit que leur \u00e9quipe a vu le jour il y a deux ans \u00e0 Against All Odds. Ce soir, tout recommence une nouvelle fois.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Frankie Kazarian vs Joe Hendry<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Frankie Kazarian s\u2019\u00e9lance mais se fait contrer par Joe Hendry avec une Pop-up Powerbomb. Kazarian se d\u00e9gage \u00e0 deux. Hendry esquive une droite de Kazarian et le soul\u00e8ve pour le ramener au centre du ring. Alors qu\u2019il se fait porter, Kazarian utilise un poing am\u00e9ricain pour frapper Joe Hendry au visage et remporter le match.<\/p>\n\n\n\n<p><em>Gagnant : Frankie Kazarian<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, Frankie Kazarian attaque Joe Hendry. Il lui porte un Chicken Wing jusqu\u2019\u00e0 ce qu\u2019Ace Steel vienne aider Joe Hendry. Steel demande \u00e0 Kazarian de sortir du ring mais il se fait bousculer. Ace Steel envoie une droite \u00e0 Frankie Kazarian.<\/p>\n\n\n\n<p>&#8211; Avant que le match ne d\u00e9bute, Trent Seven diffuse des images exclusives de Mustafa Ali apr\u00e8s l\u2019interview avec Tom Hannifan hier \u00e0 Impact.<\/p>\n\n\n\n<p><strong>X Division Championship<\/strong><\/p>\n\n\n\n<p><strong>Mustafa Ali \u00a9 vs Trent Seven<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Mustafa Ali fait un 450 Splash sur le dos de Trent Seven, qui se d\u00e9gage \u00e0 deux. Ali sort du ring pour prendre son titre et veut frapper Trent Seven avec. L\u2019arbitre le retient et l\u2019emp\u00eache d\u2019utiliser son titre comme une arme. Trent Seven fait un Low blow \u00e0 Ali dans le dos de l\u2019arbitre et encha\u00eene avec son Birminghammer. Mustafa Ali r\u00e9siste ! Il fait ensuite tomber Seven des cordes et ex\u00e9cute son 450 Splash sur les jambes de Seven. Ali fait un Sharpshooter \u00e0 Trent Seven et le force \u00e0 taper.<\/p>\n\n\n\n<p><em>Gagnant : Mustafa Ali<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, Frankie Kazarian se plaint de d\u2019Ace Steel. Santino Marella lui propose de l\u2019affronter la semaine prochaine \u00e0 Impact dans un Chicago Street Fight.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>ABC vs Josh Alexander et Eric Young<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Josh Alexander fait un Backbreaker sur Chris Bey, puis un rolling senton, suivi d\u2019un Elbow drop d\u2019Eric Young. Ace Austin brise le compte. Eric Young frappe Josh Alexander involontairement alors que Chris Bey esquive le coup. Ace Austin r\u00e9alise un \u00ab The Fold \u00bb sur Eric Young. Chris Bey le couvre pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : ABC<\/em><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Avant que le match ne commence, le concierge personnel introduit Ash by Elegance (Dana Brooke) qui s\u2019installe sur une chaise sur la rampe d\u2019entr\u00e9e pour assister au match.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>TNA Knockouts World Open Challenge <\/strong><\/p>\n\n\n\n<p><strong>Jordynne Grace \u00a9 vs Tatum Paxley<\/strong> (NXT)<\/p>\n\n\n\n<p>\u00c0 la fin du match, Tatum Paxley garde Grace au sol avec une soumission, mais la championne Knockouts parvient \u00e0 se relever et \u00e0 renverser Paxley avec un Juggernaut Jackhammer. Paxley se d\u00e9gage et r\u00e9ussi \u00e0 placer un Enzuiguri, mais cela ne suffit pas. Jordynne Grace reprend le contr\u00f4le et fait son Juggernaut Driver tout en regardant Ash by Elegance pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Jordynne Grace<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, Ash by Elegance attaque Jordynne Grace par derri\u00e8re avec un poing am\u00e9ricain. Grace riposte en sortant Ash du ring. La championne prend la bouteille de champagne et la verse sur Ash.<\/p>\n\n\n\n<p>&#8211; Avant que le match ne commence, Nic et Ryan Nemeth viennent se battre avec Eddie Edwards et Brian Myers en ringside. Les quatre catcheurs poursuivent leur bagarre dans les coulisses.<\/p>\n\n\n\n<p><strong>TNA World Championship \u2013 Broken Rules Match<\/strong><\/p>\n\n\n\n<p><strong>Moose \u00a9&nbsp;<em>accompagn\u00e9 du System<\/em>&nbsp;vs \u00ab Broken \u00bb Matt Hardy<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Matt Hardy fait un Twist Of Fate \u00e0 Moose avec une chaise autour du cou. Alisha Edwards donne plusieurs coups de kendo stick \u00e0 Hardy pour l\u2019emp\u00eacher de remporter le match. Rebecca Hardy arrive vers le ring ! Les deux femmes se battent et Rebecca finit par faire un Twist Of Fate sur Alisha. Matt Hardy se pr\u00e9pare \u00e0 faire passer Moose \u00e0 travers une table dans un coin du ring, mais le champion se pousse et Hardy fait un spear \u00e0 sa femme. Moose b\u00e9n\u00e9ficie de la situation pour surprendre Matt Hardy avec un spear pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Moose<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, le System rentre sur le ring. Matt Hardy prot\u00e8ge sa femme alors que les membres du System s\u2019acharnent sur lui. Ryan et Nic Nemeth, ainsi que Joe Hendry viennent aider Matt Hardy, en vain.&nbsp;<\/p>\n\n\n\n<p>La musique de <strong>Jeff Hardy<\/strong> se lance&nbsp;! Il appara\u00eet avec une chaise \u00e0 la main. Les fr\u00e8res Hardy font des Twist Of Fate chacun leur tour. Jeff Hardy fait une Swanton Bomb sur Moose. Les deux fr\u00e8res se prennent dans les bras.<\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/06\/14\/reprise-video-pour-le-tna-against-all-odds-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir le PPV, cliquez ici<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"mQYF4ROk8k\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/06\/14\/reprise-video-pour-le-tna-against-all-odds-2024\/\">Reprise Vid\u00e9o pour le TNA Against All Odds 2024<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le TNA Against All Odds 2024\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/06\/14\/reprise-video-pour-le-tna-against-all-odds-2024\/embed\/#?secret=ofXVK7D82Q#?secret=mQYF4ROk8k\" data-secret=\"mQYF4ROk8k\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<center><iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2FJasonDarkCashDescoteaux%2Fposts%2Fpfbid024EfnBm3edkb8VHE11hoGsUEYx4ZS4HYP5VejpQN8nLDivHB3reUTZv3cYt9j1HRnl&#038;show_text=true&#038;width=500\" width=\"500\" height=\"250\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Jonathan Gresham vs Sami Callihan \u00c0 la fin du match, l\u2019arbitre demande \u00e0 Gresham de l\u00e2cher Callihan car il met ses doigts dans les yeux de Callihan. Gresham, \u00e9nerv\u00e9, arrache le masque de l\u2019arbitre. Pendant que l\u2019arbitre s\u2019occupe de remettre son masque, Kushida arrive par derri\u00e8re et pr\u00e9l\u00e8ve de l\u2019encre noire de la bouche de&#8230;<\/p>\n","protected":false},"author":665,"featured_media":100619,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,85,21,41],"tags":[],"ppma_author":[289],"class_list":["post-100618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-nxt","category-resultats","category-tna-impact"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=100618"}],"version-history":[{"count":6,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100618\/revisions"}],"predecessor-version":[{"id":100742,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100618\/revisions\/100742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/100619"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=100618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=100618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=100618"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=100618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}