{"id":100403,"date":"2024-06-10T14:33:55","date_gmt":"2024-06-10T18:33:55","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=100403"},"modified":"2024-06-10T14:33:57","modified_gmt":"2024-06-10T18:33:57","slug":"tous-sattendent-a-voir-ricochet-a-la-all-elite-wrestling-meme-a-la-wwe-cest-dans-les-discutions","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/06\/10\/tous-sattendent-a-voir-ricochet-a-la-all-elite-wrestling-meme-a-la-wwe-cest-dans-les-discutions\/","title":{"rendered":"Tous s&rsquo;attendent \u00e0 voir Ricochet \u00e0 la All Elite Wrestling, M\u00eame \u00e0 la WWE, c&rsquo;est dans les discutions !"},"content":{"rendered":"\n<p>Alors que Ricochet sera agent libre bient\u00f4t, le catcheur de 35 ans ne devrait pas manquer de proposition \u00e0 sa sortie. S\u2019il y a de l\u2019int\u00e9r\u00eat pour le catcheur dans plusieurs promotions aux quatre coins du globe, comme nous l&rsquo;avons mentionn\u00e9 plus t\u00f4t, Fightful rapporte que la AEW est la destination la plus probable.<\/p>\n\n\n\n<p>Le site d\u2019information explique qu\u2019en plus de l\u2019int\u00e9r\u00eat que portent plusieurs personnalit\u00e9s de la AEW pour le highflyer au sein de la WWE, on envisage d\u00e9j\u00e0 son transfert vers la compagnie de Tony Khan d\u00e8s que sa clause de non comp\u00e9tition sera termin\u00e9e. Normalement 90 jours apr\u00e8s la date de fin du contrat.<\/p>\n\n\n\n<p> Aucune discussion officielle entre la AEW et Ricochet n\u2019a pu avoir lieu pour le moment, le catcheur \u00e9tant toujours sous contrat avec la promotion de Stamford, cela serait consid\u00e9r\u00e9 comme du maraudage. On sait qu&rsquo;officieusement, tout peut se faire par l&rsquo;interm\u00e9diaire d&rsquo;un tier partie, voir m\u00eame directement tant que cela n&rsquo;est pas s\u00fbt. <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Will Ospreay avait notamment fait part d\u2019une \u00ab\u00a0tristesse\u00a0\u00bb quant au traitement de Ricochet par la WWE, esp\u00e9rant le revoir bient\u00f4t sur le m\u00eame ring que lui, tandis que la NJPW est aussi int\u00e9ress\u00e9e par le catcheur.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00a0\u00bb IL FAUT QUE QUELQUE CHOSE CHANGE\u00a0\u00ab\u00a0<\/p>\n<\/blockquote>\n\n\n\n<p>Ricochet avait d\u00e9j\u00e0 fait part d\u2019une certaine frustration dans une\u00a0vid\u00e9o publi\u00e9e en mai dernier sur X. Si celle-ci peut avoir \u00e9t\u00e9 consid\u00e9r\u00e9e comme kayfabe, ces mots r\u00e9sonnent encore plus aujourd\u2019hui.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab\u00a0Je peux m\u2019entra\u00eener. Je peux me lancer des d\u00e9fis. Je peux donner tout ce que j\u2019ai. Mais il semble que ce ne soit jamais assez.\u00a0<\/em><\/p>\n\n\n\n<p><em>\u00a0Ce n\u2019est jamais assez, pas quand \u00e7a compte. Ce n\u2019est jamais assez. Je me retrouve donc dans cette situation. Presque chaque semaine, je me retrouve dans cette situation. Il faut que quelque chose change.\u00a0\u00bb<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>La date de fin exacte de Ricochet n\u2019est pas connue, mais selon Fightful celle-ci pourrait avoir lieu dans le milieu de l\u2019\u00e9t\u00e9. En attendant, il devrait \u00eatre retir\u00e9 prochainement des storylines dans lesquels il est impliqu\u00e9. Et concernant le tout, ce matin la date de son dernier RAW \u00e9tait connue. <\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"xlxSpwisA1\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/06\/10\/natalya-et-chad-gable-vont-rester-a-la-wwe-contrairement-a-ricochet-mais-toujours-pas-de-nouvelle-pour-seth-rollins\/\">Natalya Et Chad Gable vont rester \u00e0 la WWE Contrairement \u00e0 Ricochet mais Toujours Pas de Nouvelle pour Seth Rollins!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Natalya Et Chad Gable vont rester \u00e0 la WWE Contrairement \u00e0 Ricochet mais Toujours Pas de Nouvelle pour Seth Rollins!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/06\/10\/natalya-et-chad-gable-vont-rester-a-la-wwe-contrairement-a-ricochet-mais-toujours-pas-de-nouvelle-pour-seth-rollins\/embed\/#?secret=XUkzopHfSc#?secret=xlxSpwisA1\" data-secret=\"xlxSpwisA1\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Alors que Ricochet sera agent libre bient\u00f4t, le catcheur de 35 ans ne devrait pas manquer de proposition \u00e0 sa sortie. S\u2019il y a de l\u2019int\u00e9r\u00eat pour le catcheur dans plusieurs promotions aux quatre coins du globe, comme nous l&rsquo;avons mentionn\u00e9 plus t\u00f4t, Fightful rapporte que la AEW est la destination la plus probable. Le&#8230;<\/p>\n","protected":false},"author":4,"featured_media":100404,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,22,4,23],"tags":[],"ppma_author":[292],"class_list":["post-100403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-indy","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=100403"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100403\/revisions"}],"predecessor-version":[{"id":100405,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100403\/revisions\/100405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/100404"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=100403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=100403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=100403"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=100403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}