{"id":100347,"date":"2024-06-07T20:08:00","date_gmt":"2024-06-08T00:08:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=100347"},"modified":"2024-06-11T12:47:17","modified_gmt":"2024-06-11T16:47:17","slug":"resultats-et-video-pour-le-wwe-friday-night-smackdown-du-7-juin-2024","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/06\/07\/resultats-et-video-pour-le-wwe-friday-night-smackdown-du-7-juin-2024\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE Friday Night Smackdown du 7 Juin 2024!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/06\/07\/avant-gout-pour-le-wwe-friday-night-smackdown-du-7-juin-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Smackdown, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>WWE SmackDown Louisville, Kentucky, 7 juin 2024<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Corey Graves et Wade Barrett.<\/p>\n\n\n\n<p>&#8211; Le show d\u00e9bute sur des images de&nbsp;l&rsquo;attaque d&rsquo;AJ Styles sur Cody Rhodes la semaine derni\u00e8re. Les commentateurs nous souhaitent la bienvenue puis la Bloodline arrive sur le ring. <\/p>\n\n\n\n<p>Paul Heyman prend le micro et se pr\u00e9sente. Il dit que tant que Roman Reigns ne sera pas de retour, Solo Sikoa s&rsquo;assoie en Head of the Table. \u00c0 sa gauche, Tama Tonga a d\u00e9j\u00e0 \u00e9t\u00e9 intronis\u00e9 au sein de la Bloodline, il sera le bras droit de Solo Sikoa. Il y a aussi celui qui est \u00e0 sa droite, Tonga Loa.<\/p>\n\n\n\n<p>Solo Sikoa prend la parole en demandant \u00e0 Paul Heyman s&rsquo;il n&rsquo;a pas oubli\u00e9 un truc. Paul Heyman r\u00e9pond avoir dit tout ce qu&rsquo;il fallait. Solo Sikoa lui dit de les remercier pour la semaine derni\u00e8re. Heyman remercie Tonga Loa et Tama Tonga de l&rsquo;avoir sauv\u00e9 de Kevin Owens. Tama Tonga r\u00e9pond qu&rsquo;ils auraient pu laisser Kevin Owens le t*er la semaine derni\u00e8re, mais ils l&rsquo;ont sauv\u00e9 \u00e0 la demande du&nbsp;<em>Tribal Chief<\/em>.<\/p>\n\n\n\n<p>Paul Heyman dit que depuis son arriv\u00e9e aujourd&rsquo;hui, on lui r\u00e9p\u00e8te sans cesse que Kevin Owens cherche \u00e0 s&rsquo;en prendre \u00e0 tous les membres de la Bloodline&#8230; La musique de Kevin Owens retentit et il arrive sur le ring puis une bagarre \u00e9clate ! La Bloodline arrive \u00e0 le mettre au sol mais les Street Profits arrivent \u00e0 sa rescousse ! Kevin Owens et les Street Profits arrivent \u00e0 faire fuir la Bloodline.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisses, Solo Sikoa attrape Paul Heyman et lui dit d&rsquo;organiser un match \u00e0 trois contre trois pour ce soir. S&rsquo;il n&rsquo;y arrive pas, \u00e7a sera Paul Heyman contre Tama Tonga dans les vestiaires.<\/p>\n\n\n\n<p>&#8211; Plus t\u00f4t aujourd&rsquo;hui, Candice LeRae et Indi Hartwell se sont plaintes \u00e0 Nick Aldis du match pr\u00e9vu entre Cargill et Hartwell. Le GM de SmackDown annonce que \u00e7a devient un match par \u00e9quipe.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Candice LeRae et Indi Hartwell vs Bianca Belair et Jade Cargill<\/strong><\/p>\n\n\n\n<p>En d\u00e9but de rencontre, Alba Fyre, Isla Dawn, Shayna Baszler et Zoey Stark arrivent en ringside pour regarder le match.<\/p>\n\n\n\n<p>\u00c0 la fin, Bianca Belair contre une prise d&rsquo;Indi Hartwell puis lui fait une prise avec Jade Cargill qui fait le tomb\u00e9 de la victoire.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnantes : Bianca Belair et Jade Cargill<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match, Bianca Belair et Jade Cargill c\u00e9l\u00e8brent leur victoire mais les catcheuses qui \u00e9taient en ringside viennent attaquer les championnes ! Elles montent ensuite sur le ring avec une ceinture par duo et la bagarre continue&#8230; les championnes reviennent sur le ring et arrivent \u00e0 les mettre toutes au sol.<\/p>\n\n\n\n<p>&#8211; Sur le stationnement int\u00e9rieur de l&rsquo;ar\u00e9na, Nick Aldis rejoint un Cody Rhodes \u00e9nerv\u00e9. Aldis lui dit s&rsquo;\u00eatre aussi fait avoir par AJ Styles, mais ils ne devraient pas se battre \u00e0 cet endroit car quelqu&rsquo;un pourrait se blesser. <\/p>\n\n\n\n<p>Cody Rhodes r\u00e9pond que quelqu&rsquo;un sera bless\u00e9 et \u00e7a sera pas lui.<\/p>\n\n\n\n<p>&#8211; En coulisses, Sarah Schreiber est avec Apollo Crews et lui parle de son retour \u00e0 SmackDown la semaine derni\u00e8re. Il commence \u00e0 parler mais Crews se fait attaquer par la Legado Del Fantasma. <\/p>\n\n\n\n<p>Les officiels arrivent pour aider Crews \u00e0 se relever.<\/p>\n\n\n\n<p>&#8211; Nick Aldis est rejoint par LA Knight qui lui demande o\u00f9 est Logan Paul. Aldis l&rsquo;informe qu&rsquo;il n&rsquo;est pas l\u00e0 ce soir. <\/p>\n\n\n\n<p>Carmelo Hayes arrive et dit que LA Knight parle de quelqu&rsquo;un qui n&rsquo;est pas l\u00e0. Nick Aldis officialise le match entre LA Knight et Carmelo Hayes pour ce soir.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Johnny Gargano&nbsp;<em>acc de Tommaso Ciampa<\/em>&nbsp;vs Grayson Waller&nbsp;<em>acc d&rsquo;Austin Theory<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, Johnny Gargano saute sur Grayson Waller \u00e0 partir du ring mais il atterrit sur Austin Theory. Waller en profite pour l&rsquo;envoyer contre le poteau puis le remet sur le ring pour enchainer avec son finisher suivi du tomb\u00e9.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : Grayson Waller<\/em><\/p>\n\n\n\n<p>&#8211; On retrouve Cody Rhodes qui est rejoint par une s\u00e9curit\u00e9.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Apr\u00e8s la pause publicitaire, AJ Styles arrive en voiture mais la s\u00e9curit\u00e9 emp\u00eache Cody Rhodes de l&rsquo;approcher. Le champion Incontest\u00e9 de la WWE s&rsquo;en va alors dans l&rsquo;ar\u00e8ne et dit \u00e0 AJ Styles de venir maintenant. Ils ont pas besoin de s\u00e9curit\u00e9, Styles peut venir .<\/p>\n\n\n\n<p> La musique d&rsquo;AJ Styles retentit et il d\u00e9barque avec Luke Gallows et Karl Anderson mais la s\u00e9curit\u00e9 s\u00e9pare \u00e0 nouveau les deux Superstars.<\/p>\n\n\n\n<p>AJ Styles dit \u00e0 Cody Rhodes de lui donner ce que lui veut,&nbsp;un match de <span style=\"text-decoration: underline;\">championnat <\/span>\u00e0 Clash at the Castle, c&rsquo;est ce qu&rsquo;il veut. Rhodes r\u00e9pond qu&rsquo;il accepte mais que  \u00e7a va pas \u00eatre un match normal, il fera dire \u00e0 AJ Styles ce qu&rsquo;il aurait d\u00fb dire la semaine derni\u00e8re : I Quit !<\/p>\n\n\n\n<p>Nick Aldis, qui est en ringside, officialise le match.<\/p>\n\n\n\n<p>&#8211; La WWE confirme que l&rsquo;I Quit Match entre Cody Rhodes et AJ Styles aura lieu \u00e0 Clash at the Castle.<\/p>\n\n\n\n<p>&#8211; En coulisses, Bianca Belair et Jade Cargill annoncent qu&rsquo;elles vont affronter Zoey Stark, Shayna Baszler, Alba Fyre et Isla Dawn dans un Triple Threat Match par \u00e9quipe \u00e0 Clash at the Castle.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>LA Knight vs Carmelo Hayes<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, LA Knight tente son BFT sur Carmelo Hayes qui le contre en roll up&#8230; LA Knight le renverse en un autre roll up pour l&#8217;emporter.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : LA Knight<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match, LA Knight dit que si Logan Paul vient pas \u00e0 SmackDown, il va faire venir SmackDown \u00e0 Logan Paul.<\/p>\n\n\n\n<p>&#8211; En coulisses, Tiffany Stratton tombe sur Nia Jax et dit qu&rsquo;elle la soutient. La Queen of the Ring et la Princess of the Ring, personne ne pourra les arr\u00eater. Stratton part.<\/p>\n\n\n\n<p> Michin rejoint Nia Jax qui lui conseille de prendre une page du livre d&rsquo;AJ Styles et de prendre sa retraite. Michin lui jette son verre au visage et Nia Jax l&rsquo;envoie par dessus la table.<\/p>\n\n\n\n<p>&#8211; Bayley fait son entr\u00e9e et nous parle de son match contre Piper Niven \u00e0 Clash at the Castle, mais elle se fait vite interrompre par <strong>Chelsea Green  et Piper Niven <\/strong>qui arrivent. <\/p>\n\n\n\n<p>Green dit que Bayley a \u00e9t\u00e9 une loser en Arabie saoudite et une loser dans le match par \u00e9quipe avec Naomi la semaine derni\u00e8re. Bayley sera une loser quand Piper Niven deviendra championne.<\/p>\n\n\n\n<p> Bayley r\u00e9pond l&rsquo;avoir battue en Arabie saoudite, quoi qu&rsquo;il en soit Piper Niven n&rsquo;a pas besoin de Chelsea Green et elle la respecte. La premi\u00e8re fois qu&rsquo;elle l&rsquo;a vue, c&rsquo;\u00e9tait au Mae Young Classic. Lorsqu&rsquo;elles iront dans son pays d&rsquo;origine la semaine prochaine, \u00e7a sera plus qu&rsquo;un match normal. Piper Niven sera devant ses amis et sa famille. Bayley s&rsquo;amusera \u00e0 battre Niven \u00e0 Clash at the Castle.<\/p>\n\n\n\n<p>Piper Niven prend la parole et dit appr\u00e9cier le respect de Bayley mais elle ne sait rien de son parcours. Le Mae Young Classic, c&rsquo;\u00e9tait en 2017. Elle s&rsquo;est battue bec et ongles pour sortir de la mis\u00e8re.&nbsp;Pendant que Bayley faisait des c\u00e2lins au Performance Center, Piper Niven remportait des titres partout dans le monde. Elle \u00e9tait championne du Monde avant d&rsquo;arriver ici. Si Bayley savait \u00e0 quel point Niven est dangereuse, elle ne serait pas ici. <\/p>\n\n\n\n<p>Piper Niven termine en disant qu&rsquo;elle remportera la ceinture \u00e0 Clash at the Castle.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; On retrouve Logan Paul chez lui qui dit que LA Knight n&rsquo;a rien fait pour m\u00e9riter son attention, il peut revenir dans la midcard.<\/p>\n\n\n\n<p>&#8211; En coulisses, Chelsea Green et Piper Niven tombent sur Nick Aldis qui discutait avec Naomi. Cette derni\u00e8re dit \u00e0 Green de ne plus parler d&rsquo;elle. <\/p>\n\n\n\n<p>Nick Aldis demande si un match \u00e0 SmackDown peut faire en sorte qu&rsquo;elles restent \u00e0 l&rsquo;\u00e9cart. Les Superstars acceptent.<\/p>\n\n\n\n<p>&#8211; La semaine prochaine \u00e0 SmackDown : Michin affrontera Nia Jax  en plus de Grayson Waller Effect qui feront face \u00e0 DIY.<\/p>\n\n\n\n<p>&#8211; Valentina Shevchenko (combattante UFC) est dans la foule.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>6-Man Tag Team Match<\/strong><\/p>\n\n\n\n<p><strong>Bloodline (Solo Sikoa, Tama Tonga &amp; Tonga Loa) vs Street Profits (Montez Ford &amp; Angelo Dawkins) et Kevin Owens<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin, Kevin Owens \u00e9vite un Samoan Spike de Solo Sikoa et enchaine avec un Stunner suivi du tomb\u00e9&#8230; mais Tama Tonga et Tonga Loa cassent le tomb\u00e9. La bagarre continue en ringside et Sikoa attaque Montez Ford avec une chaise. L&rsquo;arbitre met fin au match.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants par DQ: Street Profits et Kevin Owens <\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match, la Bloodline passe \u00e0 tabac les Street Profits et Kevin Owens. Le show se termine avec la Bloodline qui fait passer Kevin Owens \u00e0 travers la table des commentateurs.<\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:25px\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2024\/06\/07\/avant-gout-pour-le-wwe-friday-night-smackdown-du-7-juin-2024\/\" target=\"_blank\">Pour voir Smackdown, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"PixE4Rr0iK\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/06\/07\/avant-gout-pour-le-wwe-friday-night-smackdown-du-7-juin-2024\/\">Reprise Vid\u00e9o et Programme pour le WWE Friday Night Smackdown du 7 Juin 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o et Programme pour le WWE Friday Night Smackdown du 7 Juin 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/06\/07\/avant-gout-pour-le-wwe-friday-night-smackdown-du-7-juin-2024\/embed\/#?secret=i3sYEYiBOx#?secret=PixE4Rr0iK\" data-secret=\"PixE4Rr0iK\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE SmackDown Louisville, Kentucky, 7 juin 2024 Les commentateurs sont Corey Graves et Wade Barrett. &#8211; Le show d\u00e9bute sur des images de&nbsp;l&rsquo;attaque d&rsquo;AJ Styles sur Cody Rhodes la semaine derni\u00e8re. Les commentateurs nous souhaitent la bienvenue puis la Bloodline arrive sur le ring. Paul Heyman prend le micro et se pr\u00e9sente. Il dit que&#8230;<\/p>\n","protected":false},"author":609,"featured_media":100348,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,36,23],"tags":[],"ppma_author":[295],"class_list":["post-100347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats","category-smackdown","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=100347"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100347\/revisions"}],"predecessor-version":[{"id":100497,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100347\/revisions\/100497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/100348"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=100347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=100347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=100347"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=100347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}