{"id":100044,"date":"2024-05-28T23:24:00","date_gmt":"2024-05-29T03:24:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=100044"},"modified":"2024-05-29T11:30:49","modified_gmt":"2024-05-29T15:30:49","slug":"la-championne-knockout-de-la-tna-jordy-grace-debarque-a-nxt-details-de-lentente-entre-les-deux-compagnies","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2024\/05\/28\/la-championne-knockout-de-la-tna-jordy-grace-debarque-a-nxt-details-de-lentente-entre-les-deux-compagnies\/","title":{"rendered":"La championne Knockout de la TNA Jordy Grace d\u00e9barque \u00e0 NXT! D\u00e9tails de l&rsquo;entente entre les deux compagnies!"},"content":{"rendered":"\n<p>Ce f\u00fbt la grande surprise lors de&nbsp;WWE NXT du 28 mai 2024&nbsp;lorsque Jordynne Grace a accept\u00e9 le challenge pour affronter Roxanne Perez \u00e0 NXT Battleground 2024.<\/p>\n\n\n\n<p>La WWE  a donc pass\u00e9 un nouvel accord avec la TNA afin d&rsquo;avoir la championne sur son show et en plus pour un match de championnat \u00e0 Battleground. <\/p>\n\n\n\n<p>Le PWInsider a fait le point sur le sujet et nous apprend que&nbsp;Jordynne Grace \u00e0 WWE NXT ne sera pas la seule collaboration WWE et TNA d&rsquo;ici les prochains jours.<\/p>\n\n\n\n<p>Il faut s&rsquo;attendre \u00e0 voir une suite du c\u00f4t\u00e9 de la WWE et de la TNA. On sait d\u00e9j\u00e0 que Jordynne Grace va affronter Stevie Turner la semaine prochaine avant Battleground du c\u00f4t\u00e9 de NXT. Et du c\u00f4t\u00e9 de la TNA, il se dit que des catcheurs de WWE NXT seront envoy\u00e9s sur des shows TNA afin de repr\u00e9senter la WWE. Il est pour l&rsquo;instant impossible de savoir qui seront les noms ou bien comment va s&rsquo;organiser la suite du projet. Et \u00e7a Info-Lutte vous en a parl\u00e9 avant le Royal Rumble alors que la source TNA direct de notre boss nous avait mit au parfum.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Les prochains shows t\u00e9l\u00e9vis\u00e9s de la TNA sont le 14 juin pour TNA Against All Odds et le 15 juin pour des enregistrements de TNA Impact, alors il serait logique de voir la suite de cette nouvelle alliance pour ces shows. Pour l&rsquo;instant rien n&rsquo;a \u00e9t\u00e9 confirm\u00e9, ce sera \u00e0 surveiller au moment venu.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"gC51N3MkSl\"><a href=\"https:\/\/www.jdx.info\/lutte\/2024\/05\/28\/resultats-et-video-pour-le-wwe-nxt-du-28-mai-2024\/\">R\u00e9sultats et Vid\u00e9o pour le WWE NXT du 28 Mai 2024!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le WWE NXT du 28 Mai 2024!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2024\/05\/28\/resultats-et-video-pour-le-wwe-nxt-du-28-mai-2024\/embed\/#?secret=Q1TfZOMjlX#?secret=gC51N3MkSl\" data-secret=\"gC51N3MkSl\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ce f\u00fbt la grande surprise lors de&nbsp;WWE NXT du 28 mai 2024&nbsp;lorsque Jordynne Grace a accept\u00e9 le challenge pour affronter Roxanne Perez \u00e0 NXT Battleground 2024. La WWE a donc pass\u00e9 un nouvel accord avec la TNA afin d&rsquo;avoir la championne sur son show et en plus pour un match de championnat \u00e0 Battleground. Le&#8230;<\/p>\n","protected":false},"author":4,"featured_media":100045,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,85,41,23],"tags":[],"ppma_author":[292],"class_list":["post-100044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-nxt","category-tna-impact","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=100044"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100044\/revisions"}],"predecessor-version":[{"id":100048,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/100044\/revisions\/100048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/100045"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=100044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=100044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=100044"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=100044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}